{"id":67601,"date":"2025-05-20T10:09:35","date_gmt":"2025-05-20T09:09:35","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=67601"},"modified":"2025-05-20T10:09:36","modified_gmt":"2025-05-20T09:09:36","slug":"atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/","title":{"rendered":"Atelier r\u00e9gional sur les mus\u00e9es : Faire des mus\u00e9es des espaces d&rsquo;innovation"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00c0 l&rsquo;occasion de la Journ\u00e9e internationale des mus\u00e9es et en cl\u00f4ture du mois du patrimoine, Alger a accueilli dimanche un important atelier r\u00e9gional consacr\u00e9 \u00e0 la pr\u00e9servation et \u00e0 la valorisation des mus\u00e9es et des collections mus\u00e9ales. Organis\u00e9 au Palais de la culture Moufdi Zakaria sous l&rsquo;\u00e9gide de l&rsquo;UNESCO et de l&rsquo;ALESCO, en coordination avec le minist\u00e8re de la Culture et des Arts, cet \u00e9v\u00e9nement de deux jours a rassembl\u00e9 experts et responsables culturels dans une d\u00e9marche collective visant \u00e0 repenser le r\u00f4le des mus\u00e9es face aux d\u00e9fis contemporains.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La c\u00e9r\u00e9monie d&rsquo;ouverture a \u00e9t\u00e9 pr\u00e9sid\u00e9e par le ministre de la Culture et des Arts, Zouhir Ballalou, en pr\u00e9sence de nombreuses personnalit\u00e9s, dont Ibtissem Hamlaoui, pr\u00e9sidente de l&rsquo;Observatoire national de la soci\u00e9t\u00e9 civile, Mohamed Boukhari, pr\u00e9sident du Conseil national \u00e9conomique, social et environnemental, ainsi que Mohamed Bouna\u00e2ma, Directeur g\u00e9n\u00e9ral des Archives nationales. Les organisations internationales \u00e9taient repr\u00e9sent\u00e9es par Karim Hendili pour l&rsquo;UNESCO et Humaid Al-Nofali pour l&rsquo;ALESCO.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans son allocution, le ministre de la Culture et des Arts a soulign\u00e9 la dimension strat\u00e9gique de cette rencontre qu&rsquo;il consid\u00e8re comme \u00ab l&rsquo;une des \u00e9tapes du processus d&rsquo;ouverture de l&rsquo;Alg\u00e9rie sur la coop\u00e9ration r\u00e9gionale, arabe et internationale et refl\u00e8te notre engagement collectif \u00e0 prot\u00e9ger notre patrimoine culturel de l&rsquo;humanit\u00e9 et \u00e0 valoriser son r\u00f4le dans la construction de soci\u00e9t\u00e9s plus coh\u00e9sives et ouvertes sur l&rsquo;avenir \u00bb. Il a \u00e9galement mis en lumi\u00e8re l&rsquo;\u00e9volution du concept m\u00eame de mus\u00e9e, affirmant que ces institutions \u00ab sont devenus, aujourd&rsquo;hui, des centres dynamiques du savoir, du dialogue et de l&rsquo;innovation culturelle \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le ministre a expos\u00e9 la vision alg\u00e9rienne concernant ces institutions patrimoniales, pr\u00e9cisant que l&rsquo;Alg\u00e9rie \u00ab s&#8217;emploie, dans le cadre du plan d&rsquo;action du secteur de la Culture et des Arts, \u00e0 ce que les mus\u00e9es ne se contentent pas seulement de pr\u00e9server les collections et les pi\u00e8ces arch\u00e9ologiques, mais aussi de contribuer efficacement \u00e0 la pr\u00e9servation de la m\u00e9moire collective et au renforcement de l&rsquo;identit\u00e9 nationale, ainsi que d&rsquo;adh\u00e9rer au processus de d\u00e9veloppement durable \u00bb. Cette approche s&rsquo;inscrit dans une perspective plus large, puisque le minist\u00e8re \u0153uvre \u00e0 \u00ab la promotion de la coop\u00e9ration avec tous les pays qui partagent avec nous les principes et les clauses contenus dans les conventions internationales dans le but d&rsquo;\u00e9laborer une vision commune sur l&rsquo;avenir des mus\u00e9es \u00e0 m\u00eame de renforcer la s\u00e9curit\u00e9 culturelle, de pr\u00e9server la m\u00e9moire et d&rsquo;investir dans l&rsquo;\u00e9conomie cr\u00e9ative \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De son c\u00f4t\u00e9, Karim Hendili, responsable du programme Culture au bureau r\u00e9gional de l&rsquo;UNESCO, a soulign\u00e9 le caract\u00e8re symbolique du choix de l&rsquo;Alg\u00e9rie pour accueillir cette rencontre, qui \u00ab rev\u00eat une dimension suppl\u00e9mentaire \u00bb en co\u00efncidant avec la cl\u00f4ture du mois du patrimoine et la journ\u00e9e internationale des mus\u00e9es. Il a pr\u00e9cis\u00e9 que ces travaux visent \u00e0 trouver \u00ab des moyens efficaces pour renforcer la coop\u00e9ration r\u00e9gionale, \u00e9changer les expertises, et apporter un soutien aux pays qui s&#8217;emploient \u00e0 promouvoir le r\u00f4le des mus\u00e9es \u00e0 la lumi\u00e8re des r\u00e9alit\u00e9s contemporaines \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;apport alg\u00e9rien dans ce domaine a \u00e9t\u00e9 particuli\u00e8rement salu\u00e9 par Humaid Al-Nofali, directeur du d\u00e9partement Culture \u00e0 l&rsquo;ALESCO, qui a lou\u00e9 \u00ab les efforts d\u00e9ploy\u00e9s par l&rsquo;Alg\u00e9rie pour pr\u00e9server le patrimoine mus\u00e9al et prot\u00e9ger les collections mus\u00e9ales afin de les transmettre aux jeunes g\u00e9n\u00e9rations \u00bb. Il a \u00e9galement indiqu\u00e9 que son organisation travaille activement \u00e0 \u00ab valoriser les exp\u00e9riences r\u00e9ussies dont l&rsquo;exp\u00e9rience alg\u00e9rienne, afin de les g\u00e9n\u00e9raliser aux autres pays arabes, \u00e0 travers des ateliers de formation visant \u00e0 promouvoir et \u00e0 valoriser leurs mus\u00e9es \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durant ces deux jours de travaux, les experts se sont pench\u00e9s sur l&rsquo;\u00e9valuation de la mise en \u0153uvre de la recommandation de l&rsquo;UNESCO concernant la protection et la promotion des mus\u00e9es et de leurs collections. Ils ont \u00e9galement explor\u00e9 les solutions possibles face aux d\u00e9fis actuels que rencontrent ces institutions patrimoniales, tout en renfor\u00e7ant la coop\u00e9ration r\u00e9gionale et l&rsquo;\u00e9change d&rsquo;expertises. L&rsquo;objectif final est de formuler des recommandations concr\u00e8tes permettant d&rsquo;assurer l&rsquo;avenir et la p\u00e9rennit\u00e9 des mus\u00e9es dans toute la r\u00e9gion, en phase avec la vision du pr\u00e9sident Abdelmadjid Tebboune pour \u00ab l&rsquo;ancrage des principes de bonne gouvernance et le renforcement de la pr\u00e9sence de la culture dans le processus d&rsquo;\u00e9dification de l&rsquo;Alg\u00e9rie nouvelle \u00bb, comme l&rsquo;a rappel\u00e9 le ministre Ballalou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mohand Seghir<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 l&rsquo;occasion de la Journ\u00e9e internationale des mus\u00e9es et en cl\u00f4ture du mois du patrimoine, Alger a accueilli dimanche un<\/p>\n","protected":false},"author":6,"featured_media":67602,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[36],"tags":[],"class_list":["post-67601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atelier r\u00e9gional sur les mus\u00e9es : Faire des mus\u00e9es des espaces d&rsquo;innovation - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atelier r\u00e9gional sur les mus\u00e9es : Faire des mus\u00e9es des espaces d&rsquo;innovation - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"\u00c0 l&rsquo;occasion de la Journ\u00e9e internationale des mus\u00e9es et en cl\u00f4ture du mois du patrimoine, Alger a accueilli dimanche un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-20T09:09:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T09:09:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/atelier.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/20\\\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/20\\\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Atelier r\u00e9gional sur les mus\u00e9es : Faire des mus\u00e9es des espaces d&rsquo;innovation\",\"datePublished\":\"2025-05-20T09:09:35+00:00\",\"dateModified\":\"2025-05-20T09:09:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/20\\\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\\\/\"},\"wordCount\":829,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/20\\\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/atelier.jpg\",\"articleSection\":[\"Culture\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/20\\\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/20\\\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/20\\\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\\\/\",\"name\":\"Atelier r\u00e9gional sur les mus\u00e9es : Faire des mus\u00e9es des espaces d&rsquo;innovation - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/20\\\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/20\\\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/atelier.jpg\",\"datePublished\":\"2025-05-20T09:09:35+00:00\",\"dateModified\":\"2025-05-20T09:09:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/20\\\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/20\\\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/20\\\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/atelier.jpg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/atelier.jpg\",\"width\":2048,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/20\\\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atelier r\u00e9gional sur les mus\u00e9es : Faire des mus\u00e9es des espaces d&rsquo;innovation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atelier r\u00e9gional sur les mus\u00e9es : Faire des mus\u00e9es des espaces d&rsquo;innovation - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/","og_locale":"fr_FR","og_type":"article","og_title":"Atelier r\u00e9gional sur les mus\u00e9es : Faire des mus\u00e9es des espaces d&rsquo;innovation - La Sentinelle","og_description":"\u00c0 l&rsquo;occasion de la Journ\u00e9e internationale des mus\u00e9es et en cl\u00f4ture du mois du patrimoine, Alger a accueilli dimanche un","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-05-20T09:09:35+00:00","article_modified_time":"2025-05-20T09:09:36+00:00","og_image":[{"width":2048,"height":1152,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/atelier.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Atelier r\u00e9gional sur les mus\u00e9es : Faire des mus\u00e9es des espaces d&rsquo;innovation","datePublished":"2025-05-20T09:09:35+00:00","dateModified":"2025-05-20T09:09:36+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/"},"wordCount":829,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/atelier.jpg","articleSection":["Culture"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/","name":"Atelier r\u00e9gional sur les mus\u00e9es : Faire des mus\u00e9es des espaces d&rsquo;innovation - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/atelier.jpg","datePublished":"2025-05-20T09:09:35+00:00","dateModified":"2025-05-20T09:09:36+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/atelier.jpg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/atelier.jpg","width":2048,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/20\/atelier-regional-sur-les-musees-faire-des-musees-des-espaces-dinnovation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Atelier r\u00e9gional sur les mus\u00e9es : Faire des mus\u00e9es des espaces d&rsquo;innovation"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/67601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=67601"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/67601\/revisions"}],"predecessor-version":[{"id":67604,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/67601\/revisions\/67604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/67602"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=67601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=67601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=67601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}