{"id":67717,"date":"2025-05-21T12:34:00","date_gmt":"2025-05-21T11:34:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=67717"},"modified":"2025-05-21T14:35:57","modified_gmt":"2025-05-21T13:35:57","slug":"le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/","title":{"rendered":"Prix du pr\u00e9sident de la R\u00e9publique pour le chercheur innovant : Valoriser l&rsquo;innovation"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le Premier ministre, M. Nadir Larbaoui, charg\u00e9 par le pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, a pr\u00e9sid\u00e9 mardi la c\u00e9r\u00e9monie de remise de la premi\u00e8re \u00e9dition du Prix du pr\u00e9sident de la <strong>R\u00e9publique<\/strong> pour le chercheur innovant au p\u00f4le scientifique et technologique \u00ab\u00a0Abdelhafid Ihaddaden\u00a0\u00bb \u00e0 Sidi Abdellah. Cette distinction, organis\u00e9e dans le cadre des festivit\u00e9s comm\u00e9moratives de la Journ\u00e9e nationale de l&rsquo;\u00e9tudiant c\u00e9l\u00e9br\u00e9e le 19 mai, visait \u00e0 r\u00e9compenser les travaux de recherche \u00e0 forte valeur ajout\u00e9e susceptibles de contribuer au d\u00e9veloppement scientifique et au progr\u00e8s technologique du pays. Six laur\u00e9ats ont \u00e9t\u00e9 honor\u00e9s lors de cette c\u00e9r\u00e9monie qui s&rsquo;est d\u00e9roul\u00e9e en pr\u00e9sence de plusieurs membres du gouvernement, d&rsquo;enseignants, de chercheurs et d&rsquo;\u00e9tudiants venus nombreux pour l&rsquo;occasion. Dans la cat\u00e9gorie des enseignants-chercheurs, le premier prix a \u00e9t\u00e9 attribu\u00e9 \u00e0 Ammar Azioune du Centre de recherche en biotechnologie (CRBt) pour son projet \u00ab\u00a0Transfert et d\u00e9veloppement de nouvelles technologies de puces biologiques pour des applications m\u00e9dicales en Alg\u00e9rie\u00a0\u00bb. La deuxi\u00e8me place a \u00e9t\u00e9 remport\u00e9e par Zineddine Khomri du Centre de recherche scientifique et technique sur les r\u00e9gions arides (CRSTRA) pour son projet \u00ab\u00a0Irrigation autonome des plantes \u00e0 l&rsquo;ozone\u00a0\u00bb, tandis que la troisi\u00e8me place est revenue \u00e0 Attaf Djoullah, chercheur au minist\u00e8re de la D\u00e9fense nationale, pour ses travaux sur la \u00ab\u00a0D\u00e9fense alimentaire, un nouveau concept \u00e0 l&rsquo;\u00e8re des guerres hybrides\u00a0\u00bb. Chez les \u00e9tudiants, Amel Imene Hadj Bouzid, doctorante au Centre de recherche sur l&rsquo;information scientifique et technique (CERIST), a d\u00e9croch\u00e9 la premi\u00e8re place avec son projet sur \u00ab\u00a0L&rsquo;intelligence artificielle m\u00e9dicale : vers la modernisation des soins de sant\u00e9 en Alg\u00e9rie et le d\u00e9veloppement des expertises nationales souveraines\u00a0\u00bb. Ahmed Ilyes Bensalem de l&rsquo;\u00c9cole nationale sup\u00e9rieure d&rsquo;informatique de Sidi Bel Abb\u00e8s s&rsquo;est class\u00e9 deuxi\u00e8me avec son dispositif m\u00e9dical d&rsquo;assistance technologique bas\u00e9 sur l&rsquo;intelligence artificielle pour surveiller et traiter le cancer. Nardjes Rihane, \u00e9tudiante en master \u00e0 l&rsquo;Universit\u00e9 Fr\u00e8res Mentouri de Constantine, a compl\u00e9t\u00e9 le podium avec son projet de \u00ab\u00a0D\u00e9veloppement d&rsquo;un catalyseur biologique naturel bas\u00e9 sur des bact\u00e9ries locales b\u00e9n\u00e9fiques et des r\u00e9sidus verts\u00a0\u00bb. Dans son allocution, le ministre de l&rsquo;Enseignement sup\u00e9rieur et de la Recherche scientifique, M. Kamel Baddari, a soulign\u00e9 que cette initiative \u00ab\u00a0t\u00e9moigne de l&rsquo;int\u00e9r\u00eat particulier accord\u00e9 par le pr\u00e9sident de la R\u00e9publique \u00e0 la recherche et \u00e0 l&rsquo;innovation et au renforcement de leur r\u00f4le dans l&rsquo;accompagnement des efforts de d\u00e9veloppement du pays\u00a0\u00bb. Il a rappel\u00e9 le message adress\u00e9 dimanche par le chef de l&rsquo;\u00c9tat aux \u00e9tudiants, dans lequel ce dernier \u00ab\u00a0a mis en avant les ressources financi\u00e8res allou\u00e9es et les capacit\u00e9s humaines mobilis\u00e9es pour faire de l&rsquo;universit\u00e9, dans l&rsquo;Alg\u00e9rie nouvelle et victorieuse, une locomotive essentielle \u00e0 m\u00eame de mener le pays vers le d\u00e9veloppement et la diversification de l&rsquo;activit\u00e9 \u00e9conomique\u00a0\u00bb. M. Baddari a \u00e9galement affirm\u00e9 que cette distinction \u00ab\u00a0constitue un geste d&rsquo;encouragement du pr\u00e9sident de la R\u00e9publique aux enseignants, aux chercheurs et aux \u00e9tudiants brillants, qui ont choisi le savoir comme voie, la comp\u00e9tence comme crit\u00e8re et l&rsquo;innovation comme solution pour l&rsquo;\u00e9dification d&rsquo;une Alg\u00e9rie forte de ses enfants et de son capital humain\u00a0\u00bb. Le ministre a insist\u00e9 sur l&rsquo;importance de \u00ab\u00a0la c\u00e9l\u00e9bration de l&rsquo;excellence, de la r\u00e9ussite et de tous les talents dot\u00e9s de l&rsquo;esprit d&rsquo;innovation\u00a0\u00bb, estimant que cela \u00ab\u00a0doit \u00eatre \u00e0 la t\u00eate de nos pr\u00e9occupations et de nos priorit\u00e9s, en vue de mettre en place des r\u00e9f\u00e9rentiels de comp\u00e9tences dans tous les domaines\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lyna Larbi<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Premier ministre, M. Nadir Larbaoui, charg\u00e9 par le pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, a pr\u00e9sid\u00e9 mardi la<\/p>\n","protected":false},"author":6,"featured_media":67718,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-67717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prix du pr\u00e9sident de la R\u00e9publique pour le chercheur innovant : Valoriser l&rsquo;innovation - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prix du pr\u00e9sident de la R\u00e9publique pour le chercheur innovant : Valoriser l&rsquo;innovation - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le Premier ministre, M. Nadir Larbaoui, charg\u00e9 par le pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, a pr\u00e9sid\u00e9 mardi la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-21T11:34:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T13:35:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/spm-post-1747737909.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"740\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/21\\\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/21\\\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Prix du pr\u00e9sident de la R\u00e9publique pour le chercheur innovant : Valoriser l&rsquo;innovation\",\"datePublished\":\"2025-05-21T11:34:00+00:00\",\"dateModified\":\"2025-05-21T13:35:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/21\\\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\\\/\"},\"wordCount\":666,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/21\\\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/spm-post-1747737909.jpg\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/21\\\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/21\\\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/21\\\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\\\/\",\"name\":\"Prix du pr\u00e9sident de la R\u00e9publique pour le chercheur innovant : Valoriser l&rsquo;innovation - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/21\\\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/21\\\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/spm-post-1747737909.jpg\",\"datePublished\":\"2025-05-21T11:34:00+00:00\",\"dateModified\":\"2025-05-21T13:35:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/21\\\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/21\\\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/21\\\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/spm-post-1747737909.jpg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/spm-post-1747737909.jpg\",\"width\":740,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/05\\\/21\\\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prix du pr\u00e9sident de la R\u00e9publique pour le chercheur innovant : Valoriser l&rsquo;innovation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prix du pr\u00e9sident de la R\u00e9publique pour le chercheur innovant : Valoriser l&rsquo;innovation - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/","og_locale":"fr_FR","og_type":"article","og_title":"Prix du pr\u00e9sident de la R\u00e9publique pour le chercheur innovant : Valoriser l&rsquo;innovation - La Sentinelle","og_description":"Le Premier ministre, M. Nadir Larbaoui, charg\u00e9 par le pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, a pr\u00e9sid\u00e9 mardi la","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-05-21T11:34:00+00:00","article_modified_time":"2025-05-21T13:35:57+00:00","og_image":[{"width":740,"height":360,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/spm-post-1747737909.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Prix du pr\u00e9sident de la R\u00e9publique pour le chercheur innovant : Valoriser l&rsquo;innovation","datePublished":"2025-05-21T11:34:00+00:00","dateModified":"2025-05-21T13:35:57+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/"},"wordCount":666,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/spm-post-1747737909.jpg","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/","name":"Prix du pr\u00e9sident de la R\u00e9publique pour le chercheur innovant : Valoriser l&rsquo;innovation - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/spm-post-1747737909.jpg","datePublished":"2025-05-21T11:34:00+00:00","dateModified":"2025-05-21T13:35:57+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/spm-post-1747737909.jpg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/spm-post-1747737909.jpg","width":740,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/05\/21\/le-projet-de-loi-sur-la-mobilisation-generale-presente-a-lapn-faire-face-aux-tensions-geopolitiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Prix du pr\u00e9sident de la R\u00e9publique pour le chercheur innovant : Valoriser l&rsquo;innovation"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/67717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=67717"}],"version-history":[{"count":4,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/67717\/revisions"}],"predecessor-version":[{"id":67723,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/67717\/revisions\/67723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/67718"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=67717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=67717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=67717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}