{"id":6944,"date":"2021-09-08T00:01:00","date_gmt":"2021-09-07T23:01:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=6944"},"modified":"2021-09-07T15:54:11","modified_gmt":"2021-09-07T14:54:11","slug":"plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/","title":{"rendered":"Plan d\u2019action du gouvernement : D\u00e9velopper une v\u00e9ritable industrie culturelle"},"content":{"rendered":"\n<p>Le gouvernement mise, dans son plan d&rsquo;action, sur le tourisme et l\u2019\u00e9conomie de la culture comme secteurs porteurs de croissance \u00e9conomique et s&rsquo;engage \u00e0 d\u00e9velopper une \u00ab\u00a0vraie\u00a0\u00bb industrie touristique et culturelle en encourageant l&rsquo;investissement dans ces domaines.<\/p>\n\n\n\n<p>Relevant d&#8217;embl\u00e9e que le tourisme est un \u00ab\u00a0secteur \u00e9conomique qui ne cesse d\u2019\u00e9voluer et de se parfaire en fonction des exigences des touristes, des nouvelles donn\u00e9es \u00e9conomiques et des avanc\u00e9es technologiques\u00a0\u00bb, le gouvernement propose de&nbsp; mettre en \u0153uvre un plan \u00ab\u00a0destination Alg\u00e9rie\u00a0\u00bb par une s\u00e9rie de mesures, lit-on dans le Plan d&rsquo;action qui sera soumis prochainement au Parlement.A ce titre, le gouvernement envisage de soutenir l\u2019action des agences de voyage et la facilitation des proc\u00e9dures de visas au profit des touristes \u00e9trangers, d&rsquo;encourager le recours aux formules incitatives de voyage par le biais des vols charters afin de renforcer l\u2019attractivit\u00e9 de la destination touristique Alg\u00e9rie tout en s\u2019appuyant sur l\u2019apport des repr\u00e9sentations diplomatiques et consulaires \u00e0 l\u2019\u00e9tranger.Il compte aussi favoriser l\u2019\u00e9mergence de p\u00f4les touristiques d\u2019excellence, r\u00e9pondant aux standards internationaux, notamment de nature culturelle, cultuelle et au niveau des r\u00e9gions du Sud, ainsi que d\u00e9velopper le tourisme domestique par l\u2019ach\u00e8vement du programme de modernisation et de r\u00e9habilitation du parc h\u00f4telier public.Les actions envisag\u00e9es englobent \u00e9galement l\u2019orientation des investissements touristiques et leur adaptation en fonction des besoins de la demande touristique interne et de la sp\u00e9cificit\u00e9 de chaque r\u00e9gion, ainsi que la mise en place de circuits touristiques th\u00e9matiques.<\/p>\n\n\n\n<p>Pour les investisseurs, il sera question de mettre \u00e0 leur disposition des assiettes fonci\u00e8res pour la r\u00e9alisation de structures l\u00e9g\u00e8res et modulables, au titre du d\u00e9veloppement durable et dans le cadre du d\u00e9veloppement du tourisme interne, avec ses diff\u00e9rentes fili\u00e8res et particuli\u00e8rement le thermalisme.Le gouvernement \u0153uvrera \u00e0 la relance du plan qualit\u00e9 tourisme Alg\u00e9rie (PQTA) et l\u2019am\u00e9lioration de la performance de l\u2019appareil de formation.Il est pr\u00e9vu aussi la mise \u00e0 disposition du foncier touristique au profit des investisseurs et des promoteurs qui se chargeront de la prise en charge de l&rsquo;am\u00e9nagement et la viabilisation d&rsquo;une ou plusieurs zones d&rsquo;expansion touristique, en contrepartie de la r\u00e9duction de la redevance locative de la concession, ainsi que l&rsquo;encouragement des diff\u00e9rentes formules de partenariat public-priv\u00e9.R\u00e9activer le Conseil national du tourisme (CNT) et \u00e9laborer un projet de loi d&rsquo;orientation sur le tourisme, figurent aussi parmi les actions inscrites.<\/p>\n\n\n\n<p>A cela s&rsquo;ajoute, la protection des produits de l\u2019industrie artisanale nationale et la lutte contre la contrefa\u00e7on en mati\u00e8re de produits artisanaux, notamment par rapport \u00e0 ceux import\u00e9s, l\u2019intensification et la professionnalisation des op\u00e9rations de promotion et de commercialisation des produits issus de l\u2019artisanat sur le march\u00e9 national et international et la mise en place de nouveaux m\u00e9canismes financiers pour soutenir les activit\u00e9s de l\u2019industrie artisanale.Quant \u00e0 l\u2019\u00e9conomie de la culture, l\u2019action portera sur \u00ab\u00a0la mise en place de \u00ab\u00a0m\u00e9canismes qui permettront d\u2019asseoir les conditions appropri\u00e9es et efficientes pour le lancement d\u2019une v\u00e9ritable industrie cin\u00e9matographique, bas\u00e9e sur l\u2019incitation \u00e0 l\u2019investissement et la lib\u00e9ralisation des initiatives aux fins de faire de l\u2019Alg\u00e9rie un p\u00f4le de production et de tournage cin\u00e9matographiques r\u00e9gional et international\u00a0\u00bb.Dans ce cadre, le gouvernement compte mener des actions imm\u00e9diates, dont notamment, la restructuration des entreprises publiques charg\u00e9es du cin\u00e9ma \u00e0 travers la cr\u00e9ation du centre du cin\u00e9ma alg\u00e9rien de mani\u00e8re \u00e0 uniformiser et faciliter les proc\u00e9dures d\u2019organisation, de gestion et de suivi de l\u2019industrie cin\u00e9matographique.Pour attirer les investisseurs dans les industries et infrastructures cin\u00e9matographiques, des mesures incitatives seront mises en place et les contraintes entravant la r\u00e9alisation des projets seront lev\u00e9es.Il est pr\u00e9vu, en outre, l\u2019identification et le recensement du foncier susceptible de faire l\u2019objet d\u2019investissements dans les industries et infrastructures culturelles&nbsp; notamment cin\u00e9matographiques dans les wilayas et la r\u00e9cup\u00e9ration des salles de cin\u00e9ma \u00e0 l\u2019effet de les confier \u00e0 des exploitants priv\u00e9s dans le cadre de concessions et la conception des m\u00e9canismes pour une gestion all\u00e9g\u00e9e de l\u2019aide publique d\u00e9di\u00e9e au cin\u00e9ma.Enfin, l&rsquo;action du gouvernement touchera la formation dans le domaine du cin\u00e9ma, la r\u00e9cup\u00e9ration des archives filmiques et leur num\u00e9risation, en plus de l\u2019organisation de festivals.<\/p>\n\n\n\n<p>APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le gouvernement mise, dans son plan d&rsquo;action, sur le tourisme et l\u2019\u00e9conomie de la culture comme secteurs porteurs de croissance<\/p>\n","protected":false},"author":3,"featured_media":6949,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[31],"tags":[],"class_list":["post-6944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regions"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plan d\u2019action du gouvernement : D\u00e9velopper une v\u00e9ritable industrie culturelle - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan d\u2019action du gouvernement : D\u00e9velopper une v\u00e9ritable industrie culturelle - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le gouvernement mise, dans son plan d&rsquo;action, sur le tourisme et l\u2019\u00e9conomie de la culture comme secteurs porteurs de croissance\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-07T23:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/image_2021-09-07_155404.png\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"La Sentinelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Sentinelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/09\\\/08\\\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/09\\\/08\\\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\\\/\"},\"author\":{\"name\":\"La Sentinelle\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\"},\"headline\":\"Plan d\u2019action du gouvernement : D\u00e9velopper une v\u00e9ritable industrie culturelle\",\"datePublished\":\"2021-09-07T23:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/09\\\/08\\\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\\\/\"},\"wordCount\":796,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/09\\\/08\\\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/image_2021-09-07_155404.png\",\"articleSection\":[\"R\u00e9gions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/09\\\/08\\\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/09\\\/08\\\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/09\\\/08\\\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\\\/\",\"name\":\"Plan d\u2019action du gouvernement : D\u00e9velopper une v\u00e9ritable industrie culturelle - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/09\\\/08\\\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/09\\\/08\\\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/image_2021-09-07_155404.png\",\"datePublished\":\"2021-09-07T23:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/09\\\/08\\\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/09\\\/08\\\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/09\\\/08\\\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/image_2021-09-07_155404.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/image_2021-09-07_155404.png\",\"width\":580,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2021\\\/09\\\/08\\\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan d\u2019action du gouvernement : D\u00e9velopper une v\u00e9ritable industrie culturelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/d865044e22e70a75174ce8bcad3acfb3\",\"name\":\"La Sentinelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g\",\"caption\":\"La Sentinelle\"},\"sameAs\":[\"http:\\\/\\\/www.lasentinelle.dz\"],\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/redaction\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan d\u2019action du gouvernement : D\u00e9velopper une v\u00e9ritable industrie culturelle - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/","og_locale":"fr_FR","og_type":"article","og_title":"Plan d\u2019action du gouvernement : D\u00e9velopper une v\u00e9ritable industrie culturelle - La Sentinelle","og_description":"Le gouvernement mise, dans son plan d&rsquo;action, sur le tourisme et l\u2019\u00e9conomie de la culture comme secteurs porteurs de croissance","og_url":"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2021-09-07T23:01:00+00:00","og_image":[{"width":580,"height":350,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/image_2021-09-07_155404.png","type":"image\/png"}],"author":"La Sentinelle","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"La Sentinelle","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/"},"author":{"name":"La Sentinelle","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3"},"headline":"Plan d\u2019action du gouvernement : D\u00e9velopper une v\u00e9ritable industrie culturelle","datePublished":"2021-09-07T23:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/"},"wordCount":796,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/image_2021-09-07_155404.png","articleSection":["R\u00e9gions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/","url":"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/","name":"Plan d\u2019action du gouvernement : D\u00e9velopper une v\u00e9ritable industrie culturelle - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/image_2021-09-07_155404.png","datePublished":"2021-09-07T23:01:00+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/image_2021-09-07_155404.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/image_2021-09-07_155404.png","width":580,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2021\/09\/08\/plan-daction-du-gouvernement-developper-une-veritable-industrie-culturelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Plan d\u2019action du gouvernement : D\u00e9velopper une v\u00e9ritable industrie culturelle"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/d865044e22e70a75174ce8bcad3acfb3","name":"La Sentinelle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/57de8e5d4b15d43fb361a71fbb36338450fe67865b528a43dd10ef7c51a20392?s=96&d=mm&r=g","caption":"La Sentinelle"},"sameAs":["http:\/\/www.lasentinelle.dz"],"url":"https:\/\/lasentinelle.dz\/author\/redaction\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/6944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=6944"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/6944\/revisions"}],"predecessor-version":[{"id":6950,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/6944\/revisions\/6950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/6949"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=6944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=6944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=6944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}