{"id":72349,"date":"2025-08-25T13:15:50","date_gmt":"2025-08-25T12:15:50","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=72349"},"modified":"2025-08-25T13:15:51","modified_gmt":"2025-08-25T12:15:51","slug":"le-maroc-une-menace-pour-la-stabilite-regionale","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/","title":{"rendered":"Le Maroc, une menace pour la stabilit\u00e9 r\u00e9gionale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les participants \u00e0 une conf\u00e9rence internationale organis\u00e9e par le Centre de surveillance mondial am\u00e9ricain \u00e0 New York a soulign\u00e9 que le Royaume ch\u00e9rifien et ses ambitions expansionnistes sont la principale menace pour la stabilit\u00e9 dans la r\u00e9gion du Maghreb&nbsp;?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une conf\u00e9rence internationale organis\u00e9e par le Centre de surveillance mondial am\u00e9ricain \u00e0 New York a r\u00e9uni des experts acad\u00e9miques et juridiques autour de la question du Sahara occidental, confirmant que l&rsquo;occupation marocaine du territoire constitue la principale menace pour la stabilit\u00e9 r\u00e9gionale en Afrique du Nord-Ouest. Les participants ont unanimement d\u00e9nonc\u00e9 la politique expansionniste du royaume ch\u00e9rifien et r\u00e9clam\u00e9 la d\u00e9colonisation compl\u00e8te du territoire pour garantir la paix dans la r\u00e9gion. L&rsquo;universitaire am\u00e9ricain Jacob Mundy, professeur d&rsquo;\u00e9tudes de paix et de conflits \u00e0 l&rsquo;universit\u00e9 Colgate de New York et sp\u00e9cialiste des conflits nord-africains, a rappel\u00e9 les fondements juridiques de l&rsquo;avis consultatif de la Cour internationale de justice de 1975 d\u00e9montrant l&rsquo;absence de souverainet\u00e9 marocaine sur le Sahara occidental. \u00ab\u00a0Cette d\u00e9cision a \u00e9t\u00e9 confirm\u00e9e par les r\u00e9solutions des Nations Unies qui reconnaissent le droit inali\u00e9nable du peuple sahraoui \u00e0 l&rsquo;autod\u00e9termination\u00a0\u00bb, a-t-il d\u00e9clar\u00e9, soulignant que l&rsquo;invasion marocaine \u00e9tait motiv\u00e9e par des consid\u00e9rations expansionnistes, une crise de l\u00e9gitimit\u00e9 interne du r\u00e9gime du Makhzen et la convoitise des ressources naturelles sahraouies. L&rsquo;experte en droit international Kathleen Thomas, ancienne membre juridique de la MINURSO, a t\u00e9moign\u00e9 des tentatives marocaines d&rsquo;entrave au processus de paix et de falsification de l&rsquo;identification des \u00e9lecteurs par l&rsquo;implantation massive de colons destin\u00e9e \u00e0 modifier la d\u00e9mographie du territoire. \u00ab\u00a0Le Maroc craint le r\u00e9sultat du r\u00e9f\u00e9rendum car il sait que le peuple sahraoui choisira l&rsquo;ind\u00e9pendance\u00a0\u00bb, a-t-elle affirm\u00e9, d\u00e9plorant l&rsquo;inaction du Conseil de s\u00e9curit\u00e9 face aux manipulations marocaines. L&rsquo;avocate a qualifi\u00e9 la proposition d&rsquo;autonomie marocaine de simple \u00ab\u00a0man\u0153uvre\u00a0\u00bb coloniale visant \u00e0 \u00ab\u00a0l\u00e9gitimer\u00a0\u00bb l&rsquo;occupation et \u00e0 nier le droit \u00e0 l&rsquo;autod\u00e9termination, s&rsquo;interrogeant sur la cr\u00e9dibilit\u00e9 d&rsquo;un \u00ab\u00a0r\u00e9gime totalitaire autoritaire\u00a0\u00bb pr\u00e9tendant d\u00e9fendre les droits d&rsquo;un peuple qu&rsquo;il \u00ab\u00a0occupe par la force et expose quotidiennement \u00e0 une r\u00e9pression brutale\u00a0\u00bb tout en privant son propre peuple de ses droits fondamentaux. Elle a contrast\u00e9 cette situation avec les acquis de la R\u00e9publique sahraouie qui a, souligne-t-elle, \u00e9difi\u00e9 des institutions d\u00e9mocratiques solides fond\u00e9es sur l&rsquo;\u00c9tat de droit et d\u00e9velopp\u00e9 une culture de tol\u00e9rance et de coexistence pacifique, pr\u00e9sentant l&rsquo;\u00c9tat sahraoui ind\u00e9pendant comme un facteur de stabilit\u00e9 r\u00e9gionale contrairement au r\u00e9gime marocain qui repr\u00e9sente une menace pour toute la r\u00e9gion. Thomas a \u00e9galement \u00e9voqu\u00e9 les tentatives de ternissement de la r\u00e9putation du Front Polisario, assurant que les responsables am\u00e9ricains connaissent parfaitement le caract\u00e8re infond\u00e9 des accusations marocaines. Le repr\u00e9sentant du Front Polisario aux Nations Unies Sidi Mohamed Omar a pour sa part r\u00e9it\u00e9r\u00e9 la nature juridique de la question sahraouie et le rejet cat\u00e9gorique par son peuple de la proposition coloniale marocaine \u00ab\u00a0mis\u00e9rable\u00a0\u00bb et \u00ab\u00a0ridicule\u00a0\u00bb. L&rsquo;ensemble des intervenants ont appel\u00e9 la communaut\u00e9 internationale \u00e0 abandonner la politique du deux poids deux mesures et \u00e0 comprendre que la stabilit\u00e9 \u00e0 long terme en Afrique du Nord-Ouest n\u00e9cessite imp\u00e9rativement de contenir les ambitions expansionnistes marocaines et de permettre l&rsquo;exercice libre et d\u00e9mocratique du droit \u00e0 l&rsquo;autod\u00e9termination du peuple sahraoui.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lyes Sa\u00efdi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les participants \u00e0 une conf\u00e9rence internationale organis\u00e9e par le Centre de surveillance mondial am\u00e9ricain \u00e0 New York a soulign\u00e9 que<\/p>\n","protected":false},"author":6,"featured_media":72350,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,37],"tags":[],"class_list":["post-72349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-monde"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Maroc, une menace pour la stabilit\u00e9 r\u00e9gionale - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Maroc, une menace pour la stabilit\u00e9 r\u00e9gionale - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Les participants \u00e0 une conf\u00e9rence internationale organis\u00e9e par le Centre de surveillance mondial am\u00e9ricain \u00e0 New York a soulign\u00e9 que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-25T12:15:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-25T12:15:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/08\/2484ba7e258e56d54b871474d7f20633_m.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-maroc-une-menace-pour-la-stabilite-regionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-maroc-une-menace-pour-la-stabilite-regionale\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Le Maroc, une menace pour la stabilit\u00e9 r\u00e9gionale\",\"datePublished\":\"2025-08-25T12:15:50+00:00\",\"dateModified\":\"2025-08-25T12:15:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-maroc-une-menace-pour-la-stabilite-regionale\\\/\"},\"wordCount\":602,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-maroc-une-menace-pour-la-stabilite-regionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/2484ba7e258e56d54b871474d7f20633_m.webp\",\"articleSection\":[\"\u00c0 la Une\",\"Monde\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-maroc-une-menace-pour-la-stabilite-regionale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-maroc-une-menace-pour-la-stabilite-regionale\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-maroc-une-menace-pour-la-stabilite-regionale\\\/\",\"name\":\"Le Maroc, une menace pour la stabilit\u00e9 r\u00e9gionale - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-maroc-une-menace-pour-la-stabilite-regionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-maroc-une-menace-pour-la-stabilite-regionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/2484ba7e258e56d54b871474d7f20633_m.webp\",\"datePublished\":\"2025-08-25T12:15:50+00:00\",\"dateModified\":\"2025-08-25T12:15:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-maroc-une-menace-pour-la-stabilite-regionale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-maroc-une-menace-pour-la-stabilite-regionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-maroc-une-menace-pour-la-stabilite-regionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/2484ba7e258e56d54b871474d7f20633_m.webp\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/2484ba7e258e56d54b871474d7f20633_m.webp\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-maroc-une-menace-pour-la-stabilite-regionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Maroc, une menace pour la stabilit\u00e9 r\u00e9gionale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Maroc, une menace pour la stabilit\u00e9 r\u00e9gionale - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Maroc, une menace pour la stabilit\u00e9 r\u00e9gionale - La Sentinelle","og_description":"Les participants \u00e0 une conf\u00e9rence internationale organis\u00e9e par le Centre de surveillance mondial am\u00e9ricain \u00e0 New York a soulign\u00e9 que","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-08-25T12:15:50+00:00","article_modified_time":"2025-08-25T12:15:51+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/08\/2484ba7e258e56d54b871474d7f20633_m.webp","type":"image\/webp"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Le Maroc, une menace pour la stabilit\u00e9 r\u00e9gionale","datePublished":"2025-08-25T12:15:50+00:00","dateModified":"2025-08-25T12:15:51+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/"},"wordCount":602,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/08\/2484ba7e258e56d54b871474d7f20633_m.webp","articleSection":["\u00c0 la Une","Monde"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/","name":"Le Maroc, une menace pour la stabilit\u00e9 r\u00e9gionale - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/08\/2484ba7e258e56d54b871474d7f20633_m.webp","datePublished":"2025-08-25T12:15:50+00:00","dateModified":"2025-08-25T12:15:51+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/08\/2484ba7e258e56d54b871474d7f20633_m.webp","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/08\/2484ba7e258e56d54b871474d7f20633_m.webp","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-maroc-une-menace-pour-la-stabilite-regionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Le Maroc, une menace pour la stabilit\u00e9 r\u00e9gionale"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/72349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=72349"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/72349\/revisions"}],"predecessor-version":[{"id":72351,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/72349\/revisions\/72351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/72350"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=72349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=72349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=72349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}