{"id":72367,"date":"2025-08-25T13:25:49","date_gmt":"2025-08-25T12:25:49","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=72367"},"modified":"2025-08-25T13:26:07","modified_gmt":"2025-08-25T12:26:07","slug":"le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/","title":{"rendered":"Le stockage c\u00e9r\u00e9alier \u00e0 Annaba\u00a0: Les centres de Tr\u00e9at bient\u00f4t op\u00e9rationnels"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les projets de centres de stockage c\u00e9r\u00e9alier de Tr\u00e9at entrent en phase de contr\u00f4le final en pr\u00e9paration de leur mise en exploitation. Comme annonc\u00e9 lors du lancement des travaux, les d\u00e9lais de construction ont \u00e9t\u00e9 respect\u00e9s et les centres seront incessamment op\u00e9rationnels. La wilaya a confirm\u00e9 l&rsquo;entr\u00e9e en phase finale du projet de r\u00e9alisation de deux centres de stockage de c\u00e9r\u00e9ales implant\u00e9s dans la commune de Tr\u00e9at. D&rsquo;une capacit\u00e9 de stockage de 5 000 quintaux chacun, soit une capacit\u00e9 totale de 10 000 quintaux, ces infrastructures repr\u00e9sentent un renforcement significatif des capacit\u00e9s locales de stockage, particuli\u00e8rement adapt\u00e9 \u00e0 la vocation agricole de la commune de Tr\u00e9at. Lors de la visite de suivi et de contr\u00f4le des \u00e9quipements, les autorit\u00e9s locales accompagn\u00e9es des responsables de la Coop\u00e9rative des C\u00e9r\u00e9ales et L\u00e9gumineuses S\u00e8ches d&rsquo;Annaba, de l&rsquo;Alg\u00e9rienne des Eaux et des entreprises charg\u00e9es des travaux, ont supervis\u00e9 les derni\u00e8res retouches avant la mise en exploitation des deux points de stockage c\u00e9r\u00e9alier. Selon un communiqu\u00e9 de la wilaya d&rsquo;Annaba, la proc\u00e9dure de r\u00e9ception des ouvrages devrait se faire dans les tout prochains jours. Les v\u00e9rifications finales portent essentiellement sur la conformit\u00e9 des structures et leurs raccordements aux r\u00e9seaux d&rsquo;eau et d&rsquo;\u00e9lectricit\u00e9, ainsi que sur la v\u00e9rification de la disponibilit\u00e9 des \u00e9quipements de manutention. La mise en exploitation de ces ouvrages constitue un acquis pour le secteur agricole, particuli\u00e8rement pour la fili\u00e8re c\u00e9r\u00e9ali\u00e8re. Le renforcement des capacit\u00e9s de stockage de la wilaya et l&rsquo;am\u00e9lioration de la gestion des r\u00e9coltes locales repr\u00e9sentent une valeur ajout\u00e9e \u00e0 la politique nationale du secteur agricole. Ces infrastructures strat\u00e9giques offrent un tampon logistique important durant les campagnes de r\u00e9coltes agricoles. La mise en exploitation n\u00e9cessitera toutefois l&rsquo;\u00e9tablissement de proc\u00e9dures de gestion, de maintenance et de coordination avec les coop\u00e9ratives afin de garantir une utilisation optimale, efficace et durable des silos. Les prochains jours seront d\u00e9terminants pour achever les tests techniques, formaliser la r\u00e9ception provisoire et lancer la phase d&rsquo;exploitation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sofia Chahine<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les projets de centres de stockage c\u00e9r\u00e9alier de Tr\u00e9at entrent en phase de contr\u00f4le final en pr\u00e9paration de leur mise<\/p>\n","protected":false},"author":6,"featured_media":48603,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[31],"tags":[],"class_list":["post-72367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regions"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le stockage c\u00e9r\u00e9alier \u00e0 Annaba\u00a0: Les centres de Tr\u00e9at bient\u00f4t op\u00e9rationnels - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le stockage c\u00e9r\u00e9alier \u00e0 Annaba\u00a0: Les centres de Tr\u00e9at bient\u00f4t op\u00e9rationnels - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Les projets de centres de stockage c\u00e9r\u00e9alier de Tr\u00e9at entrent en phase de contr\u00f4le final en pr\u00e9paration de leur mise\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-25T12:25:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-25T12:26:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/01\/silos.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"576\" \/>\n\t<meta property=\"og:image:height\" content=\"354\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Le stockage c\u00e9r\u00e9alier \u00e0 Annaba\u00a0: Les centres de Tr\u00e9at bient\u00f4t op\u00e9rationnels\",\"datePublished\":\"2025-08-25T12:25:49+00:00\",\"dateModified\":\"2025-08-25T12:26:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\\\/\"},\"wordCount\":393,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/silos.jpeg\",\"articleSection\":[\"R\u00e9gions\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\\\/\",\"name\":\"Le stockage c\u00e9r\u00e9alier \u00e0 Annaba\u00a0: Les centres de Tr\u00e9at bient\u00f4t op\u00e9rationnels - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/silos.jpeg\",\"datePublished\":\"2025-08-25T12:25:49+00:00\",\"dateModified\":\"2025-08-25T12:26:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/silos.jpeg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/silos.jpeg\",\"width\":576,\"height\":354},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/08\\\/25\\\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le stockage c\u00e9r\u00e9alier \u00e0 Annaba\u00a0: Les centres de Tr\u00e9at bient\u00f4t op\u00e9rationnels\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le stockage c\u00e9r\u00e9alier \u00e0 Annaba\u00a0: Les centres de Tr\u00e9at bient\u00f4t op\u00e9rationnels - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/","og_locale":"fr_FR","og_type":"article","og_title":"Le stockage c\u00e9r\u00e9alier \u00e0 Annaba\u00a0: Les centres de Tr\u00e9at bient\u00f4t op\u00e9rationnels - La Sentinelle","og_description":"Les projets de centres de stockage c\u00e9r\u00e9alier de Tr\u00e9at entrent en phase de contr\u00f4le final en pr\u00e9paration de leur mise","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-08-25T12:25:49+00:00","article_modified_time":"2025-08-25T12:26:07+00:00","og_image":[{"width":576,"height":354,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/01\/silos.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Le stockage c\u00e9r\u00e9alier \u00e0 Annaba\u00a0: Les centres de Tr\u00e9at bient\u00f4t op\u00e9rationnels","datePublished":"2025-08-25T12:25:49+00:00","dateModified":"2025-08-25T12:26:07+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/"},"wordCount":393,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/01\/silos.jpeg","articleSection":["R\u00e9gions"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/","name":"Le stockage c\u00e9r\u00e9alier \u00e0 Annaba\u00a0: Les centres de Tr\u00e9at bient\u00f4t op\u00e9rationnels - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/01\/silos.jpeg","datePublished":"2025-08-25T12:25:49+00:00","dateModified":"2025-08-25T12:26:07+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/01\/silos.jpeg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2024\/01\/silos.jpeg","width":576,"height":354},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/08\/25\/le-stockage-cerealier-a-annaba-les-centres-de-treat-bientot-operationnels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Le stockage c\u00e9r\u00e9alier \u00e0 Annaba\u00a0: Les centres de Tr\u00e9at bient\u00f4t op\u00e9rationnels"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/72367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=72367"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/72367\/revisions"}],"predecessor-version":[{"id":72369,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/72367\/revisions\/72369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/48603"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=72367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=72367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=72367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}