{"id":73662,"date":"2025-09-22T13:25:32","date_gmt":"2025-09-22T12:25:32","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=73662"},"modified":"2025-09-22T13:25:33","modified_gmt":"2025-09-22T12:25:33","slug":"lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/","title":{"rendered":"Lignes ferroviaires mini\u00e8res et projets protuaires\u00a0: Djellaoui au pas de charge"},"content":{"rendered":"\n<p>Le ministre des Travaux publics et des Infrastructures de base, Abdelkader Djellaoui, intensifie le pilotage des grands chantiers miniers du pays en cr\u00e9ant un comit\u00e9 central de suivi pour les lignes ferroviaires Est et Ouest, tout en renfor\u00e7ant l&rsquo;encadrement de l&rsquo;expansion du port min\u00e9ralier d&rsquo;Annaba. Cette offensive vise \u00e0 respecter les \u00e9ch\u00e9ances de projets strat\u00e9giques auxquels le pr\u00e9sident Abdelmadjid Tebboune accorde une importance majeure. Samedi \u00e0 Alger, lors de deux r\u00e9unions successives consacr\u00e9es aux lignes mini\u00e8res, le ministre a donn\u00e9 \u00ab\u00a0des instructions pour la cr\u00e9ation d&rsquo;un comit\u00e9 central charg\u00e9 du suivi rigoureux des diff\u00e9rentes \u00e9tapes de r\u00e9alisation de la ligne mini\u00e8re Ouest reliant B\u00e9char\u2013Tindouf\u2013Gara Djebilet et la ligne Est reliant Annaba \u00e0 Bled El Hadba, afin de les parachever dans les d\u00e9lais impartis\u00a0\u00bb, indique le communiqu\u00e9 du minist\u00e8re. Cette d\u00e9cision intervient apr\u00e8s un \u00e9tat des lieux complet de ces \u00ab\u00a0projets strat\u00e9giques majeurs auxquels le pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, accorde une grande importance\u00a0\u00bb. L&rsquo;urgence de la coordination ressort des instructions minist\u00e9rielles qui mettent l&rsquo;accent sur \u00ab\u00a0la n\u00e9cessit\u00e9 de renforcer la coop\u00e9ration et la coordination \u00e9troite entre les diff\u00e9rents groupements d&rsquo;entreprises afin d&rsquo;assurer le parach\u00e8vement de tous les tron\u00e7ons dans les d\u00e9lais impartis\u00a0\u00bb.<\/p>\n\n\n\n<p>La premi\u00e8re r\u00e9union, d\u00e9di\u00e9e \u00e0 la ligne mini\u00e8re Ouest s&rsquo;\u00e9tendant sur 950 kilom\u00e8tres, a permis au directeur g\u00e9n\u00e9ral de l&rsquo;Agence nationale d&rsquo;\u00e9tudes et de suivi de la r\u00e9alisation des investissements ferroviaires (ANESRIF) de pr\u00e9senter \u00ab\u00a0un expos\u00e9 technique d\u00e9taill\u00e9 sur l&rsquo;\u00e9tat d&rsquo;avancement du projet et les obstacles rencontr\u00e9s\u00a0\u00bb. Face aux d\u00e9fis identifi\u00e9s, le ministre a propos\u00e9 \u00ab\u00a0des solutions pratiques pour acc\u00e9l\u00e9rer la cadence des travaux et renforcer la coordination avec les diff\u00e9rents d\u00e9partements minist\u00e9riels et les autorit\u00e9s des wilayas concern\u00e9es\u00a0\u00bb. L&rsquo;engagement des entreprises contractantes s&rsquo;est traduit par des promesses concr\u00e8tes. Selon le communiqu\u00e9, \u00ab\u00a0les entreprises de r\u00e9alisation ont fait part de leur engagement \u00e0 livrer le projet dans son int\u00e9gralit\u00e9 avant la fin de l&rsquo;ann\u00e9e en cours, soit avant les d\u00e9lais contractuels\u00a0\u00bb. Cette ligne strat\u00e9gique comprend trois tron\u00e7ons principaux dont le premier, long de 575 kilom\u00e8tres et r\u00e9alis\u00e9 par un groupement alg\u00e9ro-chinois, affiche d\u00e9j\u00e0 la livraison d&rsquo;un segment de 135 kilom\u00e8tres en juillet dernier. La deuxi\u00e8me r\u00e9union a port\u00e9 sur la ligne mini\u00e8re Est reliant Annaba \u00e0 Bled El Hadba sur 422 kilom\u00e8tres, \u00ab\u00a0inscrit dans le projet global d&rsquo;exploitation et de transformation du phosphate\u00a0\u00bb. Ce projet multitron\u00e7ons mobilise un \u00e9ventail d&rsquo;entreprises nationales et alg\u00e9ro-chinoises selon une r\u00e9partition g\u00e9ographique pr\u00e9cise, notamment le tron\u00e7on nord Annaba-Bouchegouf confi\u00e9 aux entreprises nationales et le segment central Bouchegouf-Dr\u00e9a\u2013Souk Ahras aux partenaires alg\u00e9ro-chinois.<\/p>\n\n\n\n<p>L&rsquo;intensification des cadences fait l&rsquo;objet d&rsquo;engagements formels. Les entreprises nationales et \u00e9trang\u00e8res \u00ab\u00a0se sont engag\u00e9es \u00e0 mobiliser tous les moyens mat\u00e9riels et humains n\u00e9cessaires, en veillant \u00e0 fournir en quantit\u00e9s suffisantes les mat\u00e9riaux et \u00e9quipements indispensables pour assurer la continuit\u00e9 des travaux \u00e0 pleine capacit\u00e9, et \u00e0 organiser le travail selon un syst\u00e8me de rotation (8&#215;3) pour achever les travaux au niveau des chantiers dans les d\u00e9lais impartis\u00a0\u00bb, pr\u00e9cise le communiqu\u00e9.<\/p>\n\n\n\n<p>Parall\u00e8lement, le ministre a renforc\u00e9 le suivi de l&rsquo;expansion du port min\u00e9ralier d&rsquo;Annaba en \u00ab\u00a0d\u00e9cidant la cr\u00e9ation d&rsquo;une cellule de suivi du d\u00e9roulement des travaux de ce projet, regroupant l&rsquo;ensemble des acteurs, dont la directrice centrale de d\u00e9veloppement des infrastructures portuaires\u00a0\u00bb, selon le communiqu\u00e9 du minist\u00e8re. Cette initiative vise \u00e0 \u00ab\u00a0assurer et renforcer le suivi minutieux et efficace des diff\u00e9rentes phases de r\u00e9alisation\u00a0\u00bb d&rsquo;un projet qui pr\u00e9voit \u00e9galement \u00ab\u00a0la r\u00e9alisation d&rsquo;un quai min\u00e9ralier dans le cadre du projet int\u00e9gr\u00e9 du phosphate\u00a0\u00bb. L&rsquo;expertise personnelle du ministre, ancien wali d&rsquo;Annaba ayant supervis\u00e9 ces travaux, lui a permis de \u00ab\u00a0pr\u00e9senter des solutions efficaces pour le traitement des difficult\u00e9s soulev\u00e9es, afin d&rsquo;acc\u00e9l\u00e9rer le rythme des travaux et parachever l&rsquo;op\u00e9ration de r\u00e9alisation\u00a0\u00bb. Le consortium alg\u00e9ro-chinois associant Cosider travaux publics, la M\u00e9diterran\u00e9enne des travaux maritimes (Meditram) et la China Harbour Engineering Company (CHEC) s&rsquo;est engag\u00e9 \u00e0 \u00ab\u00a0fournir et fabriquer tous les mat\u00e9riaux et les \u00e9quipements n\u00e9cessaires en un temps record et bien d\u00e9fini\u00a0\u00bb. Cette mobilisation g\u00e9n\u00e9rale s&rsquo;inscrit dans \u00ab\u00a0une s\u00e9rie de r\u00e9unions p\u00e9riodiques organis\u00e9es par le ministre avec les responsables des Groupes \u00e9conomiques et de leurs filiales, des agences nationales et des organismes sous tutelle du domaine des infrastructures\u00a0\u00bb. Ces rencontres ont permis \u00ab\u00a0de finaliser les derniers pr\u00e9paratifs pour les visites de terrain qu&rsquo;il effectuera au cours des prochains jours, afin de d\u00e9cider des mesures n\u00e9cessaires \u00e0 prendre sur le terrain pour acc\u00e9l\u00e9rer la r\u00e9alisation des deux lignes et aplanir les obstacles potentiels\u00a0\u00bb, conclut le communiqu\u00e9 minist\u00e9riel.<\/p>\n\n\n\n<p>Sofia Chahine<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre des Travaux publics et des Infrastructures de base, Abdelkader Djellaoui, intensifie le pilotage des grands chantiers miniers du<\/p>\n","protected":false},"author":6,"featured_media":73663,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[29],"tags":[],"class_list":["post-73662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lignes ferroviaires mini\u00e8res et projets protuaires\u00a0: Djellaoui au pas de charge - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lignes ferroviaires mini\u00e8res et projets protuaires\u00a0: Djellaoui au pas de charge - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le ministre des Travaux publics et des Infrastructures de base, Abdelkader Djellaoui, intensifie le pilotage des grands chantiers miniers du\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-22T12:25:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-22T12:25:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/09\/548734567_1095701339416392_5162066607202500041_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/09\\\/22\\\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/09\\\/22\\\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Lignes ferroviaires mini\u00e8res et projets protuaires\u00a0: Djellaoui au pas de charge\",\"datePublished\":\"2025-09-22T12:25:32+00:00\",\"dateModified\":\"2025-09-22T12:25:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/09\\\/22\\\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\\\/\"},\"wordCount\":878,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/09\\\/22\\\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/548734567_1095701339416392_5162066607202500041_n.jpg\",\"articleSection\":[\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/09\\\/22\\\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/09\\\/22\\\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/09\\\/22\\\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\\\/\",\"name\":\"Lignes ferroviaires mini\u00e8res et projets protuaires\u00a0: Djellaoui au pas de charge - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/09\\\/22\\\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/09\\\/22\\\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/548734567_1095701339416392_5162066607202500041_n.jpg\",\"datePublished\":\"2025-09-22T12:25:32+00:00\",\"dateModified\":\"2025-09-22T12:25:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/09\\\/22\\\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/09\\\/22\\\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/09\\\/22\\\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/548734567_1095701339416392_5162066607202500041_n.jpg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/548734567_1095701339416392_5162066607202500041_n.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/09\\\/22\\\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lignes ferroviaires mini\u00e8res et projets protuaires\u00a0: Djellaoui au pas de charge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lignes ferroviaires mini\u00e8res et projets protuaires\u00a0: Djellaoui au pas de charge - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/","og_locale":"fr_FR","og_type":"article","og_title":"Lignes ferroviaires mini\u00e8res et projets protuaires\u00a0: Djellaoui au pas de charge - La Sentinelle","og_description":"Le ministre des Travaux publics et des Infrastructures de base, Abdelkader Djellaoui, intensifie le pilotage des grands chantiers miniers du","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-09-22T12:25:32+00:00","article_modified_time":"2025-09-22T12:25:33+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/09\/548734567_1095701339416392_5162066607202500041_n.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Lignes ferroviaires mini\u00e8res et projets protuaires\u00a0: Djellaoui au pas de charge","datePublished":"2025-09-22T12:25:32+00:00","dateModified":"2025-09-22T12:25:33+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/"},"wordCount":878,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/09\/548734567_1095701339416392_5162066607202500041_n.jpg","articleSection":["\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/","name":"Lignes ferroviaires mini\u00e8res et projets protuaires\u00a0: Djellaoui au pas de charge - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/09\/548734567_1095701339416392_5162066607202500041_n.jpg","datePublished":"2025-09-22T12:25:32+00:00","dateModified":"2025-09-22T12:25:33+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/09\/548734567_1095701339416392_5162066607202500041_n.jpg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/09\/548734567_1095701339416392_5162066607202500041_n.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/09\/22\/lignes-ferroviaires-minieres-et-projets-protuaires-djellaoui-au-pas-de-charge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Lignes ferroviaires mini\u00e8res et projets protuaires\u00a0: Djellaoui au pas de charge"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/73662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=73662"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/73662\/revisions"}],"predecessor-version":[{"id":73664,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/73662\/revisions\/73664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/73663"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=73662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=73662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=73662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}