{"id":74306,"date":"2025-10-07T13:21:45","date_gmt":"2025-10-07T12:21:45","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=74306"},"modified":"2025-10-07T13:21:46","modified_gmt":"2025-10-07T12:21:46","slug":"alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/","title":{"rendered":"Alexey Solomatine, ambassadeur de Russie \u00e0 Alger\u00a0: \u00ab\u00a0L&rsquo;Alg\u00e9rie, partenaire strat\u00e9gique de premier plan\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00ab\u00a0L&rsquo;Alg\u00e9rie constitue un partenaire strat\u00e9gique de premier plan pour la Russie\u00a0\u00bb. Cette d\u00e9claration de l&rsquo;ambassadeur russe Alexey Solomatine, lors de son audience avec le pr\u00e9sident de l&rsquo;APN, Brahim Boughali, r\u00e9sume la solidit\u00e9 d&rsquo;une relation bilat\u00e9rale que les deux parties s&#8217;emploient \u00e0 renforcer dans tous les domaines. Le pr\u00e9sident de l&rsquo;Assembl\u00e9e populaire nationale, Brahim Boughali, a en effet re\u00e7u lundi au si\u00e8ge de l&rsquo;Assembl\u00e9e l&rsquo;ambassadeur de la F\u00e9d\u00e9ration de Russie en Alg\u00e9rie, Alexey Solomatine. Cette rencontre, qui s&rsquo;est d\u00e9roul\u00e9e en pr\u00e9sence du pr\u00e9sident du Groupe parlementaire d&rsquo;amiti\u00e9 \u00ab\u00a0Alg\u00e9rie-Russie\u00a0\u00bb, a permis de r\u00e9affirmer l&rsquo;excellence d&rsquo;un partenariat qui s&rsquo;inscrit dans la dur\u00e9e et ne cesse de se diversifier. D\u00e8s l&rsquo;ouverture de l&rsquo;audience, M. Boughali a tenu \u00e0 &nbsp;souligner la profondeur des relations historiques qui unissent les deux pays amis et affirmant que l&rsquo;exp\u00e9rience de M. Solomatine contribuera \u00e0 renforcer et \u00e0 consolider ces liens dans divers domaines\u00a0\u00bb. Le pr\u00e9sident de l&rsquo;APN a rappel\u00e9 que \u00ab\u00a0les relations alg\u00e9ro-russes sont anciennes et solides\u00a0\u00bb, selon le communiqu\u00e9 officiel de l&rsquo;Assembl\u00e9e. Cette profondeur historique n&rsquo;est pas qu&rsquo;un simple rappel protocolaire. Elle traduit une r\u00e9alit\u00e9 tangible : depuis la lutte pour l&rsquo;ind\u00e9pendance, o\u00f9 l&rsquo;Union sovi\u00e9tique a soutenu la cause alg\u00e9rienne, jusqu&rsquo;aux d\u00e9fis contemporains, Moscou et Alger ont maintenu une relation privil\u00e9gi\u00e9e, fond\u00e9e sur le respect mutuel et la convergence de vues sur de nombreux dossiers internationaux. Le pr\u00e9sident de l&rsquo;APN a \u00ab\u00a0mis en avant la visite r\u00e9cente du Pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, \u00e0 Moscou, qui a donn\u00e9 un nouvel \u00e9lan aux relations strat\u00e9giques entre les deux pays\u00a0\u00bb. Ce d\u00e9placement pr\u00e9sidentiel a marqu\u00e9 une \u00e9tape importante dans le renforcement du partenariat bilat\u00e9ral, ouvrant la voie \u00e0 de nouvelles perspectives de coop\u00e9ration. La dimension strat\u00e9gique de cette visite ne se limite pas aux aspects symboliques. Elle s&rsquo;est traduite par la signature d&rsquo;accords concrets et l&rsquo;identification de secteurs prioritaires pour une collaboration renforc\u00e9e, faisant de l&rsquo;Alg\u00e9rie un acteur incontournable de la politique russe en Afrique et en M\u00e9diterran\u00e9e. M. Boughali a insist\u00e9 sur \u00ab\u00a0la n\u00e9cessit\u00e9 de renforcer la coop\u00e9ration \u00e9conomique entre l&rsquo;Alg\u00e9rie et la Russie, en diversifiant les \u00e9changes et en ouvrant la voie \u00e0 des partenariats \u00e9largis dans les secteurs de l&rsquo;industrie, de l&rsquo;agriculture, ainsi que de la recherche et de la technologie\u00a0\u00bb. Cette volont\u00e9 de diversification r\u00e9pond \u00e0 une ambition partag\u00e9e : d\u00e9passer les \u00e9changes traditionnels pour construire une relation \u00e9conomique plus dense et \u00e9quilibr\u00e9e. L&rsquo;expertise russe dans les domaines industriels et technologiques repr\u00e9sente un atout majeur pour l&rsquo;Alg\u00e9rie, qui cherche \u00e0 moderniser son \u00e9conomie et \u00e0 r\u00e9duire sa d\u00e9pendance aux hydrocarbures. De son c\u00f4t\u00e9, la Russie voit dans le march\u00e9 alg\u00e9rien et dans sa position g\u00e9ographique strat\u00e9gique une porte d&rsquo;entr\u00e9e vers l&rsquo;Afrique et la r\u00e9gion m\u00e9diterran\u00e9enne. Le pr\u00e9sident de l&rsquo;APN a mis en exergue \u00ab\u00a0l&rsquo;excellence de la coop\u00e9ration parlementaire entre les deux pays, saluant les relations unissant l&rsquo;APN et la Douma d&rsquo;\u00c9tat russe\u00a0\u00bb. Il a exprim\u00e9 \u00ab\u00a0sa gratitude au Pr\u00e9sident de la Douma pour l&rsquo;invitation qui lui a \u00e9t\u00e9 adress\u00e9e \u00e0 se rendre en Russie, tout en r\u00e9it\u00e9rant la bienvenue \u00e0 toutes les d\u00e9l\u00e9gations parlementaires russes d\u00e9sireuses de visiter l&rsquo;Alg\u00e9rie\u00a0\u00bb. Cette coop\u00e9ration parlementaire constitue un pilier essentiel du partenariat strat\u00e9gique. Elle permet non seulement des \u00e9changes d&rsquo;exp\u00e9riences l\u00e9gislatives, mais aussi une coordination sur les grandes questions internationales et le renforcement des liens entre les soci\u00e9t\u00e9s civiles des deux pays. M. Boughali a estim\u00e9 que \u00ab\u00a0le succ\u00e8s de la Foire du commerce intra-africain, r\u00e9cemment organis\u00e9e en Alg\u00e9rie, pourrait constituer un exemple \u00e0 suivre pour renforcer la coop\u00e9ration commerciale entre l&rsquo;Alg\u00e9rie et la Russie, d&rsquo;autant plus que les deux pays partagent des positions convergentes sur les causes internationales justes\u00a0\u00bb. Il a salu\u00e9, \u00e0 ce titre, \u00ab\u00a0la position de la Russie au Conseil de s\u00e9curit\u00e9 concernant la question sahraouie\u00a0\u00bb. Cette convergence de vues d\u00e9passe le simple cadre bilat\u00e9ral. Elle refl\u00e8te une vision commune du syst\u00e8me international, fond\u00e9e sur le multilat\u00e9ralisme, le respect de la souverainet\u00e9 des \u00c9tats et le soutien aux causes justes. Qu&rsquo;il s&rsquo;agisse du dossier sahraoui, de la question palestinienne ou de la r\u00e9forme des instances onusiennes, Alger et Moscou d\u00e9fendent des positions souvent similaires. L&rsquo;ambassadeur Alexey Solomatine a exprim\u00e9 \u00ab\u00a0la volont\u00e9 ferme de son pays de consolider davantage les relations bilat\u00e9rales entre la Russie et l&rsquo;Alg\u00e9rie, soulignant que les deux nations entretiennent une coop\u00e9ration \u00e9troite dans les domaines politique, \u00e9conomique et militaire, et que l&rsquo;Alg\u00e9rie constitue un partenaire strat\u00e9gique de premier plan pour la Russie\u00a0\u00bb. Cette qualification de \u00ab\u00a0partenaire strat\u00e9gique de premier plan\u00a0\u00bb n&rsquo;est pas anodine. Elle place l&rsquo;Alg\u00e9rie dans le cercle restreint des pays avec lesquels la Russie entretient des relations privil\u00e9gi\u00e9es, au m\u00eame titre que certaines grandes puissances \u00e9mergentes. Le diplomate russe a conclu en insistant sur \u00ab\u00a0la n\u00e9cessit\u00e9 d&rsquo;approfondir la coop\u00e9ration parlementaire entre les deux pays, estimant que le partenariat alg\u00e9ro-russe se caract\u00e9rise par la profondeur de ses liens et l&rsquo;\u00e9tendue de ses perspectives, affirmant qu&rsquo;il n&rsquo;existe aucune limite au d\u00e9veloppement et \u00e0 l&rsquo;essor de ces relations\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette d\u00e9claration, qui cl\u00f4ture l&rsquo;audience, r\u00e9sume l&rsquo;essence m\u00eame du partenariat alg\u00e9ro-russe : une relation sans plafond, port\u00e9e par une volont\u00e9 politique commune et des int\u00e9r\u00eats convergents, tant sur le plan bilat\u00e9ral que sur la sc\u00e8ne internationale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Malik Meziane<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0L&rsquo;Alg\u00e9rie constitue un partenaire strat\u00e9gique de premier plan pour la Russie\u00a0\u00bb. Cette d\u00e9claration de l&rsquo;ambassadeur russe Alexey Solomatine, lors de<\/p>\n","protected":false},"author":6,"featured_media":74307,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-74306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alexey Solomatine, ambassadeur de Russie \u00e0 Alger\u00a0: \u00ab\u00a0L&rsquo;Alg\u00e9rie, partenaire strat\u00e9gique de premier plan\u00a0\u00bb - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alexey Solomatine, ambassadeur de Russie \u00e0 Alger\u00a0: \u00ab\u00a0L&rsquo;Alg\u00e9rie, partenaire strat\u00e9gique de premier plan\u00a0\u00bb - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"\u00ab\u00a0L&rsquo;Alg\u00e9rie constitue un partenaire strat\u00e9gique de premier plan pour la Russie\u00a0\u00bb. Cette d\u00e9claration de l&rsquo;ambassadeur russe Alexey Solomatine, lors de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-07T12:21:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T12:21:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/557639489_1258885826279310_6887563026525564073_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1849\" \/>\n\t<meta property=\"og:image:height\" content=\"1193\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/07\\\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/07\\\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Alexey Solomatine, ambassadeur de Russie \u00e0 Alger\u00a0: \u00ab\u00a0L&rsquo;Alg\u00e9rie, partenaire strat\u00e9gique de premier plan\u00a0\u00bb\",\"datePublished\":\"2025-10-07T12:21:45+00:00\",\"dateModified\":\"2025-10-07T12:21:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/07\\\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\\\/\"},\"wordCount\":1023,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/07\\\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/557639489_1258885826279310_6887563026525564073_n.jpg\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/07\\\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/07\\\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/07\\\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\\\/\",\"name\":\"Alexey Solomatine, ambassadeur de Russie \u00e0 Alger\u00a0: \u00ab\u00a0L&rsquo;Alg\u00e9rie, partenaire strat\u00e9gique de premier plan\u00a0\u00bb - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/07\\\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/07\\\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/557639489_1258885826279310_6887563026525564073_n.jpg\",\"datePublished\":\"2025-10-07T12:21:45+00:00\",\"dateModified\":\"2025-10-07T12:21:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/07\\\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/07\\\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/07\\\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/557639489_1258885826279310_6887563026525564073_n.jpg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/557639489_1258885826279310_6887563026525564073_n.jpg\",\"width\":1849,\"height\":1193},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/07\\\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alexey Solomatine, ambassadeur de Russie \u00e0 Alger\u00a0: \u00ab\u00a0L&rsquo;Alg\u00e9rie, partenaire strat\u00e9gique de premier plan\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alexey Solomatine, ambassadeur de Russie \u00e0 Alger\u00a0: \u00ab\u00a0L&rsquo;Alg\u00e9rie, partenaire strat\u00e9gique de premier plan\u00a0\u00bb - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/","og_locale":"fr_FR","og_type":"article","og_title":"Alexey Solomatine, ambassadeur de Russie \u00e0 Alger\u00a0: \u00ab\u00a0L&rsquo;Alg\u00e9rie, partenaire strat\u00e9gique de premier plan\u00a0\u00bb - La Sentinelle","og_description":"\u00ab\u00a0L&rsquo;Alg\u00e9rie constitue un partenaire strat\u00e9gique de premier plan pour la Russie\u00a0\u00bb. Cette d\u00e9claration de l&rsquo;ambassadeur russe Alexey Solomatine, lors de","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-10-07T12:21:45+00:00","article_modified_time":"2025-10-07T12:21:46+00:00","og_image":[{"width":1849,"height":1193,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/557639489_1258885826279310_6887563026525564073_n.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Alexey Solomatine, ambassadeur de Russie \u00e0 Alger\u00a0: \u00ab\u00a0L&rsquo;Alg\u00e9rie, partenaire strat\u00e9gique de premier plan\u00a0\u00bb","datePublished":"2025-10-07T12:21:45+00:00","dateModified":"2025-10-07T12:21:46+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/"},"wordCount":1023,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/557639489_1258885826279310_6887563026525564073_n.jpg","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/","name":"Alexey Solomatine, ambassadeur de Russie \u00e0 Alger\u00a0: \u00ab\u00a0L&rsquo;Alg\u00e9rie, partenaire strat\u00e9gique de premier plan\u00a0\u00bb - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/557639489_1258885826279310_6887563026525564073_n.jpg","datePublished":"2025-10-07T12:21:45+00:00","dateModified":"2025-10-07T12:21:46+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/557639489_1258885826279310_6887563026525564073_n.jpg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/557639489_1258885826279310_6887563026525564073_n.jpg","width":1849,"height":1193},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/07\/alexey-solomatine-ambassadeur-de-russie-a-alger-lalgerie-partenaire-strategique-de-premier-plan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Alexey Solomatine, ambassadeur de Russie \u00e0 Alger\u00a0: \u00ab\u00a0L&rsquo;Alg\u00e9rie, partenaire strat\u00e9gique de premier plan\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/74306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=74306"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/74306\/revisions"}],"predecessor-version":[{"id":74309,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/74306\/revisions\/74309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/74307"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=74306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=74306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=74306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}