{"id":74412,"date":"2025-10-08T13:25:25","date_gmt":"2025-10-08T12:25:25","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=74412"},"modified":"2025-10-08T13:25:26","modified_gmt":"2025-10-08T12:25:26","slug":"laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/08\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\/","title":{"rendered":"L&rsquo;AIE pr\u00e9voit un essor historique des \u00e9nergies renouvelables d&rsquo;ici 2030"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L&rsquo;Agence internationale de l&rsquo;\u00e9nergie (AIE) anticipe une progression spectaculaire des capacit\u00e9s mondiales d&rsquo;\u00e9nergie renouvelable au cours des cinq prochaines ann\u00e9es. Selon son rapport annuel Renewables 2025 publi\u00e9 lundi, les installations devraient augmenter de 4 600 gigawatts (GW) d&rsquo;ici 2030, \u00ab\u00a0soit l&rsquo;\u00e9quivalent de la capacit\u00e9 totale actuelle de production d&rsquo;\u00e9lectricit\u00e9 de la Chine, de l&rsquo;Union europ\u00e9enne et du Japon\u00a0\u00bb. Le solaire photovolta\u00efque s&rsquo;impose, selon les m\u00eames pr\u00e9visions, comme le moteur principal de cette croissance et \u00ab\u00a0devrait repr\u00e9senter environ 80 % de cette croissance, stimul\u00e9 par des co\u00fbts faibles et des d\u00e9lais d&rsquo;autorisation courts\u00a0\u00bb. Cette pr\u00e9dominance s&rsquo;explique par la comp\u00e9titivit\u00e9 \u00e9conomique d\u00e9sormais acquise de cette technologie, devenue l&rsquo;une des sources d&rsquo;\u00e9lectricit\u00e9 les moins co\u00fbteuses sur de nombreux march\u00e9s. L&rsquo;\u00e9olien, l&rsquo;hydro\u00e9lectricit\u00e9, la bio\u00e9nergie et la g\u00e9othermie contribueront, souligne l\u2019AIE, \u00e0 cette progression, avec notamment une acc\u00e9l\u00e9ration notable des installations g\u00e9othermiques aux Etats-Unis, au Japon et dans de nombreuses \u00e9conomies \u00e9mergentes et en d\u00e9veloppement. La dynamique s&rsquo;av\u00e8re particuli\u00e8rement prometteuse dans les \u00e9conomies \u00e9mergentes d&rsquo;Asie, du Moyen-Orient et d&rsquo;Afrique, o\u00f9 la comp\u00e9titivit\u00e9 des co\u00fbts et le renforcement du soutien politique favorisent la croissance des \u00e9nergies renouvelables. De nombreux gouvernements introduisent de nouveaux programmes d&rsquo;ench\u00e8res et rel\u00e8vent leurs objectifs nationaux, estime l\u2019agence. Au-del\u00e0 du secteur \u00e9lectrique, les \u00e9nergies renouvelables gagnent progressivement du terrain dans les transports et le chauffage, bien que ces segments affichent une p\u00e9n\u00e9tration plus modeste, ajoute la m\u00eame source. Dans le secteur des transports, la consommation d&rsquo;\u00e9nergie renouvelable devrait passer de 4 % actuellement \u00e0 6 %, principalement gr\u00e2ce aux v\u00e9hicules \u00e9lectriques en Chine et en Europe et aux biocarburants sur des march\u00e9s cl\u00e9s comme le Br\u00e9sil, l&rsquo;Indon\u00e9sie et l&rsquo;Inde, selon les m\u00eames pr\u00e9visions. Et d\u2019ajouter que l&rsquo;\u00e9lectrification de la mobilit\u00e9 et le d\u00e9veloppement des biocarburants de nouvelle g\u00e9n\u00e9ration constituent les deux leviers majeurs de cette \u00e9volution. Concernant le chauffage des b\u00e2timents et de l&rsquo;industrie, \u00ab\u00a0la part des \u00e9nergies renouvelables devrait passer de 14 % \u00e0 18 % d&rsquo;ici 2030\u00a0\u00bb. Cette progression, quoique plus limit\u00e9e, repr\u00e9sente n\u00e9anmoins un d\u00e9fi consid\u00e9rable compte tenu de l&rsquo;inertie de ces secteurs traditionnellement d\u00e9pendants des \u00e9nergies fossiles. Les pompes \u00e0 chaleur, la biomasse et la g\u00e9othermie constituent les principales technologies appel\u00e9es \u00e0 se d\u00e9velopper dans ces usages thermiques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S.G.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Agence internationale de l&rsquo;\u00e9nergie (AIE) anticipe une progression spectaculaire des capacit\u00e9s mondiales d&rsquo;\u00e9nergie renouvelable au cours des cinq prochaines ann\u00e9es.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[29],"tags":[],"class_list":["post-74412","post","type-post","status-publish","format-standard","hentry","category-economie"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&rsquo;AIE pr\u00e9voit un essor historique des \u00e9nergies renouvelables d&rsquo;ici 2030 - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/08\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&rsquo;AIE pr\u00e9voit un essor historique des \u00e9nergies renouvelables d&rsquo;ici 2030 - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;Agence internationale de l&rsquo;\u00e9nergie (AIE) anticipe une progression spectaculaire des capacit\u00e9s mondiales d&rsquo;\u00e9nergie renouvelable au cours des cinq prochaines ann\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/08\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-08T12:25:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T12:25:26+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/08\\\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/08\\\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"L&rsquo;AIE pr\u00e9voit un essor historique des \u00e9nergies renouvelables d&rsquo;ici 2030\",\"datePublished\":\"2025-10-08T12:25:25+00:00\",\"dateModified\":\"2025-10-08T12:25:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/08\\\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\\\/\"},\"wordCount\":435,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"articleSection\":[\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/08\\\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/08\\\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/08\\\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\\\/\",\"name\":\"L&rsquo;AIE pr\u00e9voit un essor historique des \u00e9nergies renouvelables d&rsquo;ici 2030 - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"datePublished\":\"2025-10-08T12:25:25+00:00\",\"dateModified\":\"2025-10-08T12:25:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/08\\\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/08\\\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/08\\\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;AIE pr\u00e9voit un essor historique des \u00e9nergies renouvelables d&rsquo;ici 2030\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L&rsquo;AIE pr\u00e9voit un essor historique des \u00e9nergies renouvelables d&rsquo;ici 2030 - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/08\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\/","og_locale":"fr_FR","og_type":"article","og_title":"L&rsquo;AIE pr\u00e9voit un essor historique des \u00e9nergies renouvelables d&rsquo;ici 2030 - La Sentinelle","og_description":"L&rsquo;Agence internationale de l&rsquo;\u00e9nergie (AIE) anticipe une progression spectaculaire des capacit\u00e9s mondiales d&rsquo;\u00e9nergie renouvelable au cours des cinq prochaines ann\u00e9es.","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/08\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-10-08T12:25:25+00:00","article_modified_time":"2025-10-08T12:25:26+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/08\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/08\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"L&rsquo;AIE pr\u00e9voit un essor historique des \u00e9nergies renouvelables d&rsquo;ici 2030","datePublished":"2025-10-08T12:25:25+00:00","dateModified":"2025-10-08T12:25:26+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/08\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\/"},"wordCount":435,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"articleSection":["\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/10\/08\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/08\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/08\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\/","name":"L&rsquo;AIE pr\u00e9voit un essor historique des \u00e9nergies renouvelables d&rsquo;ici 2030 - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"datePublished":"2025-10-08T12:25:25+00:00","dateModified":"2025-10-08T12:25:26+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/08\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/10\/08\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/08\/laie-prevoit-un-essor-historique-des-energies-renouvelables-dici-2030\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;AIE pr\u00e9voit un essor historique des \u00e9nergies renouvelables d&rsquo;ici 2030"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/74412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=74412"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/74412\/revisions"}],"predecessor-version":[{"id":74414,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/74412\/revisions\/74414"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=74412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=74412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=74412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}