{"id":74457,"date":"2025-10-09T13:31:39","date_gmt":"2025-10-09T12:31:39","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=74457"},"modified":"2025-10-11T13:32:52","modified_gmt":"2025-10-11T12:32:52","slug":"ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/","title":{"rendered":"Ligue 1 Mobilis\u00a0: Le calendrier de la huiti\u00e8me journ\u00e9e d\u00e9voil\u00e9"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Ligue de football professionnel a d\u00e9voil\u00e9 mardi le calendrier complet de la huiti\u00e8me journ\u00e9e du championnat de Ligue 1 Mobilis qui s&rsquo;\u00e9talera sur cinq jours du vendredi 17 au mercredi 22 octobre prochain, avec une programmation \u00e9chelonn\u00e9e tenant compte des engagements continentaux des clubs alg\u00e9riens et offrant ainsi aux t\u00e9l\u00e9spectateurs et supporters un menu \u00e9tal\u00e9 permettant de suivre l&rsquo;ensemble des rencontres dans les meilleures conditions possibles. Cette journ\u00e9e qui s&rsquo;annonce particuli\u00e8rement int\u00e9ressante verra notamment le leader actuel la JS Saoura d\u00e9fendre sa premi\u00e8re place au classement lors d&rsquo;un d\u00e9placement p\u00e9rilleux \u00e0 Oran face au MC Oran, tandis que les deux repr\u00e9sentants alg\u00e9riens en Ligue des champions d&rsquo;Afrique b\u00e9n\u00e9ficieront de dates de jeu am\u00e9nag\u00e9es pour pr\u00e9server leur r\u00e9cup\u00e9ration apr\u00e8s leurs engagements continentaux. Deux matchs ouvriront le bal de cette huiti\u00e8me journ\u00e9e d\u00e8s le vendredi 17 octobre avec d&rsquo;un c\u00f4t\u00e9 l&rsquo;affiche ES Mostaganem contre ASO Chlef qui opposera deux formations en qu\u00eate de points pour se stabiliser dans la premi\u00e8re moiti\u00e9 du tableau et de l&rsquo;autre le duel entre l&rsquo;Olympique Akbou et le MC El-Bayadh, deux \u00e9quipes qui chercheront \u00e9galement \u00e0 engranger des points pr\u00e9cieux pour am\u00e9liorer leur position au classement g\u00e9n\u00e9ral. Ces deux rencontres du vendredi permettront de lancer la journ\u00e9e et donneront le ton pour la suite des hostilit\u00e9s dans un championnat qui s&rsquo;annonce particuli\u00e8rement disput\u00e9 et ind\u00e9cis cette saison au regard de l&rsquo;\u00e9quilibre qui r\u00e8gne actuellement entre les diff\u00e9rentes formations en pr\u00e9sence. Les p\u00e9rip\u00e9ties de cette huiti\u00e8me journ\u00e9e se poursuivront le samedi 18 octobre avec \u00e9galement deux affiches attractives au programme. L&rsquo;ES Ben Aknoun recevra le CS Constantine dans un match qui oppose deux clubs ambitieux d\u00e9sireux de s&rsquo;installer durablement dans le haut du tableau, tandis que le MC Oran accueillera le leader actuel la JS Saoura dans ce qui constitue sans conteste l&rsquo;affiche de cette journ\u00e9e. Cette rencontre entre le MCO et la JSS sera particuli\u00e8rement scrut\u00e9e puisque le club de B\u00e9char, qui tr\u00f4ne provisoirement en t\u00eate du classement avec quatorze points apr\u00e8s sept journ\u00e9es disput\u00e9es, poss\u00e8de deux longueurs d&rsquo;avance sur son poursuivant direct le MB Rouissat et voudra confirmer son excellent d\u00e9but de saison face \u00e0 une formation oranaise joueuse et dangereuse dans son stade devant son public.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les deux repr\u00e9sentants alg\u00e9riens engag\u00e9s en Ligue des champions d&rsquo;Afrique que sont le MC Alger et la JS Kabylie b\u00e9n\u00e9ficieront d&rsquo;un calendrier am\u00e9nag\u00e9 et joueront leurs matchs respectifs un peu plus tard dans la semaine afin de leur permettre de r\u00e9cup\u00e9rer convenablement apr\u00e8s leurs d\u00e9placements continentaux. Les Canaris de la JSK recevront la surprenante formation de l&rsquo;USM Khenchela le mardi 21 octobre dans ce qui constituera un test int\u00e9ressant pour les Canaris face \u00e0 une \u00e9quipe qui r\u00e9alise un d\u00e9but de championnat encourageant et qui voudra cr\u00e9er la surprise au stade du 1er novembre de Tizi-Ouzou. Le lendemain mercredi 22 octobre, le Doyen du football alg\u00e9rien le MC Alger accueillera le Paradou AC dans un derby alg\u00e9rois qui promet du spectacle entre deux \u00e9quipes habitu\u00e9es \u00e0 pratiquer un football offensif et spectaculaire et qui ne manqueront pas d&rsquo;offrir un beau spectacle aux amateurs du ballon rond. \u00c0 noter que deux matchs de cette huiti\u00e8me journ\u00e9e ont \u00e9t\u00e9 report\u00e9s \u00e0 une date ult\u00e9rieure qui sera communiqu\u00e9e prochainement par la Ligue de football professionnel. Il s&rsquo;agit des rencontres CR Belouizdad contre ES S\u00e9tif et USM Alger face au MB Rouissat, ces reports \u00e9tant motiv\u00e9s par l&rsquo;engagement des deux clubs alg\u00e9rois le CRB et l&rsquo;USMA au deuxi\u00e8me tour pr\u00e9liminaire de la Coupe de la Conf\u00e9d\u00e9ration africaine de football.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M.D.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Ligue de football professionnel a d\u00e9voil\u00e9 mardi le calendrier complet de la huiti\u00e8me journ\u00e9e du championnat de Ligue 1<\/p>\n","protected":false},"author":6,"featured_media":67611,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[33],"tags":[],"class_list":["post-74457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sports"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ligue 1 Mobilis\u00a0: Le calendrier de la huiti\u00e8me journ\u00e9e d\u00e9voil\u00e9 - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue 1 Mobilis\u00a0: Le calendrier de la huiti\u00e8me journ\u00e9e d\u00e9voil\u00e9 - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"La Ligue de football professionnel a d\u00e9voil\u00e9 mardi le calendrier complet de la huiti\u00e8me journ\u00e9e du championnat de Ligue 1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-09T12:31:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-11T12:32:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/Ligue-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/09\\\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/09\\\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Ligue 1 Mobilis\u00a0: Le calendrier de la huiti\u00e8me journ\u00e9e d\u00e9voil\u00e9\",\"datePublished\":\"2025-10-09T12:31:39+00:00\",\"dateModified\":\"2025-10-11T12:32:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/09\\\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\\\/\"},\"wordCount\":685,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/09\\\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Ligue-1.jpeg\",\"articleSection\":[\"Sports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/09\\\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/09\\\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/09\\\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\\\/\",\"name\":\"Ligue 1 Mobilis\u00a0: Le calendrier de la huiti\u00e8me journ\u00e9e d\u00e9voil\u00e9 - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/09\\\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/09\\\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Ligue-1.jpeg\",\"datePublished\":\"2025-10-09T12:31:39+00:00\",\"dateModified\":\"2025-10-11T12:32:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/09\\\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/09\\\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/09\\\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Ligue-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Ligue-1.jpeg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/10\\\/09\\\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue 1 Mobilis\u00a0: Le calendrier de la huiti\u00e8me journ\u00e9e d\u00e9voil\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ligue 1 Mobilis\u00a0: Le calendrier de la huiti\u00e8me journ\u00e9e d\u00e9voil\u00e9 - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue 1 Mobilis\u00a0: Le calendrier de la huiti\u00e8me journ\u00e9e d\u00e9voil\u00e9 - La Sentinelle","og_description":"La Ligue de football professionnel a d\u00e9voil\u00e9 mardi le calendrier complet de la huiti\u00e8me journ\u00e9e du championnat de Ligue 1","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-10-09T12:31:39+00:00","article_modified_time":"2025-10-11T12:32:52+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/Ligue-1.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Ligue 1 Mobilis\u00a0: Le calendrier de la huiti\u00e8me journ\u00e9e d\u00e9voil\u00e9","datePublished":"2025-10-09T12:31:39+00:00","dateModified":"2025-10-11T12:32:52+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/"},"wordCount":685,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/Ligue-1.jpeg","articleSection":["Sports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/","name":"Ligue 1 Mobilis\u00a0: Le calendrier de la huiti\u00e8me journ\u00e9e d\u00e9voil\u00e9 - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/Ligue-1.jpeg","datePublished":"2025-10-09T12:31:39+00:00","dateModified":"2025-10-11T12:32:52+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/Ligue-1.jpeg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/05\/Ligue-1.jpeg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/10\/09\/ligue-1-mobilis-le-calendrier-de-la-huitieme-journee-devoile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Ligue 1 Mobilis\u00a0: Le calendrier de la huiti\u00e8me journ\u00e9e d\u00e9voil\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/74457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=74457"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/74457\/revisions"}],"predecessor-version":[{"id":74458,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/74457\/revisions\/74458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/67611"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=74457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=74457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=74457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}