{"id":76228,"date":"2025-11-16T11:02:09","date_gmt":"2025-11-16T10:02:09","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=76228"},"modified":"2025-11-16T11:02:10","modified_gmt":"2025-11-16T10:02:10","slug":"ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/","title":{"rendered":"Ghaza sous le blocus isra\u00e9lien\u00a0:\u00a0La pluie aggrave le calvaire humanitaire\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Alors que de violentes pluies s&rsquo;abattent sur la bande de Ghaza ce week-end, l&rsquo;agence onusienne UNRWA d\u00e9nonce une situation devenue \u00ab\u00a0encore plus d\u00e9sesp\u00e9r\u00e9e\u00a0\u00bb pour les d\u00e9plac\u00e9s palestiniens, tandis que l\u2019entit\u00e9 sioniste&nbsp;continue de bloquer l&rsquo;entr\u00e9e de pr\u00e8s de 4 000 camions d&rsquo;aide humanitaire malgr\u00e9 le cessez-le-feu en vigueur depuis le 10 octobre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les images sont d\u00e9chirantes. Des milliers de tentes inond\u00e9es, des familles palestiniennes pataugeant dans la boue, des enfants grelottants sous des abris de fortune qui ne prot\u00e8gent ni de la chaleur estivale ni du froid hivernal. Vendredi et samedi matin, de fortes pr\u00e9cipitations se sont abattues sur l&rsquo;enclave palestinienne assi\u00e9g\u00e9e, transformant les camps de d\u00e9plac\u00e9s en v\u00e9ritables bourbiers. Pour ces populations qui survivent dans des conditions inhumaines depuis plus de deux ans d&rsquo;agression g\u00e9nocidaire isra\u00e9lienne, cette pluie repr\u00e9sente une catastrophe suppl\u00e9mentaire dans un calvaire sans fin.&nbsp;L&rsquo;UNRWA a lanc\u00e9 un cri d&rsquo;alarme samedi, avertissant que le syst\u00e8me de basse pression affectant actuellement Ghaza \u00ab\u00a0aura des r\u00e9percussions catastrophiques sur les personnes d\u00e9plac\u00e9es\u00a0\u00bb. L&rsquo;agence insiste sur l&rsquo;urgence absolue de faire entrer des abris dans le territoire. \u00ab\u00a0L&rsquo;UNRWA dispose de ces fournitures pour aider la population \u00e0 passer l&rsquo;hiver. Faisons-les entrer !\u00a0\u00bb, a martel\u00e9 l&rsquo;organisation, d\u00e9non\u00e7ant implicitement l&rsquo;obstruction isra\u00e9lienne. Le porte-parole de l&rsquo;ONU, St\u00e9phane Dujarric, s&rsquo;est dit profond\u00e9ment pr\u00e9occup\u00e9 par le fait que des milliers de familles d\u00e9plac\u00e9es sont d\u00e9sormais totalement expos\u00e9es \u00e0 des conditions climatiques extr\u00eames, ce qui accro\u00eet les inqui\u00e9tudes concernant leur sant\u00e9 et leur protection.&nbsp;Cette catastrophe humanitaire trouve son origine dans la destruction quasi-totale de Ghaza. L&rsquo;agression isra\u00e9lienne a entra\u00een\u00e9 la destruction compl\u00e8te ou partielle de 92&nbsp;%&nbsp;des b\u00e2timents r\u00e9sidentiels du secteur, contraignant la majorit\u00e9 des citoyens \u00e0 se d\u00e9placer dans des tentes ou \u00e0 vivre dans des maisons fissur\u00e9es, malgr\u00e9 le risque constant d&rsquo;effondrement. Les \u00e9quipes humanitaires font ce qu&rsquo;elles peuvent avec des moyens d\u00e9risoires. Le Bureau de la coordination des affaires humanitaires des Nations Unies a indiqu\u00e9 que jeudi dernier seulement, environ 1 000 tentes ont \u00e9t\u00e9 distribu\u00e9es aux familles de Deir al-Balah et de Khan Youn\u00e8s. Entre dimanche et mercredi derniers, les partenaires ont fourni environ 7 000 couvertures \u00e0 plus de 1 800 familles, environ 15 000 b\u00e2ches \u00e0 plus de 3 700 familles et des v\u00eatements d&rsquo;hiver \u00e0 plus de 500 familles. Mais ces efforts restent une goutte d&rsquo;eau face \u00e0 l&rsquo;ampleur des besoins.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Car le probl\u00e8me majeur demeure le blocus isra\u00e9lien. L&rsquo;ONU a r\u00e9v\u00e9l\u00e9 vendredi que l\u2019entit\u00e9 sioniste&nbsp;a refus\u00e9 depuis le cessez-le-feu du 10 octobre l&rsquo;entr\u00e9e \u00e0 Ghaza d&rsquo;environ 4 000 camions d&rsquo;aide humanitaire d&rsquo;urgence, comprenant tentes, couvertures et kits de cuisine, malgr\u00e9 les demandes r\u00e9p\u00e9t\u00e9es de neuf organisations partenaires. \u00ab\u00a0Les autorit\u00e9s isra\u00e9liennes ne facilitent toujours pas l&rsquo;acc\u00e8s humanitaire\u00a0\u00bb, a d\u00e9nonc\u00e9 St\u00e9phane Dujarric lors du point presse quotidien. L&rsquo;OCHA a pr\u00e9cis\u00e9 qu&rsquo;Isra\u00ebl a rejet\u00e9 23 demandes visant \u00e0 acheminer pr\u00e8s de 4 000 palettes de fournitures essentielles, notamment des tentes, des outils d&rsquo;isolation et de charpente, des matelas, des ustensiles de cuisine et des couvertures. Les partenaires des centres d&rsquo;h\u00e9bergement ont soulign\u00e9 qu&rsquo;une pr\u00e9vention ad\u00e9quate des inondations n\u00e9cessite des \u00e9quipements qui ne sont tout simplement pas disponibles \u00e0 Ghaza, notamment des outils pour \u00e9vacuer l&rsquo;eau des tentes et pour enlever les d\u00e9chets solides et les d\u00e9bris.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les conditions de vie pr\u00e9caires accroissent \u00e9galement la vuln\u00e9rabilit\u00e9 des populations aux engins explosifs, les enfants \u00e9tant parmi les plus expos\u00e9s. Certaines personnes ont \u00e9t\u00e9 bless\u00e9es en ramassant du bois de chauffage, tandis que d&rsquo;autres sont contraintes de camper pr\u00e8s de zones soup\u00e7onn\u00e9es de contenir des munitions non explos\u00e9es, faute d&rsquo;alternatives plus s\u00fbres. Parall\u00e8lement, en Cisjordanie occup\u00e9e, le Haut-Commissariat aux droits de l&rsquo;homme a fermement condamn\u00e9 vendredi les attaques men\u00e9es ces derniers jours par des groupes de colons masqu\u00e9s. Le mois d&rsquo;octobre a enregistr\u00e9 davantage d&rsquo;attaques de colons que n&rsquo;importe quel autre mois depuis 2006, soit plus de 260 incidents recens\u00e9s. Depuis le 7 octobre 2023, les forces d&rsquo;occupation isra\u00e9liennes et les colons ont tu\u00e9 au moins 1 017 Palestiniens en Cisjordanie, y compris \u00e0 J\u00e9rusalem-Est, dont 221 enfants.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur le plan diplomatique, le Conseil de s\u00e9curit\u00e9 de l&rsquo;ONU se prononcera lundi sur un projet de r\u00e9solution am\u00e9ricain soutenant le plan de paix du pr\u00e9sident Donald Trump pour Ghaza. Le texte pr\u00e9voit notamment la cr\u00e9ation d&rsquo;une force internationale de stabilisation et salue la mise en place d&rsquo;un Conseil de la paix, une autorit\u00e9 de transition pour Ghaza que Trump pr\u00e9siderait th\u00e9oriquement jusqu&rsquo;\u00e0 fin 2027. Neuf pays, dont les \u00c9tats-Unis, le Qatar, l&rsquo;\u00c9gypte, l&rsquo;Arabie saoudite et la Turquie, ont exprim\u00e9 leur soutien commun au texte en esp\u00e9rant son adoption rapide.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lyes Sa\u00efdi<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Anniversaire de la Proclamation de l&rsquo;Etat de Palestine<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un \u00ab\u00a0tournant historique\u00a0\u00bb&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;ambassade de Palestine en Alg\u00e9rie a qualifi\u00e9, samedi, la Proclamation de l&rsquo;Etat de Palestine, en 1988 depuis Alger, de \u00ab\u00a0tournant historique\u00a0\u00bb qui a remis la cause palestinienne sur le devant de la sc\u00e8ne internationale, lui redonnant une visibilit\u00e9 mondiale. Dans un communiqu\u00e9 publi\u00e9 \u00e0 l&rsquo;occasion du 37e anniversaire de la Proclamation de l&rsquo;Etat de Palestine, l&rsquo;ambassade a indiqu\u00e9 que \u00ab\u00a0le peuple palestinien c\u00e9l\u00e8bre aujourd&rsquo;hui l&rsquo;anniversaire de la D\u00e9claration historique d&rsquo;ind\u00e9pendance proclamant l&rsquo;Etat de Palestine, lue par le d\u00e9funt leader Yasser Arafat depuis l&rsquo;Alg\u00e9rie, terre b\u00e9nie abreuv\u00e9e du sang des martyrs, au terme de la 19e session du Conseil national palestinien\u00a0\u00bb, soulignant que \u00ab\u00a0cette Proclamation, fruit d&rsquo;immenses sacrifices, a constitu\u00e9 un tournant historique qui a remis la cause palestinienne sur le devant de la sc\u00e8ne internationale, lui redonnant une visibilit\u00e9 mondiale\u00a0\u00bb. Dans son communiqu\u00e9, l&rsquo;ambassade a rappel\u00e9 \u00ab\u00a0ce moment historique o\u00f9 l&rsquo;Alg\u00e9rie fut le premier pays \u00e0 reconna\u00eetre l&rsquo;Etat de Palestine, suivie depuis par 160 pays\u00a0\u00bb. L&rsquo;ambassade de Palestine est \u00e9galement revenue sur les \u00e9tapes phares du parcours de lutte et de r\u00e9sistance du peuple palestinien, soulignant que la c\u00e9l\u00e9bration de cet anniversaire intervient, cette ann\u00e9e, alors que \u00ab\u00a0le peuple palestinien est en proie \u00e0 des exactions \u00e0 El-Qods, en Cisjordanie et dans la bande de Ghaza, qui subit depuis plus de deux ans un g\u00e9nocide et un nettoyage ethnique ayant caus\u00e9 des milliers de martyrs, de bless\u00e9s et de disparus\u00a0\u00bb. Malgr\u00e9 les terribles circonstances qu&rsquo;il traverse, \u00ab\u00a0le peuple palestinien demeure courageux et r\u00e9silient sur sa terre, r\u00e9affirmant au monde entier qu&rsquo;il ne renoncera pas \u00e0 ses droits nationaux reconnus par la l\u00e9galit\u00e9 internationale et n&rsquo;abandonnera pas ses constantes, pour lesquelles des milliers de ses enfants et dirigeants ont sacrifi\u00e9 leur vie, jusqu&rsquo;\u00e0 l&rsquo;\u00e9tablissement de l&rsquo;Etat palestinien ind\u00e9pendant avec El-Qods pour capitale\u00a0\u00bb, ajoute la m\u00eame source<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que de violentes pluies s&rsquo;abattent sur la bande de Ghaza ce week-end, l&rsquo;agence onusienne UNRWA d\u00e9nonce une situation devenue<\/p>\n","protected":false},"author":6,"featured_media":75975,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,37],"tags":[],"class_list":["post-76228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-monde"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ghaza sous le blocus isra\u00e9lien\u00a0:\u00a0La pluie aggrave le calvaire humanitaire\u00a0 - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ghaza sous le blocus isra\u00e9lien\u00a0:\u00a0La pluie aggrave le calvaire humanitaire\u00a0 - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Alors que de violentes pluies s&rsquo;abattent sur la bande de Ghaza ce week-end, l&rsquo;agence onusienne UNRWA d\u00e9nonce une situation devenue\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-16T10:02:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-16T10:02:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/Ghaza-catastrophe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/16\\\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/16\\\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Ghaza sous le blocus isra\u00e9lien\u00a0:\u00a0La pluie aggrave le calvaire humanitaire\u00a0\",\"datePublished\":\"2025-11-16T10:02:09+00:00\",\"dateModified\":\"2025-11-16T10:02:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/16\\\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\\\/\"},\"wordCount\":1216,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/16\\\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Ghaza-catastrophe.jpg\",\"articleSection\":[\"\u00c0 la Une\",\"Monde\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/16\\\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/16\\\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/16\\\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\\\/\",\"name\":\"Ghaza sous le blocus isra\u00e9lien\u00a0:\u00a0La pluie aggrave le calvaire humanitaire\u00a0 - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/16\\\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/16\\\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Ghaza-catastrophe.jpg\",\"datePublished\":\"2025-11-16T10:02:09+00:00\",\"dateModified\":\"2025-11-16T10:02:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/16\\\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/16\\\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/16\\\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Ghaza-catastrophe.jpg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Ghaza-catastrophe.jpg\",\"width\":1170,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/16\\\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ghaza sous le blocus isra\u00e9lien\u00a0:\u00a0La pluie aggrave le calvaire humanitaire\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ghaza sous le blocus isra\u00e9lien\u00a0:\u00a0La pluie aggrave le calvaire humanitaire\u00a0 - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/","og_locale":"fr_FR","og_type":"article","og_title":"Ghaza sous le blocus isra\u00e9lien\u00a0:\u00a0La pluie aggrave le calvaire humanitaire\u00a0 - La Sentinelle","og_description":"Alors que de violentes pluies s&rsquo;abattent sur la bande de Ghaza ce week-end, l&rsquo;agence onusienne UNRWA d\u00e9nonce une situation devenue","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-11-16T10:02:09+00:00","article_modified_time":"2025-11-16T10:02:10+00:00","og_image":[{"width":1170,"height":530,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/Ghaza-catastrophe.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Ghaza sous le blocus isra\u00e9lien\u00a0:\u00a0La pluie aggrave le calvaire humanitaire\u00a0","datePublished":"2025-11-16T10:02:09+00:00","dateModified":"2025-11-16T10:02:10+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/"},"wordCount":1216,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/Ghaza-catastrophe.jpg","articleSection":["\u00c0 la Une","Monde"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/","name":"Ghaza sous le blocus isra\u00e9lien\u00a0:\u00a0La pluie aggrave le calvaire humanitaire\u00a0 - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/Ghaza-catastrophe.jpg","datePublished":"2025-11-16T10:02:09+00:00","dateModified":"2025-11-16T10:02:10+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/Ghaza-catastrophe.jpg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/Ghaza-catastrophe.jpg","width":1170,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/16\/ghaza-sous-le-blocus-israelien-la-pluie-aggrave-le-calvaire-humanitaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Ghaza sous le blocus isra\u00e9lien\u00a0:\u00a0La pluie aggrave le calvaire humanitaire\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/76228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=76228"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/76228\/revisions"}],"predecessor-version":[{"id":76229,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/76228\/revisions\/76229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/75975"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=76228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=76228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=76228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}