{"id":76566,"date":"2025-11-22T19:19:20","date_gmt":"2025-11-22T18:19:20","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=76566"},"modified":"2025-11-22T19:19:21","modified_gmt":"2025-11-22T18:19:21","slug":"malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/","title":{"rendered":"Malgr\u00e9 le cessez-le-feu\u00a0: Les crimes sionistes persistent \u00e0 Ghaza"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L&rsquo;entit\u00e9 sioniste intensifie ses bombardements contre les zones r\u00e9sidentielles du sud et du nord de la bande de Ghaza en violation flagrante de l&rsquo;accord de cessez-le-feu.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Samedi, 10 civils ont \u00e9t\u00e9 tu\u00e9s dans une frappe a\u00e9rienne \u00e0 l&rsquo;ouest de la ville de Ghaza, portant le bilan des violations depuis le 11 octobre \u00e0 318 martyrs et 788 bless\u00e9s. Le bilan global de l&rsquo;agression g\u00e9nocidaire s&rsquo;alourdit \u00e0 69 733 martyrs et 170 863 bless\u00e9s depuis le 7 octobre 2023.&nbsp;\u00c0 l&rsquo;aube&nbsp;de ce samedi, l&rsquo;arm\u00e9e d&rsquo;occupation a lanc\u00e9 des dizaines de raids a\u00e9riens et de tirs d&rsquo;artillerie sur les quartiers r\u00e9sidentiels du sud et du nord de la bande de Ghaza, transformant une nouvelle fois le cessez-le-feu cens\u00e9 prot\u00e9ger les civils en lettre morte. Ces attaques syst\u00e9matiques, qui se poursuivent depuis vendredi, t\u00e9moignent de la d\u00e9termination de l&rsquo;occupation \u00e0 poursuivre sa campagne de terreur contre la population palestinienne sans rel\u00e2che.&nbsp;Les t\u00e9moins oculaires et les sources locales rapportent que l&rsquo;arm\u00e9e d&rsquo;occupation a fait exploser des immeubles r\u00e9sidentiels et des installations civiles en menant des frappes a\u00e9riennes et en d\u00e9clenchant des v\u00e9hicules pi\u00e9g\u00e9s dans les zones orientales de Rafah et de Khan Youn\u00e8s, situ\u00e9es dans ce que l&rsquo;occupation appelle la \u00ab\u00a0zone jaune\u00a0\u00bb sous son contr\u00f4le militaire dans le sud de la bande de Ghaza. Ces destructions massives s&rsquo;inscrivent dans une strat\u00e9gie d\u00e9lib\u00e9r\u00e9e de rendre inhabitables de vastes territoires palestiniens.&nbsp;Dans le nord, les quartiers d&rsquo;Al-Touffah et de Chajaiya, \u00e0 l&rsquo;est de la ville de Ghaza, ont \u00e9galement \u00e9t\u00e9 la cible de frappes similaires et de fortes explosions. Les tirs d&rsquo;artillerie et les rafales sporadiques provenant de v\u00e9hicules militaires de l&rsquo;occupation positionn\u00e9s \u00e0 la lisi\u00e8re de la zone jaune ont terroris\u00e9 les habitants tout au long de la journ\u00e9e, cr\u00e9ant un climat de peur permanente dans des quartiers d\u00e9j\u00e0 d\u00e9vast\u00e9s par pr\u00e8s de 14 mois d&rsquo;agression continue.&nbsp;La journ\u00e9e du samedi a \u00e9t\u00e9 particuli\u00e8rement meurtri\u00e8re avec l&rsquo;attaque d&rsquo;un v\u00e9hicule civil pr\u00e8s du carrefour Abbas dans le quartier d&rsquo;Al-Rimal, \u00e0 l&rsquo;ouest de la ville de Ghaza. Les avions de l&rsquo;occupation ont tu\u00e9 au moins 10 civils et bless\u00e9 plusieurs autres dans cette frappe qui illustre le m\u00e9pris total de l&rsquo;entit\u00e9 sioniste pour les vies palestiniennes, m\u00eame en p\u00e9riode de cessez-le-feu.&nbsp;La veille, vendredi, l&rsquo;arm\u00e9e d&rsquo;occupation avait d\u00e9j\u00e0 cibl\u00e9 des b\u00e2timents palestiniens dans les zones sous contr\u00f4le militaire sioniste \u00e0 Khan Youn\u00e8s et \u00e0 Ghaza-ville, ainsi qu&rsquo;\u00e0 l&rsquo;est du camp de r\u00e9fugi\u00e9s de Boureij au centre de la bande de Ghaza et \u00e0 l&rsquo;est du camp de r\u00e9fugi\u00e9s de Jabalia dans le nord. Ces attaques r\u00e9p\u00e9t\u00e9es d\u00e9montrent que le cessez-le-feu n&rsquo;existe que sur le papier pour l&rsquo;entit\u00e9 sioniste.&nbsp;L&rsquo;occupation continue d&rsquo;occuper plus de 50% de la bande de Ghaza dans le cadre de l&rsquo;accord de cessez-le-feu, la \u00ab\u00a0ligne jaune\u00a0\u00bb s\u00e9parant les zones o\u00f9 l&rsquo;arm\u00e9e est d\u00e9ploy\u00e9e de celles encore habit\u00e9es par les Palestiniens. Cette ligne de d\u00e9marcation floue est devenue une zone de mort o\u00f9 les forces d&rsquo;occupation frappent \u00e0 volont\u00e9. Franz L\u00f6v, coordinateur d&rsquo;urgence de M\u00e9decins sans fronti\u00e8res \u00e0 Ghaza, a d&rsquo;ailleurs soulign\u00e9 que les gens ne connaissent pas l&#8217;emplacement exact de cette ligne jaune, ajoutant qu&rsquo;il y a 2 jours, un h\u00e9licopt\u00e8re a tir\u00e9 tr\u00e8s pr\u00e8s de leur centre de sant\u00e9 \u00e0 Al-Mawasi.&nbsp;Ces derni\u00e8res semaines, l&rsquo;arm\u00e9e d&rsquo;occupation a intensifi\u00e9 ses attaques \u00e0 l&rsquo;est de la ligne jaune, d\u00e9truisant de vastes zones et rendant les secteurs environnants extr\u00eamement dangereux pour les civils. Cette strat\u00e9gie de terre br\u00fbl\u00e9e vise \u00e0 emp\u00eacher le retour des Palestiniens d\u00e9plac\u00e9s dans leurs foyers et \u00e0 annexer de facto de larges portions du territoire de Ghaza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le bilan humain de l&rsquo;agression g\u00e9nocidaire sioniste contre la bande de Ghaza continue de s&rsquo;alourdir de mani\u00e8re vertigineuse. Selon les autorit\u00e9s sanitaires palestiniennes, 69 733 martyrs et 170 863 bless\u00e9s, en majorit\u00e9 des femmes et des enfants, ont \u00e9t\u00e9 recens\u00e9s depuis le 7 octobre 2023. Au cours des derni\u00e8res 48 heures, les corps de 7 martyrs ainsi que 30 bless\u00e9s ont \u00e9t\u00e9 transf\u00e9r\u00e9s vers les h\u00f4pitaux de Ghaza. De nombreuses victimes se trouvent encore sous les d\u00e9combres, inaccessibles aux \u00e9quipes de secours et aux ambulanciers emp\u00each\u00e9s d&rsquo;intervenir par l&rsquo;occupation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis l&rsquo;entr\u00e9e en vigueur du cessez-le-feu le 11 octobre 2025, pas moins de 318 Palestiniens sont tomb\u00e9s en martyrs et 788 autres ont \u00e9t\u00e9 bless\u00e9s, tandis que les corps de 572 martyrs ont \u00e9t\u00e9 r\u00e9cup\u00e9r\u00e9s. Ces chiffres d\u00e9montrent que le cessez-le-feu n&rsquo;a apport\u00e9 qu&rsquo;un r\u00e9pit illusoire \u00e0 la population de Ghaza, qui continue de vivre sous la menace permanente des bombardements de l&rsquo;occupation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les enfants de Ghaza paient un tribut particuli\u00e8rement lourd \u00e0 cette violation syst\u00e9matique du cessez-le-feu. Ricardo Pires, porte-parole de l&rsquo;UNICEF, a r\u00e9v\u00e9l\u00e9 que 67 enfants ont \u00e9t\u00e9 tu\u00e9s pendant la p\u00e9riode de cessez-le-feu. Une fillette a \u00e9t\u00e9 tu\u00e9e vendredi \u00e0 Khan Youn\u00e8s dans une frappe a\u00e9rienne, tandis que 7 enfants ont perdu la vie jeudi dans la ville de Ghaza et dans le sud. L&rsquo;UNICEF d\u00e9nonce que 280 d\u00e9c\u00e8s et 672 blessures ont \u00e9t\u00e9 enregistr\u00e9s depuis le d\u00e9but de la tr\u00eave.&nbsp;Les agences des Nations unies ont d\u00e9clar\u00e9 que les attaques et les raids a\u00e9riens continus men\u00e9s par l&rsquo;arm\u00e9e sioniste \u00e0 Ghaza continuent de tuer et de mutiler des personnes de tous \u00e2ges malgr\u00e9 le cessez-le-feu convenu. Cette situation r\u00e9v\u00e8le l&rsquo;hypocrisie de la communaut\u00e9 internationale qui assiste passivement \u00e0 la poursuite du g\u00e9nocide du peuple palestinien.&nbsp;Au-del\u00e0 des pertes humaines, la situation humanitaire demeure catastrophique. Franz L\u00f6v de M\u00e9decins sans fronti\u00e8res a averti que l&rsquo;aide humanitaire atteignant Ghaza reste insuffisante malgr\u00e9 le cessez-le-feu. Il a soulign\u00e9 que l&rsquo;aide humanitaire s&rsquo;est presque compl\u00e8tement arr\u00eat\u00e9e depuis le d\u00e9but du cessez-le-feu et qu&rsquo;il n&rsquo;y a pas une seule installation de sant\u00e9 fonctionnant \u00e0 pleine capacit\u00e9 dans la bande de Ghaza. Environ 4 000 enfants ont besoin d&rsquo;une \u00e9vacuation m\u00e9dicale urgente, mais le syst\u00e8me de sant\u00e9 de Ghaza s&rsquo;est effondr\u00e9, laissant les enfants sans soins.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les familles font face \u00e0 une p\u00e9nurie aigu\u00eb de nourriture malgr\u00e9 une certaine activit\u00e9 sur les march\u00e9s. Avec l&rsquo;arriv\u00e9e de l&rsquo;hiver, la situation devient encore plus d\u00e9sesp\u00e9r\u00e9e. L\u00f6v a expliqu\u00e9 qu&rsquo;avec le cessez-le-feu, les gens sont en col\u00e8re car ils n&rsquo;ont pas suffisamment de tentes pour se prot\u00e9ger de la pluie et du froid. Si aucune am\u00e9lioration tangible n&rsquo;intervient rapidement, la population de Ghaza sera \u00e0 nouveau confront\u00e9e \u00e0 des conditions hivernales difficiles qui s&rsquo;ajouteront \u00e0 leurs souffrances d\u00e9j\u00e0 insupportables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lyes Sa\u00efdi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;entit\u00e9 sioniste intensifie ses bombardements contre les zones r\u00e9sidentielles du sud et du nord de la bande de Ghaza en<\/p>\n","protected":false},"author":6,"featured_media":76567,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[37],"tags":[],"class_list":["post-76566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monde"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Malgr\u00e9 le cessez-le-feu\u00a0: Les crimes sionistes persistent \u00e0 Ghaza - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Malgr\u00e9 le cessez-le-feu\u00a0: Les crimes sionistes persistent \u00e0 Ghaza - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;entit\u00e9 sioniste intensifie ses bombardements contre les zones r\u00e9sidentielles du sud et du nord de la bande de Ghaza en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-22T18:19:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-22T18:19:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/Ghaza.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/22\\\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/22\\\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Malgr\u00e9 le cessez-le-feu\u00a0: Les crimes sionistes persistent \u00e0 Ghaza\",\"datePublished\":\"2025-11-22T18:19:20+00:00\",\"dateModified\":\"2025-11-22T18:19:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/22\\\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\\\/\"},\"wordCount\":1215,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/22\\\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Ghaza.webp\",\"articleSection\":[\"Monde\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/22\\\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/22\\\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/22\\\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\\\/\",\"name\":\"Malgr\u00e9 le cessez-le-feu\u00a0: Les crimes sionistes persistent \u00e0 Ghaza - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/22\\\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/22\\\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Ghaza.webp\",\"datePublished\":\"2025-11-22T18:19:20+00:00\",\"dateModified\":\"2025-11-22T18:19:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/22\\\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/22\\\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/22\\\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Ghaza.webp\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Ghaza.webp\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/22\\\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Malgr\u00e9 le cessez-le-feu\u00a0: Les crimes sionistes persistent \u00e0 Ghaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Malgr\u00e9 le cessez-le-feu\u00a0: Les crimes sionistes persistent \u00e0 Ghaza - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/","og_locale":"fr_FR","og_type":"article","og_title":"Malgr\u00e9 le cessez-le-feu\u00a0: Les crimes sionistes persistent \u00e0 Ghaza - La Sentinelle","og_description":"L&rsquo;entit\u00e9 sioniste intensifie ses bombardements contre les zones r\u00e9sidentielles du sud et du nord de la bande de Ghaza en","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-11-22T18:19:20+00:00","article_modified_time":"2025-11-22T18:19:21+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/Ghaza.webp","type":"image\/webp"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Malgr\u00e9 le cessez-le-feu\u00a0: Les crimes sionistes persistent \u00e0 Ghaza","datePublished":"2025-11-22T18:19:20+00:00","dateModified":"2025-11-22T18:19:21+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/"},"wordCount":1215,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/Ghaza.webp","articleSection":["Monde"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/","name":"Malgr\u00e9 le cessez-le-feu\u00a0: Les crimes sionistes persistent \u00e0 Ghaza - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/Ghaza.webp","datePublished":"2025-11-22T18:19:20+00:00","dateModified":"2025-11-22T18:19:21+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/Ghaza.webp","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/Ghaza.webp","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/22\/malgre-le-cessez-le-feu-les-crimes-sionistes-persistent-a-ghaza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Malgr\u00e9 le cessez-le-feu\u00a0: Les crimes sionistes persistent \u00e0 Ghaza"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/76566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=76566"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/76566\/revisions"}],"predecessor-version":[{"id":76568,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/76566\/revisions\/76568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/76567"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=76566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=76566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=76566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}