{"id":76828,"date":"2025-11-26T15:11:13","date_gmt":"2025-11-26T14:11:13","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=76828"},"modified":"2025-11-26T15:11:14","modified_gmt":"2025-11-26T14:11:14","slug":"ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/","title":{"rendered":"Ils sont destin\u00e9s aux poids lourds\u00a0: Naftal commande un demi-million de pneus \u00e0 l&rsquo;Italien Pirelli"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Naftal poursuit son plan d&rsquo;approvisionnement massif du march\u00e9 national en pneumatiques. Apr\u00e8s avoir scell\u00e9 il y a quelques jours un accord avec l&rsquo;Allemand Continental pour un million d&rsquo;unit\u00e9s destin\u00e9es aux v\u00e9hicules l\u00e9gers, le distributeur public alg\u00e9rien vient de signer mardi avec la soci\u00e9t\u00e9 italienne Prometeon un contrat portant sur l&rsquo;acquisition de 500.000 pneus de marque Pirelli pour v\u00e9hicules poids lourds, poursuivant ainsi la strat\u00e9gie gouvernementale visant \u00e0 stabiliser les prix et \u00e0 \u00e9radiquer la sp\u00e9culation qui gangr\u00e8ne ce segment du march\u00e9 automobile. Le contrat a \u00e9t\u00e9 paraph\u00e9 mardi au si\u00e8ge de Naftal \u00e0 Alger, marquant une nouvelle \u00e9tape dans la politique d&rsquo;importation massive de pneumatiques d\u00e9cid\u00e9e par les autorit\u00e9s. Selon le communiqu\u00e9 publi\u00e9 par la filiale de Sonatrach, sp\u00e9cialis\u00e9e dans la distribution des carburants et lubrifiants, cet accord vise \u00e0 fournir au march\u00e9 national un demi-million de pneus Pirelli destin\u00e9s aux camions et bus, des v\u00e9hicules essentiels au bon fonctionnement du transport routier et de la logistique \u00e0 travers le pays. Cette signature intervient une semaine seulement apr\u00e8s la conclusion d&rsquo;un premier partenariat strat\u00e9gique avec le g\u00e9ant allemand Continental, le 17 novembre. Ce pr\u00e9c\u00e9dent accord portait sur la fourniture d&rsquo;un million de pneus pour voitures, avec des baisses de prix promises allant jusqu&rsquo;\u00e0 55%. La rapidit\u00e9 avec laquelle ces contrats se succ\u00e8dent t\u00e9moigne de l&rsquo;urgence per\u00e7ue par les pouvoirs publics face aux tensions qui caract\u00e9risent le march\u00e9 des pneumatiques depuis plusieurs mois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;origine de cette offensive commerciale remonte au mois d&rsquo;ao\u00fbt dernier, lorsqu&rsquo;un tragique accident a endeuill\u00e9 le pays. La chute d&rsquo;un bus dans l&rsquo;oued El Harrach, causant la mort de 18 passagers, avait mis en lumi\u00e8re l&rsquo;\u00e9tat pr\u00e9occupant du parc automobile national et les graves d\u00e9faillances en mati\u00e8re de s\u00e9curit\u00e9 routi\u00e8re. Face \u00e0 cette catastrophe, le pr\u00e9sident de la R\u00e9publique avait convoqu\u00e9 une r\u00e9union d&rsquo;urgence consacr\u00e9e au secteur des transports et ordonn\u00e9 deux mesures chocs : l&rsquo;importation en urgence de 10.000 bus neufs et l&rsquo;acquisition massive de pneumatiques de toutes cat\u00e9gories. C&rsquo;est dans ce contexte que Naftal s&rsquo;est vu confier la mission d&rsquo;assurer l&rsquo;approvisionnement du march\u00e9 national en pneus de qualit\u00e9. Lors de la c\u00e9r\u00e9monie de signature du contrat avec Prometeon, le directeur g\u00e9n\u00e9ral de Naftal, Djamel Cherdoud, a exprim\u00e9 sa gratitude envers les autorit\u00e9s publiques pour la confiance accord\u00e9e \u00e0 l&rsquo;entreprise. Le communiqu\u00e9 de Naftal souligne que cette initiative refl\u00e8te la nouvelle dynamique de la politique de la soci\u00e9t\u00e9, qui vise \u00e0 garantir un approvisionnement r\u00e9gulier en pneus pour v\u00e9hicules lourds, \u00e9l\u00e9ments essentiels du transport routier et des services logistiques. L&rsquo;accord avec Prometeon pour les pneus Pirelli destin\u00e9s aux poids lourds compl\u00e8te ainsi le dispositif d&rsquo;importation mis en place avec Continental pour les v\u00e9hicules l\u00e9gers. Cette approche diff\u00e9renci\u00e9e permet de couvrir l&rsquo;ensemble des segments du march\u00e9 automobile alg\u00e9rien, des v\u00e9hicules particuliers aux v\u00e9hicules utilitaires et de transport de marchandises. La strat\u00e9gie consiste \u00e0 s&rsquo;appuyer sur des fabricants mondiaux reconnus pour leur qualit\u00e9, garantissant ainsi aux consommateurs alg\u00e9riens des produits conformes aux normes internationales. \u00c0 travers cet accord, Naftal r\u00e9affirme son engagement \u00e0 renforcer l&rsquo;approvisionnement du march\u00e9 national et \u00e0 fournir des produits respectant les standards internationaux, conform\u00e9ment \u00e0 sa strat\u00e9gie visant \u00e0 am\u00e9liorer la qualit\u00e9 de service et \u00e0 diversifier son offre au profit de ses clients \u00e0 travers tout le territoire national. La distribution de ces pneumatiques import\u00e9s sera assur\u00e9e via le vaste r\u00e9seau de Naftal, qui compte plus de deux mille points de vente r\u00e9partis sur l&rsquo;ensemble du territoire. Mais l&rsquo;ambition des pouvoirs publics va bien au-del\u00e0 de ces premiers contrats. Naftal a en effet annonc\u00e9 il y a quelques jours qu&rsquo;elle envisage, dans une seconde phase, d&rsquo;importer quatre millions et demi de pneus suppl\u00e9mentaires. Ce projet d&rsquo;envergure t\u00e9moigne de la volont\u00e9 des autorit\u00e9s de structurer durablement le march\u00e9 des pneumatiques et d&rsquo;\u00e9viter les p\u00e9nuries qui ont caract\u00e9ris\u00e9 les derniers mois, tout en cassant les prix pratiqu\u00e9s par les circuits sp\u00e9culatifs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Amar Malki<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Naftal poursuit son plan d&rsquo;approvisionnement massif du march\u00e9 national en pneumatiques. Apr\u00e8s avoir scell\u00e9 il y a quelques jours un<\/p>\n","protected":false},"author":6,"featured_media":76423,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[29],"tags":[],"class_list":["post-76828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ils sont destin\u00e9s aux poids lourds\u00a0: Naftal commande un demi-million de pneus \u00e0 l&rsquo;Italien Pirelli - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ils sont destin\u00e9s aux poids lourds\u00a0: Naftal commande un demi-million de pneus \u00e0 l&rsquo;Italien Pirelli - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Naftal poursuit son plan d&rsquo;approvisionnement massif du march\u00e9 national en pneumatiques. Apr\u00e8s avoir scell\u00e9 il y a quelques jours un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-26T14:11:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T14:11:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/pneus.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Ils sont destin\u00e9s aux poids lourds\u00a0: Naftal commande un demi-million de pneus \u00e0 l&rsquo;Italien Pirelli\",\"datePublished\":\"2025-11-26T14:11:13+00:00\",\"dateModified\":\"2025-11-26T14:11:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\\\/\"},\"wordCount\":742,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/pneus.webp\",\"articleSection\":[\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\\\/\",\"name\":\"Ils sont destin\u00e9s aux poids lourds\u00a0: Naftal commande un demi-million de pneus \u00e0 l&rsquo;Italien Pirelli - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/pneus.webp\",\"datePublished\":\"2025-11-26T14:11:13+00:00\",\"dateModified\":\"2025-11-26T14:11:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/pneus.webp\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/pneus.webp\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ils sont destin\u00e9s aux poids lourds\u00a0: Naftal commande un demi-million de pneus \u00e0 l&rsquo;Italien Pirelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ils sont destin\u00e9s aux poids lourds\u00a0: Naftal commande un demi-million de pneus \u00e0 l&rsquo;Italien Pirelli - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/","og_locale":"fr_FR","og_type":"article","og_title":"Ils sont destin\u00e9s aux poids lourds\u00a0: Naftal commande un demi-million de pneus \u00e0 l&rsquo;Italien Pirelli - La Sentinelle","og_description":"Naftal poursuit son plan d&rsquo;approvisionnement massif du march\u00e9 national en pneumatiques. Apr\u00e8s avoir scell\u00e9 il y a quelques jours un","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-11-26T14:11:13+00:00","article_modified_time":"2025-11-26T14:11:14+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/pneus.webp","type":"image\/webp"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Ils sont destin\u00e9s aux poids lourds\u00a0: Naftal commande un demi-million de pneus \u00e0 l&rsquo;Italien Pirelli","datePublished":"2025-11-26T14:11:13+00:00","dateModified":"2025-11-26T14:11:14+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/"},"wordCount":742,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/pneus.webp","articleSection":["\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/","name":"Ils sont destin\u00e9s aux poids lourds\u00a0: Naftal commande un demi-million de pneus \u00e0 l&rsquo;Italien Pirelli - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/pneus.webp","datePublished":"2025-11-26T14:11:13+00:00","dateModified":"2025-11-26T14:11:14+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/pneus.webp","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/pneus.webp","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/ils-sont-destines-aux-poids-lourds-naftal-commande-un-demi-million-de-pneus-a-litalien-pirelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Ils sont destin\u00e9s aux poids lourds\u00a0: Naftal commande un demi-million de pneus \u00e0 l&rsquo;Italien Pirelli"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/76828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=76828"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/76828\/revisions"}],"predecessor-version":[{"id":76830,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/76828\/revisions\/76830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/76423"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=76828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=76828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=76828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}