{"id":76834,"date":"2025-11-26T15:13:04","date_gmt":"2025-11-26T14:13:04","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=76834"},"modified":"2025-11-26T15:13:05","modified_gmt":"2025-11-26T14:13:05","slug":"lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/","title":{"rendered":"Lutte antidrogue en milieu scolaire\u00a0: Le num\u00e9ro vert 1111 pour les signalements"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le minist\u00e8re de l&rsquo;\u00c9ducation nationale a annonc\u00e9 mardi l&rsquo;adoption officielle du num\u00e9ro vert 1111 pour le signalement des cas li\u00e9s aux drogues et substances psychotropes en milieu scolaire, dans le cadre de la mise en \u0153uvre de la strat\u00e9gie nationale de lutte contre ce fl\u00e9au initi\u00e9e par le pr\u00e9sident de la R\u00e9publique. Selon un communiqu\u00e9 du minist\u00e8re, cette mesure s&rsquo;inscrit \u00ab\u00a0en application des orientations du pr\u00e9sident de la R\u00e9publique, M. Abdelmadjid Tebboune, relatives \u00e0 la strat\u00e9gie nationale de lutte contre les drogues et les substances psychotropes, notamment dans son aspect li\u00e9 au milieu scolaire\u00a0\u00bb. Le secteur a ainsi entam\u00e9 \u00ab\u00a0la mise en \u0153uvre des mesures pratiques annonc\u00e9es par le ministre de l&rsquo;\u00c9ducation nationale, M. Mohammed Seghir Saadaoui, lors du lancement de la caravane nationale de sensibilisation, le 2 novembre 2025, notamment en ce qui a trait \u00e0 la mise en place d&rsquo;un num\u00e9ro vert d\u00e9di\u00e9 au signalement, en tant que m\u00e9canisme central pour consacrer la culture de la pr\u00e9vention au sein des \u00e9tablissements scolaires\u00a0\u00bb. Cette d\u00e9cision fait suite \u00e0 une r\u00e9union de travail pr\u00e9sid\u00e9e par le ministre Saadaoui en compagnie de la D\u00e9l\u00e9gu\u00e9e nationale \u00e0 la protection de l&rsquo;enfance, Meriem Cherfi, consacr\u00e9e \u00e0 l&rsquo;examen de la possibilit\u00e9 d&rsquo;adopter ce num\u00e9ro vert en milieu scolaire. Le choix de ce dispositif s&rsquo;explique par le fait que \u00ab\u00a0la tranche d&rsquo;\u00e2ge de moins de 18 ans, qui concerne l\u00e9galement la qualit\u00e9 d&rsquo;enfant, se trouve, pour la majorit\u00e9, au sein des \u00e9tablissements scolaires, d&rsquo;o\u00f9 la n\u00e9cessit\u00e9 de la coordination afin d&rsquo;assurer une pr\u00e9vention pr\u00e9coce et une protection des \u00e9l\u00e8ves contre ces dangers\u00a0\u00bb, pr\u00e9cise le communiqu\u00e9. Pour pr\u00e9parer la mise en place de ce m\u00e9canisme, une \u00e9quipe technique sp\u00e9cialis\u00e9e du minist\u00e8re a effectu\u00e9 une visite au si\u00e8ge de l&rsquo;Organe national de la protection et de la promotion de l&rsquo;enfance (ONPPE) afin de s&rsquo;enqu\u00e9rir des m\u00e9canismes de r\u00e9ception et de traitement des signalements. Cette mission visait \u00e0 \u00ab\u00a0\u00e9valuer la possibilit\u00e9 de les adapter avec la sp\u00e9cificit\u00e9 du secteur, notamment en termes de volume et de nombre des \u00e9tablissements scolaires et des \u00e9l\u00e8ves \u00e0 travers le pays\u00a0\u00bb, tout en garantissant \u00ab\u00a0la confidentialit\u00e9 et la protection des auteurs de signalements\u00a0\u00bb et en mettant en place \u00ab\u00a0un protocole commun de prise en charge des cas et d&rsquo;intervention\u00a0\u00bb. Les r\u00e9sultats de cette \u00e9valuation ont confirm\u00e9 la faisabilit\u00e9 du projet, permettant au minist\u00e8re d&rsquo;annoncer \u00ab\u00a0l&rsquo;adoption officielle du num\u00e9ro vert 1111 et sa mise \u00e0 la disposition de l&rsquo;ensemble de la communaut\u00e9 \u00e9ducative (\u00e9l\u00e8ves, enseignants, administratifs, travailleurs et parents d&rsquo;\u00e9l\u00e8ves), pour signaler les cas n\u00e9cessitant un suivi ou une intervention imm\u00e9diate\u00a0\u00bb. L&rsquo;objectif est de \u00ab\u00a0renforcer la culture du signalement et consacrer les bases de la pr\u00e9vention des drogues et des substances psychotropes au sein des \u00e9tablissements scolaires\u00a0\u00bb. Le minist\u00e8re assure que les informations signal\u00e9es \u00ab\u00a0sont trait\u00e9es en toute confidentialit\u00e9 et transmises, selon leur nature, aux instances comp\u00e9tentes pour une prise en charge imm\u00e9diate des cas, garantissant ainsi la protection juridique et sociale des \u00e9l\u00e8ves et permettant ainsi d&rsquo;\u00e9tablir un environnement scolaire s\u00fbr et sain\u00a0\u00bb. Cette garantie de confidentialit\u00e9 constitue un \u00e9l\u00e9ment crucial pour encourager les signalements et lever les r\u00e9ticences que pourraient avoir les membres de la communaut\u00e9 \u00e9ducative.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Selon le communiqu\u00e9, cette mesure constitue \u00ab\u00a0un pas qualitatif dans la protection des \u00e9l\u00e8ves contre les drogues et les substances psychotropes, et sera accompagn\u00e9e d&rsquo;un suivi p\u00e9riodique et d&rsquo;une \u00e9valuation r\u00e9guli\u00e8re des r\u00e9sultats aux niveaux local et national, en coordination avec les instances et secteurs concern\u00e9s\u00a0\u00bb. Cette dimension \u00e9valuative permettra d&rsquo;ajuster le dispositif et d&rsquo;en mesurer l&rsquo;efficacit\u00e9 dans la dur\u00e9e, tout en favorisant une approche coordonn\u00e9e entre les diff\u00e9rents acteurs impliqu\u00e9s dans la protection de l&rsquo;enfance et la pr\u00e9vention en milieu scolaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Malik Meziane<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le minist\u00e8re de l&rsquo;\u00c9ducation nationale a annonc\u00e9 mardi l&rsquo;adoption officielle du num\u00e9ro vert 1111 pour le signalement des cas li\u00e9s<\/p>\n","protected":false},"author":6,"featured_media":75747,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-76834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lutte antidrogue en milieu scolaire\u00a0: Le num\u00e9ro vert 1111 pour les signalements - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lutte antidrogue en milieu scolaire\u00a0: Le num\u00e9ro vert 1111 pour les signalements - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le minist\u00e8re de l&rsquo;\u00c9ducation nationale a annonc\u00e9 mardi l&rsquo;adoption officielle du num\u00e9ro vert 1111 pour le signalement des cas li\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-26T14:13:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T14:13:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/drogue.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Lutte antidrogue en milieu scolaire\u00a0: Le num\u00e9ro vert 1111 pour les signalements\",\"datePublished\":\"2025-11-26T14:13:04+00:00\",\"dateModified\":\"2025-11-26T14:13:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\\\/\"},\"wordCount\":701,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/drogue.jpg\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\\\/\",\"name\":\"Lutte antidrogue en milieu scolaire\u00a0: Le num\u00e9ro vert 1111 pour les signalements - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/drogue.jpg\",\"datePublished\":\"2025-11-26T14:13:04+00:00\",\"dateModified\":\"2025-11-26T14:13:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/drogue.jpg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/drogue.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2025\\\/11\\\/26\\\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lutte antidrogue en milieu scolaire\u00a0: Le num\u00e9ro vert 1111 pour les signalements\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lutte antidrogue en milieu scolaire\u00a0: Le num\u00e9ro vert 1111 pour les signalements - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/","og_locale":"fr_FR","og_type":"article","og_title":"Lutte antidrogue en milieu scolaire\u00a0: Le num\u00e9ro vert 1111 pour les signalements - La Sentinelle","og_description":"Le minist\u00e8re de l&rsquo;\u00c9ducation nationale a annonc\u00e9 mardi l&rsquo;adoption officielle du num\u00e9ro vert 1111 pour le signalement des cas li\u00e9s","og_url":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2025-11-26T14:13:04+00:00","article_modified_time":"2025-11-26T14:13:05+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/drogue.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Lutte antidrogue en milieu scolaire\u00a0: Le num\u00e9ro vert 1111 pour les signalements","datePublished":"2025-11-26T14:13:04+00:00","dateModified":"2025-11-26T14:13:05+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/"},"wordCount":701,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/drogue.jpg","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/","url":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/","name":"Lutte antidrogue en milieu scolaire\u00a0: Le num\u00e9ro vert 1111 pour les signalements - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/drogue.jpg","datePublished":"2025-11-26T14:13:04+00:00","dateModified":"2025-11-26T14:13:05+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/drogue.jpg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/11\/drogue.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2025\/11\/26\/lutte-antidrogue-en-milieu-scolaire-le-numero-vert-1111-pour-les-signalements\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Lutte antidrogue en milieu scolaire\u00a0: Le num\u00e9ro vert 1111 pour les signalements"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/76834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=76834"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/76834\/revisions"}],"predecessor-version":[{"id":76835,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/76834\/revisions\/76835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/75747"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=76834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=76834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=76834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}