{"id":79380,"date":"2026-01-12T20:29:52","date_gmt":"2026-01-12T19:29:52","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=79380"},"modified":"2026-01-12T20:29:54","modified_gmt":"2026-01-12T19:29:54","slug":"un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/","title":{"rendered":"Un r\u00e9seau international de blanchiment d&rsquo;argent\u00a0d\u00e9mantel\u00e9\u00a0:\u00a0plus de 6 milliards de centimes\u00a0saisis"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale de la wilaya de Sidi Bel Abb\u00e8s ont proc\u00e9d\u00e9 au d\u00e9mant\u00e8lement d&rsquo;un r\u00e9seau criminel international sp\u00e9cialis\u00e9 dans le blanchiment d&rsquo;argent issu du trafic illicite de drogue, avec la saisie de plus de 6 milliards de centimes, indique lundi un communiqu\u00e9 des m\u00eames services.&nbsp;\u00ab\u00a0Dans le cadre de la lutte contre le crime organis\u00e9, notamment \u00e0 travers l&rsquo;ass\u00e8chement des sources de financement des r\u00e9seaux criminels, la brigade de lutte contre les crimes \u00e9conomiques et financiers de la S\u00fbret\u00e9 de wilaya de Sidi Bel Abb\u00e8s a proc\u00e9d\u00e9 au d\u00e9mant\u00e8lement d&rsquo;un groupe criminel organis\u00e9 transfrontalier, impliqu\u00e9 dans le blanchiment d&rsquo;argent provenant du trafic illicite de drogue, avec la r\u00e9cup\u00e9ration des biens et gains issus de cette activit\u00e9 criminelle, estim\u00e9s \u00e0 plus de 6 milliards et 600 millions de centimes\u00a0\u00bb, pr\u00e9cise le communiqu\u00e9.Cette op\u00e9ration fait suite \u00e0 \u00ab\u00a0une enqu\u00eate ant\u00e9rieure men\u00e9e par les services op\u00e9rationnels de la S\u00fbret\u00e9 de wilaya, laquelle avait permis de d\u00e9jouer une tentative de passage d&rsquo;une importante cargaison de drogue et d&rsquo;arr\u00eater les principaux mis en cause\u00a0\u00bb. Les investigations ont repris, par la suite, pour \u00ab\u00a0retracer le circuit financier du r\u00e9seau, \u00e0 travers l&rsquo;exploitation de preuves num\u00e9riques et techniques\u00a0\u00bb, a ajout\u00e9 la m\u00eame source.Suite \u00e0 quoi, \u00ab\u00a0il a \u00e9t\u00e9 proc\u00e9d\u00e9 \u00e0 l&rsquo;arrestation de trois (3) individus appartenant au groupe criminel qui a tent\u00e9 d\u00e9lib\u00e9r\u00e9ment de l\u00e9gitimiser les gains mal acquis issus du trafic de drogue, en les injectant dans des op\u00e9rations commerciales et d&rsquo;exportation de marchandises, moyennant des factures domicili\u00e9es \u00e0 la banque et des d\u00e9clarations mensong\u00e8res, causant ainsi au Tr\u00e9sor public des pertes en devises estim\u00e9es \u00e0 pr\u00e8s de 2 millions d&rsquo;euros\u00a0\u00bb, note le texte.&nbsp;L&rsquo;op\u00e9ration, men\u00e9e sous la supervision du parquet comp\u00e9tent, s&rsquo;est sold\u00e9e par la saisie et la r\u00e9cup\u00e9ration \u00ab\u00a0de 88.800 euros, d&rsquo;une somme en monnaie nationale d\u00e9passant 500 millions de centimes, de bijoux en m\u00e9tal jaune pesant pr\u00e8s de 1 kg pour une valeur de 2,8 milliards de centimes, ainsi que de deux v\u00e9hicules de tourisme et d&rsquo;une motocyclette, selon la m\u00eame source.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale de la wilaya de Sidi Bel Abb\u00e8s ont proc\u00e9d\u00e9 au d\u00e9mant\u00e8lement d&rsquo;un r\u00e9seau criminel<\/p>\n","protected":false},"author":6,"featured_media":79381,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-79380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un r\u00e9seau international de blanchiment d&rsquo;argent\u00a0d\u00e9mantel\u00e9\u00a0:\u00a0plus de 6 milliards de centimes\u00a0saisis - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un r\u00e9seau international de blanchiment d&rsquo;argent\u00a0d\u00e9mantel\u00e9\u00a0:\u00a0plus de 6 milliards de centimes\u00a0saisis - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale de la wilaya de Sidi Bel Abb\u00e8s ont proc\u00e9d\u00e9 au d\u00e9mant\u00e8lement d&rsquo;un r\u00e9seau criminel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-12T19:29:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-12T19:29:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/01\/dgf-hgfsytd.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"1050\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/01\\\/12\\\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/01\\\/12\\\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Un r\u00e9seau international de blanchiment d&rsquo;argent\u00a0d\u00e9mantel\u00e9\u00a0:\u00a0plus de 6 milliards de centimes\u00a0saisis\",\"datePublished\":\"2026-01-12T19:29:52+00:00\",\"dateModified\":\"2026-01-12T19:29:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/01\\\/12\\\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\\\/\"},\"wordCount\":407,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/01\\\/12\\\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dgf-hgfsytd.webp\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/01\\\/12\\\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/01\\\/12\\\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/01\\\/12\\\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\\\/\",\"name\":\"Un r\u00e9seau international de blanchiment d&rsquo;argent\u00a0d\u00e9mantel\u00e9\u00a0:\u00a0plus de 6 milliards de centimes\u00a0saisis - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/01\\\/12\\\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/01\\\/12\\\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dgf-hgfsytd.webp\",\"datePublished\":\"2026-01-12T19:29:52+00:00\",\"dateModified\":\"2026-01-12T19:29:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/01\\\/12\\\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/01\\\/12\\\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/01\\\/12\\\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dgf-hgfsytd.webp\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dgf-hgfsytd.webp\",\"width\":1400,\"height\":1050},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/01\\\/12\\\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un r\u00e9seau international de blanchiment d&rsquo;argent\u00a0d\u00e9mantel\u00e9\u00a0:\u00a0plus de 6 milliards de centimes\u00a0saisis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un r\u00e9seau international de blanchiment d&rsquo;argent\u00a0d\u00e9mantel\u00e9\u00a0:\u00a0plus de 6 milliards de centimes\u00a0saisis - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/","og_locale":"fr_FR","og_type":"article","og_title":"Un r\u00e9seau international de blanchiment d&rsquo;argent\u00a0d\u00e9mantel\u00e9\u00a0:\u00a0plus de 6 milliards de centimes\u00a0saisis - La Sentinelle","og_description":"Les \u00e9l\u00e9ments de la S\u00fbret\u00e9 nationale de la wilaya de Sidi Bel Abb\u00e8s ont proc\u00e9d\u00e9 au d\u00e9mant\u00e8lement d&rsquo;un r\u00e9seau criminel","og_url":"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2026-01-12T19:29:52+00:00","article_modified_time":"2026-01-12T19:29:54+00:00","og_image":[{"width":1400,"height":1050,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/01\/dgf-hgfsytd.webp","type":"image\/webp"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Un r\u00e9seau international de blanchiment d&rsquo;argent\u00a0d\u00e9mantel\u00e9\u00a0:\u00a0plus de 6 milliards de centimes\u00a0saisis","datePublished":"2026-01-12T19:29:52+00:00","dateModified":"2026-01-12T19:29:54+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/"},"wordCount":407,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/01\/dgf-hgfsytd.webp","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/","url":"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/","name":"Un r\u00e9seau international de blanchiment d&rsquo;argent\u00a0d\u00e9mantel\u00e9\u00a0:\u00a0plus de 6 milliards de centimes\u00a0saisis - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/01\/dgf-hgfsytd.webp","datePublished":"2026-01-12T19:29:52+00:00","dateModified":"2026-01-12T19:29:54+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/01\/dgf-hgfsytd.webp","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/01\/dgf-hgfsytd.webp","width":1400,"height":1050},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/01\/12\/un-reseau-international-de-blanchiment-dargent-demantele-plus-de-6-milliards-de-centimes-saisis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Un r\u00e9seau international de blanchiment d&rsquo;argent\u00a0d\u00e9mantel\u00e9\u00a0:\u00a0plus de 6 milliards de centimes\u00a0saisis"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/79380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=79380"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/79380\/revisions"}],"predecessor-version":[{"id":79383,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/79380\/revisions\/79383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/79381"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=79380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=79380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=79380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}