{"id":81028,"date":"2026-02-10T13:55:38","date_gmt":"2026-02-10T12:55:38","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=81028"},"modified":"2026-02-10T13:55:39","modified_gmt":"2026-02-10T12:55:39","slug":"meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/","title":{"rendered":"Meeting en Salle de Metz\u00a0: Nouveau record d&rsquo;Alg\u00e9rie et arabe pour Mohamed Gouaned sur 800 m\u00e8tres"},"content":{"rendered":"\n<p>Le demi-fondiste alg\u00e9rien Mohamed Ali Gouaned a \u00e9tabli un nouveau record national et arabe du 800 m\u00e8tres en salle, en r\u00e9alisant un chrono de 1:44.67, lors du meeting hivernal de Metz (France), disput\u00e9 dimanche soir .Le natif de Biskra (23 ans) am\u00e9liore ainsi ses propres records sur la distance, qu&rsquo;il avait d\u00e9j\u00e0 battus la semaine pass\u00e9e, en 1:45.10, lors du Meeting en Salle de l&rsquo;Eure (France).&nbsp;Le bon chrono r\u00e9alis\u00e9 par Gouaned est consid\u00e9r\u00e9 \u00e9galement comme un minima de qualification aux prochains championnats du monde en salle, pr\u00e9vus la mi-mars 2026 \u00e0 Torun, en Pologne.<\/p>\n\n\n\n<p>Ce qui est \u00e9galement le cas pour son compatriote Slimane Moula, qui s&rsquo;est qualifi\u00e9 ce week-end, avec un chrono de 1:45.48, r\u00e9alis\u00e9 lors d&rsquo;un meeting international en Russie.&nbsp;Deux autres athl\u00e8tes alg\u00e9riens ambitionnent de se qualifier \u00e0 ces Mondiaux, Ha\u00efthem Chenitef (sur 1500 m\u00e8tres) et Yasser Mohamed Tahar Triki (au triple saut).&nbsp;Ces deux athl\u00e8tes comptent s&rsquo;engager en effet dans certains meetings pr\u00e9vus prochainement dans diff\u00e9rents pays d&rsquo;Europe, avec l&rsquo;objectif d&rsquo;y r\u00e9aliser les minimas n\u00e9cessaires.&nbsp;<\/p>\n\n\n\n<p>APS&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le demi-fondiste alg\u00e9rien Mohamed Ali Gouaned a \u00e9tabli un nouveau record national et arabe du 800 m\u00e8tres en salle, en<\/p>\n","protected":false},"author":6,"featured_media":81029,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[33],"tags":[],"class_list":["post-81028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sports"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meeting en Salle de Metz\u00a0: Nouveau record d&rsquo;Alg\u00e9rie et arabe pour Mohamed Gouaned sur 800 m\u00e8tres - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meeting en Salle de Metz\u00a0: Nouveau record d&rsquo;Alg\u00e9rie et arabe pour Mohamed Gouaned sur 800 m\u00e8tres - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le demi-fondiste alg\u00e9rien Mohamed Ali Gouaned a \u00e9tabli un nouveau record national et arabe du 800 m\u00e8tres en salle, en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T12:55:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T12:55:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/mohamed-Gouaned.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/10\\\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/10\\\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Meeting en Salle de Metz\u00a0: Nouveau record d&rsquo;Alg\u00e9rie et arabe pour Mohamed Gouaned sur 800 m\u00e8tres\",\"datePublished\":\"2026-02-10T12:55:38+00:00\",\"dateModified\":\"2026-02-10T12:55:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/10\\\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\\\/\"},\"wordCount\":213,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/10\\\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/mohamed-Gouaned.jpeg\",\"articleSection\":[\"Sports\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/10\\\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/10\\\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/10\\\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\\\/\",\"name\":\"Meeting en Salle de Metz\u00a0: Nouveau record d&rsquo;Alg\u00e9rie et arabe pour Mohamed Gouaned sur 800 m\u00e8tres - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/10\\\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/10\\\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/mohamed-Gouaned.jpeg\",\"datePublished\":\"2026-02-10T12:55:38+00:00\",\"dateModified\":\"2026-02-10T12:55:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/10\\\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/10\\\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/10\\\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/mohamed-Gouaned.jpeg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/mohamed-Gouaned.jpeg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/10\\\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meeting en Salle de Metz\u00a0: Nouveau record d&rsquo;Alg\u00e9rie et arabe pour Mohamed Gouaned sur 800 m\u00e8tres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meeting en Salle de Metz\u00a0: Nouveau record d&rsquo;Alg\u00e9rie et arabe pour Mohamed Gouaned sur 800 m\u00e8tres - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/","og_locale":"fr_FR","og_type":"article","og_title":"Meeting en Salle de Metz\u00a0: Nouveau record d&rsquo;Alg\u00e9rie et arabe pour Mohamed Gouaned sur 800 m\u00e8tres - La Sentinelle","og_description":"Le demi-fondiste alg\u00e9rien Mohamed Ali Gouaned a \u00e9tabli un nouveau record national et arabe du 800 m\u00e8tres en salle, en","og_url":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2026-02-10T12:55:38+00:00","article_modified_time":"2026-02-10T12:55:39+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/mohamed-Gouaned.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Meeting en Salle de Metz\u00a0: Nouveau record d&rsquo;Alg\u00e9rie et arabe pour Mohamed Gouaned sur 800 m\u00e8tres","datePublished":"2026-02-10T12:55:38+00:00","dateModified":"2026-02-10T12:55:39+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/"},"wordCount":213,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/mohamed-Gouaned.jpeg","articleSection":["Sports"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/","url":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/","name":"Meeting en Salle de Metz\u00a0: Nouveau record d&rsquo;Alg\u00e9rie et arabe pour Mohamed Gouaned sur 800 m\u00e8tres - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/mohamed-Gouaned.jpeg","datePublished":"2026-02-10T12:55:38+00:00","dateModified":"2026-02-10T12:55:39+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/mohamed-Gouaned.jpeg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/mohamed-Gouaned.jpeg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/10\/meeting-en-salle-de-metz-nouveau-record-dalgerie-et-arabe-pour-mohamed-gouaned-sur-800-metres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Meeting en Salle de Metz\u00a0: Nouveau record d&rsquo;Alg\u00e9rie et arabe pour Mohamed Gouaned sur 800 m\u00e8tres"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/81028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=81028"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/81028\/revisions"}],"predecessor-version":[{"id":81031,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/81028\/revisions\/81031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/81029"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=81028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=81028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=81028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}