{"id":81122,"date":"2026-02-11T13:33:34","date_gmt":"2026-02-11T12:33:34","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=81122"},"modified":"2026-02-11T13:33:35","modified_gmt":"2026-02-11T12:33:35","slug":"lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/","title":{"rendered":"L&rsquo;ONU face \u00e0 une contamination\u00a0aux explosifs\u00a0sans pr\u00e9c\u00e9dent\u00a0:\u00a0Ghaza ensevelie sous 70 millions de tonnes de gravats\u00a0"},"content":{"rendered":"\n<p>Plus de 200 \u00e9valuations des risques li\u00e9s aux engins explosifs ont \u00e9t\u00e9 men\u00e9es la semaine derni\u00e8re dans la bande de Ghaza, ensevelie sous pr\u00e8s de 70 millions de tonnes de gravats apr\u00e8s plus de deux ans d&rsquo;agression g\u00e9nocidaire sioniste, tandis que l&rsquo;ONU alerte sur une contamination&nbsp;aux explosifs&nbsp;d&rsquo;une ampleur in\u00e9dite qui a d\u00e9j\u00e0 fait 9 morts et 65 bless\u00e9s depuis l&rsquo;entr\u00e9e en vigueur du cessez-le-feu en octobre dernier.<\/p>\n\n\n\n<p>Le porte-parole du Secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;ONU, St\u00e9phane Dujarric, a r\u00e9v\u00e9l\u00e9 lundi que les partenaires de la lutte anti-mines ont men\u00e9, jusqu&rsquo;\u00e0 mercredi dernier, plus de 200 \u00e9valuations des risques potentiels li\u00e9s aux engins explosifs afin de faciliter le d\u00e9blaiement des d\u00e9combres dans l&rsquo;enclave palestinienne martyris\u00e9e. Ces op\u00e9rations s&rsquo;ajoutent au soutien apport\u00e9 pour s\u00e9curiser les mouvements et les op\u00e9rations humanitaires dans un environnement extr\u00eamement p\u00e9rilleux o\u00f9 chaque m\u00e8tre carr\u00e9 peut receler un danger mortel.&nbsp;Au cours de la m\u00eame semaine, les \u00e9quipes sp\u00e9cialis\u00e9es ont \u00e9galement sensibilis\u00e9 plus de 10.000 enfants et adultes palestiniens aux risques li\u00e9s aux engins explosifs, une campagne d&rsquo;\u00e9ducation vitale dans un territoire transform\u00e9 en v\u00e9ritable champ de mines. Selon les partenaires de la lutte anti-mines cit\u00e9s par Dujarric, ce risque demeure majeur puisque 33 incidents impliquant des engins explosifs ont \u00e9t\u00e9 signal\u00e9s depuis l&rsquo;entr\u00e9e en vigueur du cessez-le-feu en octobre 2025, causant la mort de neuf personnes et blessant 65 autres. L&rsquo;enclave palestinienne est d\u00e9sormais confront\u00e9e \u00e0 une contamination explosive d&rsquo;une ampleur jamais vue dans l&rsquo;histoire des conflits modernes.&nbsp;Les chiffres r\u00e9v\u00e9l\u00e9s par le service de lutte anti-mines de l&rsquo;ONU donnent la mesure de la catastrophe. Depuis le d\u00e9but de l&rsquo;agression sioniste en octobre 2023, environ 70.000 tonnes d&rsquo;explosifs ont \u00e9t\u00e9 largu\u00e9es sur Ghaza. Le service UNMAS estime que 5 \u00e0 10% de ces munitions n&rsquo;ont toujours pas explos\u00e9, ce qui repr\u00e9sente entre 3.500 et 7.000 tonnes d&rsquo;engins demeurant dispers\u00e9s dans les maisons, les h\u00f4pitaux et les \u00e9coles. Ces munitions non explos\u00e9es constituent autant de pi\u00e8ges mortels pour une population civile d\u00e9j\u00e0 d\u00e9vast\u00e9e par plus de deux ans de bombardements incessants.&nbsp;La situation humanitaire demeure dramatique et les obstacles \u00e0 l&rsquo;aide internationale se multiplient. St\u00e9phane Dujarric a d\u00e9plor\u00e9 que les restrictions impos\u00e9es par l&rsquo;occupant, notamment celles concernant l&rsquo;entr\u00e9e d&rsquo;articles class\u00e9s comme \u00e0 double usage ou non humanitaires, continuent d&rsquo;entraver la r\u00e9ponse humanitaire. Ces articles comprennent des pi\u00e8ces de rechange essentielles et certains mat\u00e9riaux de construction indispensables pour les abris, alors que des centaines de milliers de Palestiniens vivent dans des conditions pr\u00e9caires. La radiation de certaines ONG internationales importantes et les restrictions impos\u00e9es \u00e0 l&rsquo;UNRWA et \u00e0 d&rsquo;autres agences des Nations unies compromettent \u00e9galement gravement les op\u00e9rations humanitaires, a-t-il ajout\u00e9.<\/p>\n\n\n\n<p>Sur le terrain, les violations de l&rsquo;accord de cessez-le-feu se poursuivent quotidiennement. L&rsquo;arm\u00e9e d&rsquo;occupation sioniste a men\u00e9 mardi de vastes op\u00e9rations de destruction ayant cibl\u00e9 des immeubles r\u00e9sidentiels palestiniens dans diverses zones de Ghaza, selon l&rsquo;agence palestinienne Wafa. Les forces d&rsquo;occupation ont proc\u00e9d\u00e9 \u00e0 des destructions massives dans les zones sous leur contr\u00f4le \u00e0 l&rsquo;est de Khan Youn\u00e8s, tandis que des t\u00e9moins oculaires dans le nord de l&rsquo;enclave ont rapport\u00e9 des op\u00e9rations similaires men\u00e9es \u00e0 l&rsquo;est de la ville de Ghaza.&nbsp;Des drones ont largu\u00e9 des charges explosives sur ce qui restait des habitations palestiniennes dans le camp de Jabalia, d\u00e9j\u00e0 ravag\u00e9 par les bombardements pr\u00e9c\u00e9dents.&nbsp;Ces op\u00e9rations ont \u00e9t\u00e9 accompagn\u00e9es de tirs intenses en direction des c\u00f4tes de Rafah et de Khan Youn\u00e8s, ainsi que de tirs provenant des v\u00e9hicules militaires stationn\u00e9s \u00e0 l&rsquo;est de Khan Youn\u00e8s, maintenant une atmosph\u00e8re de terreur permanente parmi la population civile palestinienne.&nbsp;Le bilan humain de cette agression g\u00e9nocidaire continue de s&rsquo;alourdir. Selon le dernier d\u00e9compte des autorit\u00e9s sanitaires palestiniennes publi\u00e9 mardi, l&rsquo;agression a fait 72.037 martyrs et 171.666 bless\u00e9s, en majorit\u00e9 des femmes et des enfants, depuis le 7 octobre 2023. Au cours des derni\u00e8res 24 heures seulement, les corps de 5 martyrs et 5 personnes bless\u00e9es ont \u00e9t\u00e9 transf\u00e9r\u00e9s vers les h\u00f4pitaux de Ghaza, tandis que de nombreuses victimes se trouvent encore sous les d\u00e9combres. Depuis l&rsquo;entr\u00e9e en vigueur du cessez-le-feu le 10 octobre dernier, 586 Palestiniens sont tomb\u00e9s en martyrs et 1.558 autres ont \u00e9t\u00e9 bless\u00e9s, tandis que 717 corps de martyrs ont \u00e9t\u00e9 r\u00e9cup\u00e9r\u00e9s.<\/p>\n\n\n\n<p>L&rsquo;inqui\u00e9tude de la communaut\u00e9 internationale s&rsquo;\u00e9tend \u00e9galement \u00e0 la Cisjordanie occup\u00e9e, o\u00f9 le Secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;ONU Antonio Guterres a exprim\u00e9 sa vive pr\u00e9occupation face aux d\u00e9cisions r\u00e9cemment annonc\u00e9es par l&rsquo;entit\u00e9 sioniste visant \u00e0 \u00e9tendre son contr\u00f4le. Selon son porte-parole, Guterres a r\u00e9affirm\u00e9 que toutes les colonies en Cisjordanie occup\u00e9e, y compris \u00e0 Al-Qods occup\u00e9e, constituent une violation flagrante du droit international et des r\u00e9solutions pertinentes des Nations unies. Ces mesures compromettent les perspectives de la solution \u00e0 deux \u00c9tats et sont ill\u00e9gales selon les conclusions de la Cour internationale de Justice.&nbsp;Face \u00e0 cette escalade, la Ligue arabe tiendra mercredi une r\u00e9union d&rsquo;urgence pour discuter des moyens d&rsquo;action arabe et internationale contre les d\u00e9cisions du gouvernement d&rsquo;occupation visant \u00e0 \u00e9tendre la colonisation et \u00e0 approfondir l&rsquo;annexion des territoires palestiniens.<\/p>\n\n\n\n<p>Lyes Sa\u00efdi<\/p>\n\n\n\n<p><strong>L&rsquo;ONU compte retirer la majeure partie des Casques bleus d\u00e9ploy\u00e9s au Liban d&rsquo;ici mi-2027<\/strong><\/p>\n\n\n\n<p>L&rsquo;ONU compte retirer d&rsquo;ici la mi-2027 la majeure partie des Casques bleus d\u00e9ploy\u00e9s au Liban, dont le mandat expire \u00e0 la fin de l&rsquo;ann\u00e9e, a indiqu\u00e9, mardi, sa porte-parole, Kandice Ardiel.&nbsp;La Force Int\u00e9rimaire des Nations unies au Liban (FINUL) \u00ab\u00a0pr\u00e9voit de r\u00e9duire et de retirer tout son personnel militaire d&rsquo;ici la mi-2027\u00a0\u00bb, a d\u00e9clar\u00e9 Mme Ardiel \u00e0 la presse.<\/p>\n\n\n\n<p>Les Casques bleus de la FINUL sont d\u00e9ploy\u00e9s au Liban depuis mars 1978, mais ils devront partir \u00e0 compter du 31 d\u00e9cembre et dans un d\u00e9lai d&rsquo;un an, conform\u00e9ment \u00e0 une r\u00e9solution vot\u00e9e en ao\u00fbt dernier.&nbsp;Apr\u00e8s la fin de son mandat le 31 d\u00e9cembre 2026, \u00ab\u00a0nous commencerons le processus de rapatriement du personnel et des \u00e9quipements et le transfert de nos positions aux autorit\u00e9s libanaises\u00a0\u00bb, a-t-elle pr\u00e9cis\u00e9.&nbsp;La porte-parole a pr\u00e9cis\u00e9 qu&rsquo;apr\u00e8s la cessation des op\u00e9rations de la FINUL, celle-ci aura des missions limit\u00e9es, notamment \u00ab\u00a0prot\u00e9ger le personnel et les biens de l&rsquo;ONU\u00a0\u00bb et prot\u00e9ger le d\u00e9part de ses membres.&nbsp;Les Casques bleus patrouillent pr\u00e8s de la fronti\u00e8re avec l&rsquo;entit\u00e9 sioniste et op\u00e8rent actuellement en coop\u00e9ration avec l&rsquo;arm\u00e9e libanaise.&nbsp;Malgr\u00e9 un accord de cessez-le-feu entr\u00e9 en vigueur en novembre 2024, l&rsquo;entit\u00e9 sioniste poursuit son agression contre le Liban, et la FINUL a rapport\u00e9 \u00e0 plusieurs reprises des tirs sionistes sur ses positions.&nbsp;La porte-parole a indiqu\u00e9 en outre, que la Finul avait r\u00e9duit de presque 2.000 le nombre de Casques bleus, et que quelque 200 doivent encore partir en mai.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plus de 200 \u00e9valuations des risques li\u00e9s aux engins explosifs ont \u00e9t\u00e9 men\u00e9es la semaine derni\u00e8re dans la bande de<\/p>\n","protected":false},"author":6,"featured_media":74912,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[52,37],"tags":[],"class_list":["post-81122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-monde"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&rsquo;ONU face \u00e0 une contamination\u00a0aux explosifs\u00a0sans pr\u00e9c\u00e9dent\u00a0:\u00a0Ghaza ensevelie sous 70 millions de tonnes de gravats\u00a0 - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&rsquo;ONU face \u00e0 une contamination\u00a0aux explosifs\u00a0sans pr\u00e9c\u00e9dent\u00a0:\u00a0Ghaza ensevelie sous 70 millions de tonnes de gravats\u00a0 - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Plus de 200 \u00e9valuations des risques li\u00e9s aux engins explosifs ont \u00e9t\u00e9 men\u00e9es la semaine derni\u00e8re dans la bande de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-11T12:33:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T12:33:35+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/11\\\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/11\\\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"L&rsquo;ONU face \u00e0 une contamination\u00a0aux explosifs\u00a0sans pr\u00e9c\u00e9dent\u00a0:\u00a0Ghaza ensevelie sous 70 millions de tonnes de gravats\u00a0\",\"datePublished\":\"2026-02-11T12:33:34+00:00\",\"dateModified\":\"2026-02-11T12:33:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/11\\\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\\\/\"},\"wordCount\":1260,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/11\\\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Ghaza.avif\",\"articleSection\":[\"\u00c0 la Une\",\"Monde\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/11\\\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/11\\\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/11\\\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\\\/\",\"name\":\"L&rsquo;ONU face \u00e0 une contamination\u00a0aux explosifs\u00a0sans pr\u00e9c\u00e9dent\u00a0:\u00a0Ghaza ensevelie sous 70 millions de tonnes de gravats\u00a0 - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/11\\\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/11\\\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Ghaza.avif\",\"datePublished\":\"2026-02-11T12:33:34+00:00\",\"dateModified\":\"2026-02-11T12:33:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/11\\\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/11\\\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/11\\\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Ghaza.avif\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Ghaza.avif\",\"width\":2000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/11\\\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;ONU face \u00e0 une contamination\u00a0aux explosifs\u00a0sans pr\u00e9c\u00e9dent\u00a0:\u00a0Ghaza ensevelie sous 70 millions de tonnes de gravats\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L&rsquo;ONU face \u00e0 une contamination\u00a0aux explosifs\u00a0sans pr\u00e9c\u00e9dent\u00a0:\u00a0Ghaza ensevelie sous 70 millions de tonnes de gravats\u00a0 - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/","og_locale":"fr_FR","og_type":"article","og_title":"L&rsquo;ONU face \u00e0 une contamination\u00a0aux explosifs\u00a0sans pr\u00e9c\u00e9dent\u00a0:\u00a0Ghaza ensevelie sous 70 millions de tonnes de gravats\u00a0 - La Sentinelle","og_description":"Plus de 200 \u00e9valuations des risques li\u00e9s aux engins explosifs ont \u00e9t\u00e9 men\u00e9es la semaine derni\u00e8re dans la bande de","og_url":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2026-02-11T12:33:34+00:00","article_modified_time":"2026-02-11T12:33:35+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"L&rsquo;ONU face \u00e0 une contamination\u00a0aux explosifs\u00a0sans pr\u00e9c\u00e9dent\u00a0:\u00a0Ghaza ensevelie sous 70 millions de tonnes de gravats\u00a0","datePublished":"2026-02-11T12:33:34+00:00","dateModified":"2026-02-11T12:33:35+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/"},"wordCount":1260,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/Ghaza.avif","articleSection":["\u00c0 la Une","Monde"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/","url":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/","name":"L&rsquo;ONU face \u00e0 une contamination\u00a0aux explosifs\u00a0sans pr\u00e9c\u00e9dent\u00a0:\u00a0Ghaza ensevelie sous 70 millions de tonnes de gravats\u00a0 - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/Ghaza.avif","datePublished":"2026-02-11T12:33:34+00:00","dateModified":"2026-02-11T12:33:35+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/Ghaza.avif","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/Ghaza.avif","width":2000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/11\/lonu-face-a-une-contamination-aux-explosifs-sans-precedent-ghaza-ensevelie-sous-70-millions-de-tonnes-de-gravats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;ONU face \u00e0 une contamination\u00a0aux explosifs\u00a0sans pr\u00e9c\u00e9dent\u00a0:\u00a0Ghaza ensevelie sous 70 millions de tonnes de gravats\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/81122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=81122"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/81122\/revisions"}],"predecessor-version":[{"id":81124,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/81122\/revisions\/81124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/74912"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=81122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=81122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=81122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}