{"id":82052,"date":"2026-02-22T20:31:47","date_gmt":"2026-02-22T19:31:47","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=82052"},"modified":"2026-02-22T20:31:48","modified_gmt":"2026-02-22T19:31:48","slug":"programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/","title":{"rendered":"Programme d&rsquo;importation de 10.000 bus\u00a0: R\u00e9ception de 338 bus au port d&rsquo;Alger et de 97 autres au port de Djen Djen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L&rsquo;Etablissement de d\u00e9veloppement de l&rsquo;industrie de v\u00e9hicules (EDIV), relevant de la Direction des fabrications militaires du minist\u00e8re de la D\u00e9fense nationale (MDN), a r\u00e9ceptionn\u00e9, dimanche, 338 bus de diff\u00e9rentes cat\u00e9gories au port d&rsquo;Alger et 97 autres au port de Djen Djen, livr\u00e9s par le partenaire chinois, dans le cadre du programme d&rsquo;importation de 10.000 bus neufs destin\u00e9s au renouvellement du parc national de transport de voyageurs. Cette op\u00e9ration s&rsquo;inscrit dans le cadre de la mise en \u0153uvre du programme du pr\u00e9sident de la R\u00e9publique, Chef supr\u00eame des Forces arm\u00e9es, ministre de la D\u00e9fense nationale, M. Abdelmadjid Tebboune, pour l&rsquo;importation de 10.000 bus neufs destin\u00e9s au renouvellement du parc national des bus de transport de voyageurs. La concr\u00e9tisation de ce programme est supervis\u00e9e par le ministre d\u00e9l\u00e9gu\u00e9 aupr\u00e8s du ministre de la D\u00e9fense nationale, Chef d&rsquo;Etat-Major de l&rsquo;Arm\u00e9e nationale populaire, le G\u00e9n\u00e9ral d&rsquo;Arm\u00e9e Sa\u00efd Chanegriha. La r\u00e9ception d&rsquo;autres bus import\u00e9s aupr\u00e8s des partenaires \u00e9trangers, notamment la R\u00e9publique populaire de Chine et la R\u00e9publique f\u00e9d\u00e9rale d&rsquo;Allemagne, se poursuit. Le pr\u00e9sident de la R\u00e9publique avait d\u00e9cid\u00e9 l&rsquo;importation de 10.000 bus de transport de voyageurs neufs pour remplacer les bus v\u00e9tustes, ainsi que l&rsquo;importation imm\u00e9diate et massive de divers types de pneumatiques pour v\u00e9hicules.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Etablissement de d\u00e9veloppement de l&rsquo;industrie de v\u00e9hicules (EDIV), relevant de la Direction des fabrications militaires du minist\u00e8re de la D\u00e9fense<\/p>\n","protected":false},"author":6,"featured_media":80503,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-82052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Programme d&rsquo;importation de 10.000 bus\u00a0: R\u00e9ception de 338 bus au port d&rsquo;Alger et de 97 autres au port de Djen Djen - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programme d&rsquo;importation de 10.000 bus\u00a0: R\u00e9ception de 338 bus au port d&rsquo;Alger et de 97 autres au port de Djen Djen - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;Etablissement de d\u00e9veloppement de l&rsquo;industrie de v\u00e9hicules (EDIV), relevant de la Direction des fabrications militaires du minist\u00e8re de la D\u00e9fense\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-22T19:31:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-22T19:31:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/bus.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/22\\\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/22\\\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Programme d&rsquo;importation de 10.000 bus\u00a0: R\u00e9ception de 338 bus au port d&rsquo;Alger et de 97 autres au port de Djen Djen\",\"datePublished\":\"2026-02-22T19:31:47+00:00\",\"dateModified\":\"2026-02-22T19:31:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/22\\\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\\\/\"},\"wordCount\":272,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/22\\\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/bus.webp\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/22\\\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/22\\\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/22\\\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\\\/\",\"name\":\"Programme d&rsquo;importation de 10.000 bus\u00a0: R\u00e9ception de 338 bus au port d&rsquo;Alger et de 97 autres au port de Djen Djen - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/22\\\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/22\\\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/bus.webp\",\"datePublished\":\"2026-02-22T19:31:47+00:00\",\"dateModified\":\"2026-02-22T19:31:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/22\\\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/22\\\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/22\\\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/bus.webp\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/bus.webp\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/22\\\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programme d&rsquo;importation de 10.000 bus\u00a0: R\u00e9ception de 338 bus au port d&rsquo;Alger et de 97 autres au port de Djen Djen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programme d&rsquo;importation de 10.000 bus\u00a0: R\u00e9ception de 338 bus au port d&rsquo;Alger et de 97 autres au port de Djen Djen - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/","og_locale":"fr_FR","og_type":"article","og_title":"Programme d&rsquo;importation de 10.000 bus\u00a0: R\u00e9ception de 338 bus au port d&rsquo;Alger et de 97 autres au port de Djen Djen - La Sentinelle","og_description":"L&rsquo;Etablissement de d\u00e9veloppement de l&rsquo;industrie de v\u00e9hicules (EDIV), relevant de la Direction des fabrications militaires du minist\u00e8re de la D\u00e9fense","og_url":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2026-02-22T19:31:47+00:00","article_modified_time":"2026-02-22T19:31:48+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/bus.webp","type":"image\/webp"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Programme d&rsquo;importation de 10.000 bus\u00a0: R\u00e9ception de 338 bus au port d&rsquo;Alger et de 97 autres au port de Djen Djen","datePublished":"2026-02-22T19:31:47+00:00","dateModified":"2026-02-22T19:31:48+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/"},"wordCount":272,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/bus.webp","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/","url":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/","name":"Programme d&rsquo;importation de 10.000 bus\u00a0: R\u00e9ception de 338 bus au port d&rsquo;Alger et de 97 autres au port de Djen Djen - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/bus.webp","datePublished":"2026-02-22T19:31:47+00:00","dateModified":"2026-02-22T19:31:48+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/bus.webp","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/bus.webp","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/22\/programme-dimportation-de-10-000-bus-reception-de-338-bus-au-port-dalger-et-de-97-autres-au-port-de-djen-djen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Programme d&rsquo;importation de 10.000 bus\u00a0: R\u00e9ception de 338 bus au port d&rsquo;Alger et de 97 autres au port de Djen Djen"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/82052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=82052"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/82052\/revisions"}],"predecessor-version":[{"id":82054,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/82052\/revisions\/82054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/80503"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=82052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=82052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=82052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}