{"id":82339,"date":"2026-02-25T20:12:09","date_gmt":"2026-02-25T19:12:09","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=82339"},"modified":"2026-02-25T20:12:11","modified_gmt":"2026-02-25T19:12:11","slug":"organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/","title":{"rendered":"Organisation territoriale\u00a0: Sayoud promet des moyens pour les nouvelles wilayas et annonce une r\u00e9forme du financement local"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le ministre de l&rsquo;Int\u00e9rieur, des Collectivit\u00e9s locales et des Transports, Sa\u00efd Sayoud, a r\u00e9affirm\u00e9 mercredi devant les d\u00e9put\u00e9s de l&rsquo;Assembl\u00e9e populaire nationale l&rsquo;engagement de l&rsquo;\u00c9tat \u00e0 doter les nouvelles wilayas des moyens mat\u00e9riels et humains n\u00e9cessaires \u00e0 leur fonctionnement, tout en annon\u00e7ant l&rsquo;\u00e9laboration d&rsquo;une feuille de route pour r\u00e9former le syst\u00e8me financier local. Ces d\u00e9clarations interviennent lors de l&rsquo;examen du texte de loi relatif \u00e0 l&rsquo;organisation territoriale du pays, qui pr\u00e9voit la promotion de 11 circonscriptions administratives en wilayas \u00e0 part enti\u00e8re. R\u00e9pondant aux questions des d\u00e9put\u00e9s lors de la s\u00e9ance pl\u00e9ni\u00e8re consacr\u00e9e \u00e0 l&rsquo;examen de ce texte strat\u00e9gique, le ministre a mis en avant l&rsquo;importance que rev\u00eat cette loi pour \u00ab\u00a0rem\u00e9dier aux d\u00e9s\u00e9quilibres et r\u00e9pondre aux aspirations des citoyens\u00a0\u00bb. M. Sayoud a pr\u00e9cis\u00e9 que \u00ab\u00a0cette d\u00e9marche importante s&rsquo;inscrit dans la dynamique des r\u00e9formes engag\u00e9es par l&rsquo;\u00c9tat alg\u00e9rien, sous la conduite clairvoyante du pr\u00e9sident de la R\u00e9publique, Abdelmadjid Tebboune, dans le cadre d&rsquo;une vision strat\u00e9gique reposant sur une approche \u00e9quilibr\u00e9e, responsable et progressive, visant \u00e0 rem\u00e9dier aux disparit\u00e9s territoriales\u00a0\u00bb. Cette approche, a-t-il ajout\u00e9, pr\u00e9voit \u00ab\u00a0la cr\u00e9ation de nouvelles communes et wilayas sur des bases saines fond\u00e9es sur des crit\u00e8res objectifs et pr\u00e9cis, en parfaite ad\u00e9quation avec les aspirations des citoyens et les exigences de la conjoncture actuelle\u00a0\u00bb. Le ministre a \u00e9galement rappel\u00e9 qu'\u00a0\u00bbune \u00e9valuation globale de la loi relative \u00e0 l&rsquo;organisation territoriale du pays est en cours pour d\u00e9gager les aspects positifs, relever les insuffisances et \u00e9laborer une feuille de route prospective permettant \u00e0 l&rsquo;Alg\u00e9rie d&rsquo;y rem\u00e9dier\u00a0\u00bb. Concernant la pr\u00e9occupation li\u00e9e \u00e0 la gouvernance et \u00e0 la d\u00e9centralisation, qui a occup\u00e9 une place importante dans les d\u00e9bats parlementaires, Sa\u00efd Sayoud a r\u00e9affirm\u00e9 \u00ab\u00a0son engagement \u00e0 \u0153uvrer, en coordination avec les diff\u00e9rents secteurs, au renforcement des nouvelles wilayas en les dotant des moyens mat\u00e9riels et humains n\u00e9cessaires pour leur permettre d&rsquo;am\u00e9liorer leurs capacit\u00e9s de gestion, et promouvoir une action publique locale efficace et performante\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1.800 postes budg\u00e9taires pour les nouvelles wilayas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur le plan financier, le ministre a d\u00e9voil\u00e9 des chiffres concrets t\u00e9moignant de la mobilisation de l&rsquo;\u00c9tat. \u00ab\u00a0Une enveloppe financi\u00e8re de plus de 22 milliards de dinars a \u00e9t\u00e9 allou\u00e9e par la Caisse de Solidarit\u00e9 et de Garantie des Collectivit\u00e9s locales, et les Plans communaux de d\u00e9veloppement, destin\u00e9e au financement de projets de proximit\u00e9 \u00e0 m\u00eame de r\u00e9pondre rapidement aux attentes des populations et d&rsquo;impulser une nouvelle dynamique aux nouvelles wilayas\u00a0\u00bb, a-t-il pr\u00e9cis\u00e9. En mati\u00e8re de ressources humaines, M. Sayoud a annonc\u00e9 que 1.800 nouveaux postes budg\u00e9taires ont \u00e9t\u00e9 ouverts au profit de ces wilayas, ce qui permettra, selon lui, \u00ab\u00a0d&rsquo;am\u00e9liorer la qualit\u00e9 des services publics\u00a0\u00bb. Il a \u00e9galement \u00e9voqu\u00e9 \u00ab\u00a0la d\u00e9signation de cadres exp\u00e9riment\u00e9s dans la gestion des affaires locales pour superviser la gestion\u00a0\u00bb de ces nouvelles entit\u00e9s administratives. Dans une d\u00e9marche visant \u00e0 garantir l&rsquo;autonomie financi\u00e8re des wilayas nouvellement cr\u00e9\u00e9es, le ministre a annonc\u00e9 que son secteur s&#8217;emploie \u00e0 \u00ab\u00a0l&rsquo;\u00e9laboration d&rsquo;une feuille de route pour la r\u00e9forme du syst\u00e8me financier local, afin de permettre aux collectivit\u00e9s locales de mobiliser leurs ressources sans d\u00e9pendance excessive aux allocations et transferts du budget de l&rsquo;\u00c9tat\u00a0\u00bb. Cette annonce marque une volont\u00e9 de rupture avec un mod\u00e8le de financement centralis\u00e9 qui a longtemps caract\u00e9ris\u00e9 la gestion des collectivit\u00e9s locales alg\u00e9riennes. Ces d\u00e9clarations interviennent au lendemain de la pr\u00e9sentation officielle du texte de loi devant l&rsquo;APN. Mardi, lors de son intervention devant les d\u00e9put\u00e9s, M. Sayoud avait soulign\u00e9 que ce texte, d\u00e9j\u00e0 vot\u00e9 par les membres du Conseil de la Nation, refl\u00e8te une \u00ab\u00a0volont\u00e9 politique claire de consolider l&rsquo;\u00e9quilibre r\u00e9gional et d&rsquo;appuyer le d\u00e9veloppement durable \u00e0 travers l&rsquo;ensemble du territoire national\u00a0\u00bb. Il avait \u00e9galement pr\u00e9cis\u00e9 qu&rsquo;il constitue \u00ab\u00a0une \u00e9tape institutionnelle importante vers le rapprochement du pouvoir d\u00e9cisionnel et l&rsquo;instauration d&rsquo;une administration plus efficace, capable de r\u00e9pondre aux attentes des citoyens et d&rsquo;am\u00e9liorer la qualit\u00e9 du service public\u00a0\u00bb. Le ministre avait alors expliqu\u00e9 que le texte s&rsquo;inscrit dans un processus national progressif de r\u00e9organisation du territoire, \u00ab\u00a0fond\u00e9 sur des crit\u00e8res objectifs pr\u00e9cis et une vision strat\u00e9gique globale incluant des donn\u00e9es d\u00e9mographiques, humaines, \u00e9conomiques et g\u00e9ographiques, tenant compte des exigences du d\u00e9veloppement et de l&rsquo;efficacit\u00e9 administrative\u00a0\u00bb. Il avait \u00e9galement rappel\u00e9 que cette initiative intervient dans le cadre de la mise en \u0153uvre des directives du pr\u00e9sident de la R\u00e9publique, qui a donn\u00e9 des instructions claires pour traiter le dossier du d\u00e9coupage territorial, suivant \u00ab\u00a0une approche \u00e9quilibr\u00e9e et responsable, tenant compte des sp\u00e9cificit\u00e9s de chaque territoire\u00a0\u00bb. M. Sayoud avait pr\u00e9cis\u00e9 que le texte de loi pr\u00e9voit une p\u00e9riode transitoire d&rsquo;une ann\u00e9e pour concr\u00e9tiser cette d\u00e9marche, s&rsquo;\u00e9tendant jusqu&rsquo;au 31 d\u00e9cembre 2026, p\u00e9riode durant laquelle \u00ab\u00a0les autorit\u00e9s des wilayas-m\u00e8res continuent d&rsquo;exercer toutes les pr\u00e9rogatives et obligations li\u00e9es \u00e0 la gestion des services des nouvelles wilayas jusqu&rsquo;au parach\u00e8vement de leur mise en place\u00a0\u00bb. Le texte pr\u00e9voit la promotion de 11 circonscriptions administratives en wilayas \u00e0 part enti\u00e8re, couvrant une superficie de 100.000 kilom\u00e8tres carr\u00e9s et comptant plus de 2,5 millions d&rsquo;habitants, comprenant 40 da\u00efras et 108 communes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hocine Fadheli<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre de l&rsquo;Int\u00e9rieur, des Collectivit\u00e9s locales et des Transports, Sa\u00efd Sayoud, a r\u00e9affirm\u00e9 mercredi devant les d\u00e9put\u00e9s de l&rsquo;Assembl\u00e9e<\/p>\n","protected":false},"author":6,"featured_media":82340,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-82339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Organisation territoriale\u00a0: Sayoud promet des moyens pour les nouvelles wilayas et annonce une r\u00e9forme du financement local - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Organisation territoriale\u00a0: Sayoud promet des moyens pour les nouvelles wilayas et annonce une r\u00e9forme du financement local - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le ministre de l&rsquo;Int\u00e9rieur, des Collectivit\u00e9s locales et des Transports, Sa\u00efd Sayoud, a r\u00e9affirm\u00e9 mercredi devant les d\u00e9put\u00e9s de l&rsquo;Assembl\u00e9e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-25T19:12:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T19:12:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/sayoud-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/25\\\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/25\\\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Organisation territoriale\u00a0: Sayoud promet des moyens pour les nouvelles wilayas et annonce une r\u00e9forme du financement local\",\"datePublished\":\"2026-02-25T19:12:09+00:00\",\"dateModified\":\"2026-02-25T19:12:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/25\\\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\\\/\"},\"wordCount\":973,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/25\\\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sayoud-1.jpg\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/25\\\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/25\\\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/25\\\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\\\/\",\"name\":\"Organisation territoriale\u00a0: Sayoud promet des moyens pour les nouvelles wilayas et annonce une r\u00e9forme du financement local - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/25\\\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/25\\\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sayoud-1.jpg\",\"datePublished\":\"2026-02-25T19:12:09+00:00\",\"dateModified\":\"2026-02-25T19:12:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/25\\\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/25\\\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/25\\\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sayoud-1.jpg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sayoud-1.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/02\\\/25\\\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Organisation territoriale\u00a0: Sayoud promet des moyens pour les nouvelles wilayas et annonce une r\u00e9forme du financement local\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Organisation territoriale\u00a0: Sayoud promet des moyens pour les nouvelles wilayas et annonce une r\u00e9forme du financement local - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/","og_locale":"fr_FR","og_type":"article","og_title":"Organisation territoriale\u00a0: Sayoud promet des moyens pour les nouvelles wilayas et annonce une r\u00e9forme du financement local - La Sentinelle","og_description":"Le ministre de l&rsquo;Int\u00e9rieur, des Collectivit\u00e9s locales et des Transports, Sa\u00efd Sayoud, a r\u00e9affirm\u00e9 mercredi devant les d\u00e9put\u00e9s de l&rsquo;Assembl\u00e9e","og_url":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2026-02-25T19:12:09+00:00","article_modified_time":"2026-02-25T19:12:11+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/sayoud-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Organisation territoriale\u00a0: Sayoud promet des moyens pour les nouvelles wilayas et annonce une r\u00e9forme du financement local","datePublished":"2026-02-25T19:12:09+00:00","dateModified":"2026-02-25T19:12:11+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/"},"wordCount":973,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/sayoud-1.jpg","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/","url":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/","name":"Organisation territoriale\u00a0: Sayoud promet des moyens pour les nouvelles wilayas et annonce une r\u00e9forme du financement local - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/sayoud-1.jpg","datePublished":"2026-02-25T19:12:09+00:00","dateModified":"2026-02-25T19:12:11+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/sayoud-1.jpg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/02\/sayoud-1.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/02\/25\/organisation-territoriale-sayoud-promet-des-moyens-pour-les-nouvelles-wilayas-et-annonce-une-reforme-du-financement-local\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Organisation territoriale\u00a0: Sayoud promet des moyens pour les nouvelles wilayas et annonce une r\u00e9forme du financement local"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/82339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=82339"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/82339\/revisions"}],"predecessor-version":[{"id":82341,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/82339\/revisions\/82341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/82340"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=82339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=82339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=82339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}