{"id":85524,"date":"2026-04-13T14:00:00","date_gmt":"2026-04-13T13:00:00","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=85524"},"modified":"2026-04-13T14:17:35","modified_gmt":"2026-04-13T13:17:35","slug":"energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/","title":{"rendered":"Energie solaire\u00a0: Mise en service de deux centrales d&rsquo;une capacit\u00e9 totale de 400 MW\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le ministre de l&rsquo;Energie et des Energies renouvelables, Mourad Adjal, a indiqu\u00e9, dimanche \u00e0 Alger, que deux centrales solaires d&rsquo;une capacit\u00e9 globale de 400 m\u00e9gawatts (MW) ont \u00e9t\u00e9 r\u00e9cemment mises en service, pr\u00e9cisant que le secteur vise \u00e0 atteindre une capacit\u00e9 de production suppl\u00e9mentaire de plus de 1.400 MW durant l&rsquo;ann\u00e9e en cours. S&rsquo;exprimant lors d&rsquo;une rencontre nationale des dirigeants du secteur de l&rsquo;\u00e9nergie et des \u00e9nergies renouvelables, M. Adjal a expliqu\u00e9 que les projets dont la r\u00e9ception est programm\u00e9e de mani\u00e8re progressive au cours des prochains mois pour atteindre plus de 1400 MW, s&rsquo;inscrivent dans le cadre de la concr\u00e9tisation de la premi\u00e8re phase du projet de 3.200 MW, au titre du programme national de production de 15.000 MW \u00e0 l&rsquo;horizon 2035. S&rsquo;agissant des deux centrales photovolta\u00efques mises en service la semaine derni\u00e8re, le ministre a d\u00e9taill\u00e9 qu&rsquo;il s&rsquo;agit de la centrale de production de 200 MW \u00e0 Tendla dans la wilaya d&rsquo;El Meghaier, et de la centrale de 200 MW \u00e0 El Ghrous dans la wilaya de Biskra. Concernant l&rsquo;avancement global du projet de r\u00e9alisation de 3.200 m\u00e9gawatts-cr\u00eate (MWc) d&rsquo;\u00e9nergie solaire photovolta\u00efque, le taux de r\u00e9alisation des 22 centrales pr\u00e9vues a atteint 40%, selon les explications fournies lors de cette rencontre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">APS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre de l&rsquo;Energie et des Energies renouvelables, Mourad Adjal, a indiqu\u00e9, dimanche \u00e0 Alger, que deux centrales solaires d&rsquo;une<\/p>\n","protected":false},"author":6,"featured_media":75469,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[29],"tags":[],"class_list":["post-85524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Energie solaire\u00a0: Mise en service de deux centrales d&rsquo;une capacit\u00e9 totale de 400 MW\u00a0 - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energie solaire\u00a0: Mise en service de deux centrales d&rsquo;une capacit\u00e9 totale de 400 MW\u00a0 - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le ministre de l&rsquo;Energie et des Energies renouvelables, Mourad Adjal, a indiqu\u00e9, dimanche \u00e0 Alger, que deux centrales solaires d&rsquo;une\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-13T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T13:17:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/ENR.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"1265\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Energie solaire\u00a0: Mise en service de deux centrales d&rsquo;une capacit\u00e9 totale de 400 MW\u00a0\",\"datePublished\":\"2026-04-13T13:00:00+00:00\",\"dateModified\":\"2026-04-13T13:17:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\\\/\"},\"wordCount\":236,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ENR.gif\",\"articleSection\":[\"\u00c9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\\\/\",\"name\":\"Energie solaire\u00a0: Mise en service de deux centrales d&rsquo;une capacit\u00e9 totale de 400 MW\u00a0 - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ENR.gif\",\"datePublished\":\"2026-04-13T13:00:00+00:00\",\"dateModified\":\"2026-04-13T13:17:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ENR.gif\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ENR.gif\",\"width\":1900,\"height\":1265},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energie solaire\u00a0: Mise en service de deux centrales d&rsquo;une capacit\u00e9 totale de 400 MW\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energie solaire\u00a0: Mise en service de deux centrales d&rsquo;une capacit\u00e9 totale de 400 MW\u00a0 - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/","og_locale":"fr_FR","og_type":"article","og_title":"Energie solaire\u00a0: Mise en service de deux centrales d&rsquo;une capacit\u00e9 totale de 400 MW\u00a0 - La Sentinelle","og_description":"Le ministre de l&rsquo;Energie et des Energies renouvelables, Mourad Adjal, a indiqu\u00e9, dimanche \u00e0 Alger, que deux centrales solaires d&rsquo;une","og_url":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2026-04-13T13:00:00+00:00","article_modified_time":"2026-04-13T13:17:35+00:00","og_image":[{"width":1900,"height":1265,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/ENR.gif","type":"image\/gif"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Energie solaire\u00a0: Mise en service de deux centrales d&rsquo;une capacit\u00e9 totale de 400 MW\u00a0","datePublished":"2026-04-13T13:00:00+00:00","dateModified":"2026-04-13T13:17:35+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/"},"wordCount":236,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/ENR.gif","articleSection":["\u00c9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/","url":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/","name":"Energie solaire\u00a0: Mise en service de deux centrales d&rsquo;une capacit\u00e9 totale de 400 MW\u00a0 - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/ENR.gif","datePublished":"2026-04-13T13:00:00+00:00","dateModified":"2026-04-13T13:17:35+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/ENR.gif","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2025\/10\/ENR.gif","width":1900,"height":1265},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/energie-solaire-mise-en-service-de-deux-centrales-dune-capacite-totale-de-400-mw\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Energie solaire\u00a0: Mise en service de deux centrales d&rsquo;une capacit\u00e9 totale de 400 MW\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/85524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=85524"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/85524\/revisions"}],"predecessor-version":[{"id":85526,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/85524\/revisions\/85526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/75469"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=85524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=85524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=85524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}