{"id":85540,"date":"2026-04-13T14:24:30","date_gmt":"2026-04-13T13:24:30","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=85540"},"modified":"2026-04-13T14:24:31","modified_gmt":"2026-04-13T13:24:31","slug":"les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/","title":{"rendered":"Les retraites vers\u00e9es en mai avec les nouvelles revalorisations"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le ministre du Travail, de l&rsquo;Emploi et de la S\u00e9curit\u00e9 sociale, Abdelhak Sa\u00efhi, a instruit les services concern\u00e9s de proc\u00e9der au versement des pensions de retraite, augmentations comprises, d\u00e8s la premi\u00e8re semaine de mai 2026. Ces directives ont \u00e9t\u00e9 \u00e9mises lors d&rsquo;une r\u00e9union de coordination qu&rsquo;il a pr\u00e9sid\u00e9e dimanche, consacr\u00e9e au bilan des activit\u00e9s de la p\u00e9riode allant du 1er mars au 11 avril 2026. Le ministre a insist\u00e9 sur la n\u00e9cessit\u00e9 de respecter scrupuleusement ce d\u00e9lai et de redoubler d&rsquo;efforts pour honorer les engagements dans les temps impartis. La r\u00e9union a \u00e9galement \u00e9t\u00e9 l&rsquo;occasion de passer en revue les chantiers en cours, notamment l&rsquo;acc\u00e9l\u00e9ration de la num\u00e9risation des services et le traitement imm\u00e9diat des recours des jeunes non b\u00e9n\u00e9ficiaires de l&rsquo;allocation ch\u00f4mage via la plateforme \u00ab Insat \u00bb. Sa\u00efhi a par ailleurs appel\u00e9 \u00e0 apurer les dossiers en suspens, \u00e0 renforcer la coordination interminist\u00e9rielle pour simplifier les proc\u00e9dures administratives et \u00e0 consolider le r\u00f4le de l&rsquo;inspection du travail, le tout dans le cadre d&rsquo;une r\u00e9forme globale visant \u00e0 moderniser le secteur et \u00e0 rapprocher l&rsquo;administration du citoyen, conform\u00e9ment aux orientations du pr\u00e9sident Tebboune.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R.N.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre du Travail, de l&rsquo;Emploi et de la S\u00e9curit\u00e9 sociale, Abdelhak Sa\u00efhi, a instruit les services concern\u00e9s de proc\u00e9der<\/p>\n","protected":false},"author":6,"featured_media":19824,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-85540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les retraites vers\u00e9es en mai avec les nouvelles revalorisations - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les retraites vers\u00e9es en mai avec les nouvelles revalorisations - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Le ministre du Travail, de l&rsquo;Emploi et de la S\u00e9curit\u00e9 sociale, Abdelhak Sa\u00efhi, a instruit les services concern\u00e9s de proc\u00e9der\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-13T13:24:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T13:24:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/retraite.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1491\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Les retraites vers\u00e9es en mai avec les nouvelles revalorisations\",\"datePublished\":\"2026-04-13T13:24:30+00:00\",\"dateModified\":\"2026-04-13T13:24:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\\\/\"},\"wordCount\":225,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/retraite.png\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\\\/\",\"name\":\"Les retraites vers\u00e9es en mai avec les nouvelles revalorisations - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/retraite.png\",\"datePublished\":\"2026-04-13T13:24:30+00:00\",\"dateModified\":\"2026-04-13T13:24:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/retraite.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/retraite.png\",\"width\":1491,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/13\\\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les retraites vers\u00e9es en mai avec les nouvelles revalorisations\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les retraites vers\u00e9es en mai avec les nouvelles revalorisations - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/","og_locale":"fr_FR","og_type":"article","og_title":"Les retraites vers\u00e9es en mai avec les nouvelles revalorisations - La Sentinelle","og_description":"Le ministre du Travail, de l&rsquo;Emploi et de la S\u00e9curit\u00e9 sociale, Abdelhak Sa\u00efhi, a instruit les services concern\u00e9s de proc\u00e9der","og_url":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2026-04-13T13:24:30+00:00","article_modified_time":"2026-04-13T13:24:31+00:00","og_image":[{"width":1491,"height":900,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/retraite.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Les retraites vers\u00e9es en mai avec les nouvelles revalorisations","datePublished":"2026-04-13T13:24:30+00:00","dateModified":"2026-04-13T13:24:31+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/"},"wordCount":225,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/retraite.png","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/","url":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/","name":"Les retraites vers\u00e9es en mai avec les nouvelles revalorisations - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/retraite.png","datePublished":"2026-04-13T13:24:30+00:00","dateModified":"2026-04-13T13:24:31+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/retraite.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2022\/04\/retraite.png","width":1491,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/13\/les-retraites-versees-en-mai-avec-les-nouvelles-revalorisations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Les retraites vers\u00e9es en mai avec les nouvelles revalorisations"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/85540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=85540"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/85540\/revisions"}],"predecessor-version":[{"id":85541,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/85540\/revisions\/85541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/19824"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=85540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=85540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=85540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}