{"id":85795,"date":"2026-04-15T20:03:22","date_gmt":"2026-04-15T19:03:22","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=85795"},"modified":"2026-04-15T20:03:23","modified_gmt":"2026-04-15T19:03:23","slug":"lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/","title":{"rendered":"Lutte contre le narcotrafic\u00a0: L\u2019ANP maintient une pression constante"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Plus de 11 quintaux de kif trait\u00e9 provenant des fronti\u00e8res avec le Maroc ont \u00e9t\u00e9 saisis mardi \u00e0 B\u00e9char par des d\u00e9tachements combin\u00e9s de l\u2019Arm\u00e9e nationale populaire (ANP), une op\u00e9ration qui s\u2019inscrit dans une s\u00e9rie d\u2019interventions ayant permis, en une semaine, de d\u00e9jouer l\u2019introduction de pr\u00e8s de 14 quintaux de drogue, tandis que les bilans r\u00e9cents font \u00e9galement \u00e9tat d\u2019un dispositif soutenu sur l\u2019ensemble du territoire national. Selon les communiqu\u00e9s du minist\u00e8re de la D\u00e9fense nationale (MDN), ces r\u00e9sultats illustrent la pression maintenue contre les r\u00e9seaux criminels, confirm\u00e9e \u00e0 la fois par le bilan hebdomadaire du 8 au 14 avril et par les donn\u00e9es du mois de mars. Dans le d\u00e9tail, le MDN indique que \u00ab dans la dynamique des efforts de lutte contre les barons de la contrebande et les narcotrafiquants, et suite \u00e0 une exploitation optimale des informations, des d\u00e9tachements combin\u00e9s de l&rsquo;ANP relevant du secteur militaire de B\u00e9char en 3e R\u00e9gion militaire, ont d\u00e9jou\u00e9, hier 14 avril 2026, une tentative d&rsquo;introduction de (11) quintaux et (10) kilogrammes de kif trait\u00e9 provenant des fronti\u00e8res avec le Maroc \u00bb. Le communiqu\u00e9 souligne que \u00ab cette op\u00e9ration qualitative r\u00e9affirme une autre fois la mobilisation des unit\u00e9s de l&rsquo;ANP \u00e0 faire face \u00e0 toute tentative visant \u00e0 porter atteinte \u00e0 la s\u00e9curit\u00e9 du citoyen \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette intervention s\u2019inscrit dans un contexte marqu\u00e9 par une intensification des op\u00e9rations contre les trafics transfrontaliers. Les forces de l\u2019ANP maintiennent ainsi une pression constante sur les r\u00e9seaux criminels, notamment aux fronti\u00e8res ouest, o\u00f9 les tentatives d\u2019introduction de stup\u00e9fiants continuent d\u2019\u00eatre r\u00e9guli\u00e8rement mises en \u00e9chec gr\u00e2ce \u00e0 l\u2019exploitation du renseignement et \u00e0 la coordination entre unit\u00e9s op\u00e9rationnelles. Ces actions traduisent la vigilance permanente des forces engag\u00e9es dans la protection des fronti\u00e8res et la lutte contre les trafics organis\u00e9s multiformes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les r\u00e9sultats enregistr\u00e9s lors de la derni\u00e8re op\u00e9ration font d\u2019ailleurs \u00e9cho au bilan hebdomadaire couvrant la p\u00e9riode du 8 au 14 avril 2026. Le MDN pr\u00e9cise \u00e0 ce titre que \u00ab dans la dynamique des efforts soutenus dans la lutte antiterroriste et contre la criminalit\u00e9 organis\u00e9e multiforme, des unit\u00e9s et des d\u00e9tachements de l&rsquo;Arm\u00e9e nationale populaire ont ex\u00e9cut\u00e9 (\u2026) plusieurs op\u00e9rations ayant abouti \u00e0 des r\u00e9sultats de qualit\u00e9 qui refl\u00e8tent le haut professionnalisme, la vigilance et la disponibilit\u00e9 permanente de nos Forces arm\u00e9es \u00e0 travers tout le territoire national \u00bb. Dans ce cadre, \u00ab des d\u00e9tachements combin\u00e9s de l&rsquo;ANP ont intercept\u00e9 (\u2026) 40 narcotrafiquants et mis en \u00e9chec des tentatives d&rsquo;introduction de 13 quintaux et 83 kilogrammes de kif trait\u00e9 provenant des fronti\u00e8res avec le Maroc, alors qu&rsquo;un (1) kilogramme de coca\u00efne et 169.173 comprim\u00e9s psychotropes ont \u00e9t\u00e9 saisis \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le m\u00eame bilan fait \u00e9galement \u00e9tat d\u2019op\u00e9rations contre l\u2019orpaillage illicite dans le Sud du pays. Ainsi, \u00e0 Tamanrasset, Bordj Badji Mokhtar, In Salah, Illizi et In Guezzam, des d\u00e9tachements de l\u2019ANP \u00ab ont arr\u00eat\u00e9 299 individus et saisi 30 v\u00e9hicules, 364 groupes \u00e9lectrog\u00e8nes, 204 marteaux-piqueurs, ainsi que des quantit\u00e9s de m\u00e9lange d&rsquo;or brut et de pierres, et d&rsquo;\u00e9quipements utilis\u00e9s dans des op\u00e9rations d&rsquo;orpaillage illicite \u00bb. Par ailleurs, \u00ab 11 autres individus ont \u00e9t\u00e9 appr\u00e9hend\u00e9s et 8 fusils de chasse, 19.780 litres de carburants, 22 quintaux de tabacs et 544 tonnes de denr\u00e9es alimentaires, destin\u00e9s \u00e0 la contrebande, ont \u00e9t\u00e9 saisis \u00bb. Concernant la lutte contre l\u2019\u00e9migration clandestine, \u00ab les Garde-c\u00f4tes ont mis en \u00e9chec (\u2026) des tentatives d&rsquo;\u00e9migration clandestine et proc\u00e9d\u00e9 au sauvetage de 177 individus (\u2026) alors que 253 immigrants clandestins (\u2026) ont \u00e9t\u00e9 arr\u00eat\u00e9s \u00e0 travers le territoire national \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au-del\u00e0 de ces r\u00e9sultats hebdomadaires, les op\u00e9rations r\u00e9centes prolongent la dynamique observ\u00e9e dans le bilan mensuel de mars 2026, qui met en \u00e9vidence l\u2019ampleur du dispositif s\u00e9curitaire d\u00e9ploy\u00e9. Dans le cadre de la lutte antiterroriste, neuf terroristes ont \u00e9t\u00e9 abattus, deux autres se sont rendus aux autorit\u00e9s militaires, tandis que 17 \u00e9l\u00e9ments de soutien ont \u00e9t\u00e9 arr\u00eat\u00e9s. Sur le front du narcotrafic, 155 narcotrafiquants ont \u00e9t\u00e9 interpell\u00e9s, avec la saisie de 30,60 quintaux de kif trait\u00e9, 122 kilogrammes de coca\u00efne et 6285.431 comprim\u00e9s psychotropes. Les op\u00e9rations men\u00e9es contre l\u2019orpaillage illicite et la contrebande ont permis l\u2019arrestation de 1 572 individus et la r\u00e9cup\u00e9ration d\u2019\u00e9quipements importants, dont 386 marteaux-piqueurs, 688 groupes \u00e9lectrog\u00e8nes et trois d\u00e9tecteurs de m\u00e9taux. Les unit\u00e9s de l\u2019ANP ont \u00e9galement saisi 156 761 litres de carburant destin\u00e9s \u00e0 la contrebande, r\u00e9cup\u00e9r\u00e9 39 armes \u00e0 feu et 140 v\u00e9hicules de diff\u00e9rents types. S\u2019agissant de l\u2019immigration clandestine, 1 748 ressortissants subsahariens de diverses nationalit\u00e9s ont \u00e9t\u00e9 intercept\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sofia Chahine<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plus de 11 quintaux de kif trait\u00e9 provenant des fronti\u00e8res avec le Maroc ont \u00e9t\u00e9 saisis mardi \u00e0 B\u00e9char par<\/p>\n","protected":false},"author":6,"featured_media":42978,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-85795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lutte contre le narcotrafic\u00a0: L\u2019ANP maintient une pression constante - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lutte contre le narcotrafic\u00a0: L\u2019ANP maintient une pression constante - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Plus de 11 quintaux de kif trait\u00e9 provenant des fronti\u00e8res avec le Maroc ont \u00e9t\u00e9 saisis mardi \u00e0 B\u00e9char par\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-15T19:03:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T19:03:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/06\/kif.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1210\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/15\\\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/15\\\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Lutte contre le narcotrafic\u00a0: L\u2019ANP maintient une pression constante\",\"datePublished\":\"2026-04-15T19:03:22+00:00\",\"dateModified\":\"2026-04-15T19:03:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/15\\\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\\\/\"},\"wordCount\":805,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/15\\\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/kif.jpg\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/15\\\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/15\\\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/15\\\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\\\/\",\"name\":\"Lutte contre le narcotrafic\u00a0: L\u2019ANP maintient une pression constante - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/15\\\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/15\\\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/kif.jpg\",\"datePublished\":\"2026-04-15T19:03:22+00:00\",\"dateModified\":\"2026-04-15T19:03:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/15\\\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/15\\\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/15\\\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/kif.jpg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/kif.jpg\",\"width\":1210,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/04\\\/15\\\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lutte contre le narcotrafic\u00a0: L\u2019ANP maintient une pression constante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lutte contre le narcotrafic\u00a0: L\u2019ANP maintient une pression constante - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/","og_locale":"fr_FR","og_type":"article","og_title":"Lutte contre le narcotrafic\u00a0: L\u2019ANP maintient une pression constante - La Sentinelle","og_description":"Plus de 11 quintaux de kif trait\u00e9 provenant des fronti\u00e8res avec le Maroc ont \u00e9t\u00e9 saisis mardi \u00e0 B\u00e9char par","og_url":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2026-04-15T19:03:22+00:00","article_modified_time":"2026-04-15T19:03:23+00:00","og_image":[{"width":1210,"height":682,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/06\/kif.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Lutte contre le narcotrafic\u00a0: L\u2019ANP maintient une pression constante","datePublished":"2026-04-15T19:03:22+00:00","dateModified":"2026-04-15T19:03:23+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/"},"wordCount":805,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/06\/kif.jpg","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/","url":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/","name":"Lutte contre le narcotrafic\u00a0: L\u2019ANP maintient une pression constante - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/06\/kif.jpg","datePublished":"2026-04-15T19:03:22+00:00","dateModified":"2026-04-15T19:03:23+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/06\/kif.jpg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2023\/06\/kif.jpg","width":1210,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/04\/15\/lutte-contre-le-narcotrafic-lanp-maintient-une-pression-constante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Lutte contre le narcotrafic\u00a0: L\u2019ANP maintient une pression constante"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/85795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=85795"}],"version-history":[{"count":1,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/85795\/revisions"}],"predecessor-version":[{"id":85796,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/85795\/revisions\/85796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/42978"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=85795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=85795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=85795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}