{"id":88459,"date":"2026-05-30T19:48:27","date_gmt":"2026-05-30T18:48:27","guid":{"rendered":"https:\/\/lasentinelle.dz\/?p=88459"},"modified":"2026-05-30T19:48:29","modified_gmt":"2026-05-30T18:48:29","slug":"les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger","status":"publish","type":"post","link":"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/","title":{"rendered":"Les derni\u00e8res secousses telluriques rel\u00e8vent d&rsquo;une \u00ab\u00a0activit\u00e9 sismique mod\u00e9r\u00e9e ne pr\u00e9sentant aucun danger\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les secousses telluriques enregistr\u00e9es, durant les jours de l&rsquo;A\u00efd El-Adha, rel\u00e8vent d&rsquo;une activit\u00e9 sismique \u00ab\u00a0mod\u00e9r\u00e9e\u00a0\u00bb et ne pr\u00e9sentent aucun danger pour la vie des personnes, a assur\u00e9, samedi dans un communiqu\u00e9, le Centre de recherche en astronomie astrophysique et g\u00e9ophysique (CRAAG). Le CRAAG a indiqu\u00e9 qu&rsquo;une \u00ab\u00a0activit\u00e9 sismique mod\u00e9r\u00e9e\u00a0\u00bb a \u00e9t\u00e9 enregistr\u00e9e, marqu\u00e9e par trois secousses survenues le premier jour de l&rsquo;A\u00efd El-Adha, dont les \u00e9picentres ont \u00e9t\u00e9 localis\u00e9s respectivement \u00e0 Mihoub dans la wilaya de M\u00e9d\u00e9a (3,0 degr\u00e9s), \u00e0 Timgad dans la wilaya de Batna (3,4 degr\u00e9s) et \u00e0 Ghazaouet dans la wilaya de Tlemcen (4,1 degr\u00e9s). Le CRAAG a \u00e9galement enregistr\u00e9 une autre secousse tellurique vendredi au nord de la commune d&rsquo;Aokas dans la wilaya de B\u00e9ja\u00efa, d&rsquo;une magnitude de 3,3 degr\u00e9s sur l&rsquo;\u00e9chelle de Richter. Le CRAAG a expliqu\u00e9 que cette activit\u00e9 sismique est \u00ab\u00a0naturelle et normale\u00a0\u00bb, au regard de la situation g\u00e9ographique de l&rsquo;Alg\u00e9rie, situ\u00e9e sur la plaque tectonique africaine qui entre en collision avec la place tectonique eurasiatique \u00e0 raison d&rsquo;environ 5 millim\u00e8tres par an, soit un mouvement annuel lent g\u00e9n\u00e9rant des secousses de faible intensit\u00e9. Le Centre a ajout\u00e9, dans le m\u00eame contexte, qu&rsquo;il \u00ab\u00a0enregistre pr\u00e8s de 80 secousses telluriques par mois, dont 90% ne sont pas ressenties\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">APS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les secousses telluriques enregistr\u00e9es, durant les jours de l&rsquo;A\u00efd El-Adha, rel\u00e8vent d&rsquo;une activit\u00e9 sismique \u00ab\u00a0mod\u00e9r\u00e9e\u00a0\u00bb et ne pr\u00e9sentent aucun danger<\/p>\n","protected":false},"author":6,"featured_media":88460,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"default","_twitter_share_type":"default","_linkedin_share_type":"default","_pinterest_share_type":"default","_linkedin_share_type_page":"","_instagram_share_type":"default","_medium_share_type":"default","_threads_share_type":"default","_google_business_share_type":"default","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[27],"tags":[],"class_list":["post-88459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les derni\u00e8res secousses telluriques rel\u00e8vent d&rsquo;une \u00ab\u00a0activit\u00e9 sismique mod\u00e9r\u00e9e ne pr\u00e9sentant aucun danger\u00a0\u00bb - La Sentinelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les derni\u00e8res secousses telluriques rel\u00e8vent d&rsquo;une \u00ab\u00a0activit\u00e9 sismique mod\u00e9r\u00e9e ne pr\u00e9sentant aucun danger\u00a0\u00bb - La Sentinelle\" \/>\n<meta property=\"og:description\" content=\"Les secousses telluriques enregistr\u00e9es, durant les jours de l&rsquo;A\u00efd El-Adha, rel\u00e8vent d&rsquo;une activit\u00e9 sismique \u00ab\u00a0mod\u00e9r\u00e9e\u00a0\u00bb et ne pr\u00e9sentent aucun danger\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/\" \/>\n<meta property=\"og:site_name\" content=\"La Sentinelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-30T18:48:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-30T18:48:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/05\/CRAAG.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"327\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/05\\\/30\\\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/05\\\/30\\\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\"},\"headline\":\"Les derni\u00e8res secousses telluriques rel\u00e8vent d&rsquo;une \u00ab\u00a0activit\u00e9 sismique mod\u00e9r\u00e9e ne pr\u00e9sentant aucun danger\u00a0\u00bb\",\"datePublished\":\"2026-05-30T18:48:27+00:00\",\"dateModified\":\"2026-05-30T18:48:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/05\\\/30\\\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\\\/\"},\"wordCount\":253,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/05\\\/30\\\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/CRAAG.jpg\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/05\\\/30\\\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/05\\\/30\\\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/05\\\/30\\\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\\\/\",\"name\":\"Les derni\u00e8res secousses telluriques rel\u00e8vent d&rsquo;une \u00ab\u00a0activit\u00e9 sismique mod\u00e9r\u00e9e ne pr\u00e9sentant aucun danger\u00a0\u00bb - La Sentinelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/05\\\/30\\\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/05\\\/30\\\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/CRAAG.jpg\",\"datePublished\":\"2026-05-30T18:48:27+00:00\",\"dateModified\":\"2026-05-30T18:48:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/05\\\/30\\\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/05\\\/30\\\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/05\\\/30\\\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/CRAAG.jpg\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/CRAAG.jpg\",\"width\":580,\"height\":327},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/index.php\\\/2026\\\/05\\\/30\\\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lasentinelle.dz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les derni\u00e8res secousses telluriques rel\u00e8vent d&rsquo;une \u00ab\u00a0activit\u00e9 sismique mod\u00e9r\u00e9e ne pr\u00e9sentant aucun danger\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#website\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"name\":\"La Sentinelle\",\"description\":\"Quotidien national d&#039;information\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasentinelle.dz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#organization\",\"name\":\"Quotidien La Sentinelle\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"contentUrl\":\"https:\\\/\\\/lasentinelle.dz\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-sentinelleSLOGAN-1.png\",\"width\":615,\"height\":142,\"caption\":\"Quotidien La Sentinelle\"},\"image\":{\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/La-Sentinelle-104059864394773\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lasentinelle.dz\\\/#\\\/schema\\\/person\\\/729ee0024f24e0b8c5ec17232f8e8b41\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"description\":\"admin\",\"url\":\"https:\\\/\\\/lasentinelle.dz\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les derni\u00e8res secousses telluriques rel\u00e8vent d&rsquo;une \u00ab\u00a0activit\u00e9 sismique mod\u00e9r\u00e9e ne pr\u00e9sentant aucun danger\u00a0\u00bb - La Sentinelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/","og_locale":"fr_FR","og_type":"article","og_title":"Les derni\u00e8res secousses telluriques rel\u00e8vent d&rsquo;une \u00ab\u00a0activit\u00e9 sismique mod\u00e9r\u00e9e ne pr\u00e9sentant aucun danger\u00a0\u00bb - La Sentinelle","og_description":"Les secousses telluriques enregistr\u00e9es, durant les jours de l&rsquo;A\u00efd El-Adha, rel\u00e8vent d&rsquo;une activit\u00e9 sismique \u00ab\u00a0mod\u00e9r\u00e9e\u00a0\u00bb et ne pr\u00e9sentent aucun danger","og_url":"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/","og_site_name":"La Sentinelle","article_publisher":"https:\/\/www.facebook.com\/La-Sentinelle-104059864394773","article_published_time":"2026-05-30T18:48:27+00:00","article_modified_time":"2026-05-30T18:48:29+00:00","og_image":[{"width":580,"height":327,"url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/05\/CRAAG.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/#article","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/"},"author":{"name":"admin","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41"},"headline":"Les derni\u00e8res secousses telluriques rel\u00e8vent d&rsquo;une \u00ab\u00a0activit\u00e9 sismique mod\u00e9r\u00e9e ne pr\u00e9sentant aucun danger\u00a0\u00bb","datePublished":"2026-05-30T18:48:27+00:00","dateModified":"2026-05-30T18:48:29+00:00","mainEntityOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/"},"wordCount":253,"commentCount":0,"publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/05\/CRAAG.jpg","articleSection":["Actualit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/","url":"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/","name":"Les derni\u00e8res secousses telluriques rel\u00e8vent d&rsquo;une \u00ab\u00a0activit\u00e9 sismique mod\u00e9r\u00e9e ne pr\u00e9sentant aucun danger\u00a0\u00bb - La Sentinelle","isPartOf":{"@id":"https:\/\/lasentinelle.dz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/#primaryimage"},"image":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/#primaryimage"},"thumbnailUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/05\/CRAAG.jpg","datePublished":"2026-05-30T18:48:27+00:00","dateModified":"2026-05-30T18:48:29+00:00","breadcrumb":{"@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/#primaryimage","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/05\/CRAAG.jpg","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2026\/05\/CRAAG.jpg","width":580,"height":327},{"@type":"BreadcrumbList","@id":"https:\/\/lasentinelle.dz\/index.php\/2026\/05\/30\/les-dernieres-secousses-telluriques-relevent-dune-activite-sismique-moderee-ne-presentant-aucun-danger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lasentinelle.dz\/"},{"@type":"ListItem","position":2,"name":"Les derni\u00e8res secousses telluriques rel\u00e8vent d&rsquo;une \u00ab\u00a0activit\u00e9 sismique mod\u00e9r\u00e9e ne pr\u00e9sentant aucun danger\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/lasentinelle.dz\/#website","url":"https:\/\/lasentinelle.dz\/","name":"La Sentinelle","description":"Quotidien national d&#039;information","publisher":{"@id":"https:\/\/lasentinelle.dz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasentinelle.dz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lasentinelle.dz\/#organization","name":"Quotidien La Sentinelle","url":"https:\/\/lasentinelle.dz\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/","url":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","contentUrl":"https:\/\/lasentinelle.dz\/wp-content\/uploads\/2021\/09\/logo-sentinelleSLOGAN-1.png","width":615,"height":142,"caption":"Quotidien La Sentinelle"},"image":{"@id":"https:\/\/lasentinelle.dz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/La-Sentinelle-104059864394773"]},{"@type":"Person","@id":"https:\/\/lasentinelle.dz\/#\/schema\/person\/729ee0024f24e0b8c5ec17232f8e8b41","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c81fed838786e9b53f540bf46533e750f5d292099ae3b66cfc6fb1982e29df7?s=96&d=mm&r=g","caption":"admin"},"description":"admin","url":"https:\/\/lasentinelle.dz\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/88459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/comments?post=88459"}],"version-history":[{"count":2,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/88459\/revisions"}],"predecessor-version":[{"id":88462,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/posts\/88459\/revisions\/88462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media\/88460"}],"wp:attachment":[{"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/media?parent=88459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/categories?post=88459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasentinelle.dz\/index.php\/wp-json\/wp\/v2\/tags?post=88459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}